{"id":63617,"date":"2026-08-30T13:07:37","date_gmt":"2026-08-30T13:07:37","guid":{"rendered":"https:\/\/honigbee.com\/?post_type=product&#038;p=63617"},"modified":"2026-08-30T13:11:38","modified_gmt":"2026-08-30T13:11:38","slug":"proteinriegel-milchschokolade-erdnuss-62-g","status":"publish","type":"product","link":"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/","title":{"rendered":"Proteinriegel Milchschokolade Erdnuss 62 g \u2013 Applied Nutrition Protein Crunch Bar"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0421\u044a\u0434\u044a\u0440\u0436\u0430\u043d\u0438\u0435<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u041f\u0440\u0435\u0432\u043a\u043b\u044e\u0447\u0432\u0430\u043d\u0435 \u043d\u0430 \u0441\u044a\u0434\u044a\u0440\u0436\u0430\u043d\u0438\u0435\u0442\u043e\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">\u041f\u0440\u0435\u0432\u043a\u043b\u044e\u0447\u0432\u0430\u043d\u0435<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Proteinriegel_Milchschokolade_Erdnuss_von_Applied_Nutrition\" >Proteinriegel Milchschokolade Erdnuss von Applied Nutrition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#21_g_Eiweis_pro_Proteinriegel\" >21 g Eiwei\u00df pro Proteinriegel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Milk_Chocolate_Peanut_%E2%80%93_Milchschokolade_Erdnuss\" >Milk Chocolate Peanut \u2013 Milchschokolade Erdnuss<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Nahrwerte\" >\u0425\u0440\u0430\u043d\u0438\u0442\u0435\u043b\u043d\u0438 \u0441\u0442\u043e\u0439\u043d\u043e\u0441\u0442\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Zutaten\" >\u0421\u044a\u0441\u0442\u0430\u0432\u043a\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Allergiehinweise\" >Allergiehinweise<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Verzehrempfehlung\" >\u041f\u0440\u0435\u043f\u043e\u0440\u044a\u0447\u0438\u0442\u0435\u043b\u0435\u043d \u043f\u0440\u0438\u0435\u043c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Aufbewahrung\" >Aufbewahrung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/honigbee.com\/bg\/produkt\/proteinriegel-milchschokolade-erdnuss-62-g\/#Protein_Snack_fur_Sport_und_Alltag\" >Protein Snack f\u00fcr Sport und Alltag<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"912\" data-end=\"976\"><span class=\"ez-toc-section\" id=\"Proteinriegel_Milchschokolade_Erdnuss_von_Applied_Nutrition\"><\/span>Proteinriegel Milchschokolade Erdnuss von Applied Nutrition<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"978\" data-end=\"1241\">The <strong data-start=\"982\" data-end=\"1023\">Proteinriegel Milchschokolade Erdnuss<\/strong> von Applied Nutrition ist ein knuspriger Protein Snack mit Milchschokolade, Karamell und Erdn\u00fcssen. Der Protein Crunch Bar eignet sich ideal als eiwei\u00dfreicher Snack f\u00fcr unterwegs, nach dem Training oder zwischendurch.<\/p>\n<p data-start=\"1243\" data-end=\"1380\">Ein Riegel enth\u00e4lt <strong data-start=\"1262\" data-end=\"1298\">21 g Eiwei\u00df bei nur 1,9 g Zucker<\/strong> und verbindet einen hohen Proteingehalt mit einem schokoladig-nussigen Geschmack.<\/p>\n<hr data-start=\"1382\" data-end=\"1385\" \/>\n<h4 data-start=\"1387\" data-end=\"1421\"><span class=\"ez-toc-section\" id=\"21_g_Eiweis_pro_Proteinriegel\"><\/span>21 g Eiwei\u00df pro Proteinriegel<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1423\" data-end=\"1509\">The <strong data-start=\"1427\" data-end=\"1468\">Proteinriegel Milchschokolade Erdnuss<\/strong> liefert <strong data-start=\"1477\" data-end=\"1508\">21 g Eiwei\u00df pro 62-g-Riegel<\/strong>.<\/p>\n<p data-start=\"1511\" data-end=\"1612\">Protein tr\u00e4gt zur <strong data-start=\"1529\" data-end=\"1570\">Zunahme und Erhaltung von Muskelmasse<\/strong> sowie zur Erhaltung normaler Knochen bei.<\/p>\n<p data-start=\"1614\" data-end=\"1762\">Durch das handliche Format l\u00e4sst sich der Riegel unkompliziert mitnehmen und eignet sich f\u00fcr Sport, Arbeit, Reisen oder als Protein Snack im Alltag.<\/p>\n<hr data-start=\"1764\" data-end=\"1767\" \/>\n<h4 data-start=\"1769\" data-end=\"1821\"><span class=\"ez-toc-section\" id=\"Milk_Chocolate_Peanut_%E2%80%93_Milchschokolade_Erdnuss\"><\/span>Milk Chocolate Peanut \u2013 Milchschokolade Erdnuss<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1823\" data-end=\"1926\">Die Geschmacksrichtung <strong data-start=\"1846\" data-end=\"1871\">Milk Chocolate Peanut<\/strong> kombiniert Milchschokolade mit Karamell und Erdn\u00fcssen.<\/p>\n<p data-start=\"1928\" data-end=\"2062\">Der knusprige Protein Crunch Bar enth\u00e4lt neben <strong data-start=\"1975\" data-end=\"1990\">21 g Eiwei\u00df<\/strong> auch <strong data-start=\"1996\" data-end=\"2019\">4,9 g Ballaststoffe<\/strong> und lediglich <strong data-start=\"2034\" data-end=\"2061\">1,9 g Zucker pro Riegel<\/strong>.<\/p>\n<p data-start=\"2064\" data-end=\"2154\">The <strong data-start=\"2068\" data-end=\"2109\">Proteinriegel Milchschokolade Erdnuss<\/strong> ist zudem f\u00fcr Vegetarier geeignet und Halal.<\/p>\n<hr data-start=\"2156\" data-end=\"2159\" \/>\n<h4 data-start=\"2161\" data-end=\"2175\"><span class=\"ez-toc-section\" id=\"Nahrwerte\"><\/span>\u0425\u0440\u0430\u043d\u0438\u0442\u0435\u043b\u043d\u0438 \u0441\u0442\u043e\u0439\u043d\u043e\u0441\u0442\u0438<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2177\" data-end=\"2210\"><strong data-start=\"2177\" data-end=\"2210\">Nettogewicht: 62 g \u2013 1 Riegel<\/strong><\/p>\n<div class=\"group TyagGW_tableContainer\">\n<div class=\"TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"2212\" data-end=\"2649\">\n<thead data-start=\"2212\" data-end=\"2275\">\n<tr data-start=\"2212\" data-end=\"2275\">\n<th class=\"last:pe-10\" data-start=\"2212\" data-end=\"2242\" data-col-size=\"sm\">Durchschnittliche N\u00e4hrwerte<\/th>\n<th class=\"last:pe-10\" data-start=\"2242\" data-end=\"2254\" data-col-size=\"sm\">pro 100 g<\/th>\n<th class=\"last:pe-10\" data-start=\"2254\" data-end=\"2275\" data-col-size=\"sm\">pro Riegel (62 g)<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"2292\" data-end=\"2649\">\n<tr data-start=\"2292\" data-end=\"2344\">\n<td data-start=\"2292\" data-end=\"2302\" data-col-size=\"sm\">Energie<\/td>\n<td data-col-size=\"sm\" data-start=\"2302\" data-end=\"2323\">1325 kJ \/ 317 kcal<\/td>\n<td data-col-size=\"sm\" data-start=\"2323\" data-end=\"2344\">861 kJ \/ 206 kcal<\/td>\n<\/tr>\n<tr data-start=\"2345\" data-end=\"2369\">\n<td data-start=\"2345\" data-end=\"2352\" data-col-size=\"sm\">Fett<\/td>\n<td data-start=\"2352\" data-end=\"2360\" data-col-size=\"sm\">8,6 g<\/td>\n<td data-start=\"2360\" data-end=\"2369\" data-col-size=\"sm\">5,6 g<\/td>\n<\/tr>\n<tr data-start=\"2370\" data-end=\"2419\">\n<td data-start=\"2370\" data-end=\"2400\" data-col-size=\"sm\">davon ges\u00e4ttigte Fetts\u00e4uren<\/td>\n<td data-col-size=\"sm\" data-start=\"2400\" data-end=\"2409\">4,92 g<\/td>\n<td data-col-size=\"sm\" data-start=\"2409\" data-end=\"2419\">3,20 g<\/td>\n<\/tr>\n<tr data-start=\"2420\" data-end=\"2445\">\n<td data-start=\"2420\" data-end=\"2432\" data-col-size=\"sm\">Transfett<\/td>\n<td data-start=\"2432\" data-end=\"2438\" data-col-size=\"sm\">0 g<\/td>\n<td data-start=\"2438\" data-end=\"2445\" data-col-size=\"sm\">0 g<\/td>\n<\/tr>\n<tr data-start=\"2446\" data-end=\"2477\">\n<td data-start=\"2446\" data-end=\"2462\" data-col-size=\"sm\">Kohlenhydrate<\/td>\n<td data-start=\"2462\" data-end=\"2469\" data-col-size=\"sm\">34 g<\/td>\n<td data-start=\"2469\" data-end=\"2477\" data-col-size=\"sm\">22 g<\/td>\n<\/tr>\n<tr data-start=\"2478\" data-end=\"2512\">\n<td data-start=\"2478\" data-end=\"2493\" data-col-size=\"sm\">davon Zucker<\/td>\n<td data-start=\"2493\" data-end=\"2502\" data-col-size=\"sm\">2,92 g<\/td>\n<td data-start=\"2502\" data-end=\"2512\" data-col-size=\"sm\">1,90 g<\/td>\n<\/tr>\n<tr data-start=\"2513\" data-end=\"2563\">\n<td data-start=\"2513\" data-end=\"2542\" data-col-size=\"sm\">davon mehrwertige Alkohole<\/td>\n<td data-col-size=\"sm\" data-start=\"2542\" data-end=\"2552\">27,38 g<\/td>\n<td data-col-size=\"sm\" data-start=\"2552\" data-end=\"2563\">17,80 g<\/td>\n<\/tr>\n<tr data-start=\"2564\" data-end=\"2597\">\n<td data-start=\"2564\" data-end=\"2580\" data-col-size=\"sm\">Ballaststoffe<\/td>\n<td data-start=\"2580\" data-end=\"2588\" data-col-size=\"sm\">7,5 g<\/td>\n<td data-start=\"2588\" data-end=\"2597\" data-col-size=\"sm\">4,9 g<\/td>\n<\/tr>\n<tr data-start=\"2598\" data-end=\"2622\">\n<td data-start=\"2598\" data-end=\"2607\" data-col-size=\"sm\">Eiwei\u00df<\/td>\n<td data-col-size=\"sm\" data-start=\"2607\" data-end=\"2614\">33 g<\/td>\n<td data-col-size=\"sm\" data-start=\"2614\" data-end=\"2622\">21 g<\/td>\n<\/tr>\n<tr data-start=\"2623\" data-end=\"2649\">\n<td data-start=\"2623\" data-end=\"2630\" data-col-size=\"sm\">Salz<\/td>\n<td data-start=\"2630\" data-end=\"2639\" data-col-size=\"sm\">0,48 g<\/td>\n<td data-start=\"2639\" data-end=\"2649\" data-col-size=\"sm\">0,31 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<hr data-start=\"2651\" data-end=\"2654\" \/>\n<h4 data-start=\"2656\" data-end=\"2668\"><span class=\"ez-toc-section\" id=\"Zutaten\"><\/span>\u0421\u044a\u0441\u0442\u0430\u0432\u043a\u0438<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2670\" data-end=\"3509\"><strong data-start=\"2670\" data-end=\"2682\">\u0421\u044a\u0441\u0442\u0430\u0432\u043a\u0438:<\/strong> Proteinmischung: Milchproteinisolat, hydrolysiertes Weizenprotein, Sojaproteinisolat, Molkenproteinisolat; Emulgator: Lecithine (Sonnenblumen) (<strong data-start=\"2827\" data-end=\"2836\">Milch<\/strong>), Kuvert\u00fcre aus Milchschokolade mit S\u00fc\u00dfungsmittel: S\u00fc\u00dfungsmittel: Maltit; Kakaobutter, Vollmilchpulver, Kakaomasse, Emulgator: Lecithine (<strong data-start=\"2975\" data-end=\"2983\">Soja<\/strong>), nat\u00fcrliches Vanillearoma, Feuchthaltemittel: Glycerin; Karamellaroma, F\u00fcllung: Feuchthaltemittel: Glycerin; Maltodextrin, Oligofruktose, Wasser, F\u00fcllstoff: Maltitpolyole; Kokos\u00f6l, Magermilchpulver, modifizierte St\u00e4rke, Farbstoff: Zuckerkul\u00f6r; Verdickungsmittel: Pektin; S\u00e4ureregulator: Calciumlactat; Emulgator: Lecithine (Raps), Salz, nat\u00fcrliche Aromen, Verdickungsmittel: Xanthan; l\u00f6sliche Tapiokafasern, S\u00fc\u00dfungsmittel: Maltitolsirup, Sucralose, <strong data-start=\"3434\" data-end=\"3452\">Erdn\u00fcsse (3 %)<\/strong>, Wasser, gehackte <strong data-start=\"3471\" data-end=\"3489\">Erdn\u00fcsse (3 %)<\/strong>, nat\u00fcrliche Aromen.<\/p>\n<hr data-start=\"3511\" data-end=\"3514\" \/>\n<h4 data-start=\"3516\" data-end=\"3537\"><span class=\"ez-toc-section\" id=\"Allergiehinweise\"><\/span>Allergiehinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3539\" data-end=\"3584\">Enth\u00e4lt <strong data-start=\"3547\" data-end=\"3583\">Milch, Weizen, Soja und Erdn\u00fcsse<\/strong>.<\/p>\n<p data-start=\"3586\" data-end=\"3684\">Kann Spuren von <strong data-start=\"3602\" data-end=\"3673\">Gluten, Milch, Soja, Erdn\u00fcssen, N\u00fcssen, Schwefeldioxid und Sulfiten<\/strong> enthalten.<\/p>\n<hr data-start=\"3686\" data-end=\"3689\" \/>\n<h4 data-start=\"3691\" data-end=\"3713\"><span class=\"ez-toc-section\" id=\"Verzehrempfehlung\"><\/span>\u041f\u0440\u0435\u043f\u043e\u0440\u044a\u0447\u0438\u0442\u0435\u043b\u0435\u043d \u043f\u0440\u0438\u0435\u043c<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3715\" data-end=\"3808\">The <strong data-start=\"3719\" data-end=\"3760\">Proteinriegel Milchschokolade Erdnuss<\/strong> nach Bedarf als proteinreichen Snack verzehren.<\/p>\n<p data-start=\"3810\" data-end=\"3868\">Ideal f\u00fcr unterwegs, zwischendurch oder nach dem Training.<\/p>\n<p data-start=\"3870\" data-end=\"3938\"><strong data-start=\"3870\" data-end=\"3882\">\u0418\u0437\u0432\u0435\u0441\u0442\u0438\u0435:<\/strong> \u00dcberm\u00e4\u00dfiger Verzehr kann eine abf\u00fchrende Wirkung haben.<\/p>\n<hr data-start=\"3940\" data-end=\"3943\" \/>\n<h4 data-start=\"3945\" data-end=\"3962\"><span class=\"ez-toc-section\" id=\"Aufbewahrung\"><\/span>Aufbewahrung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3964\" data-end=\"4074\">K\u00fchl und trocken bei <strong data-start=\"3985\" data-end=\"3997\">15\u201322 \u00b0C<\/strong> lagern. Vor direkter Sonneneinstrahlung, Ger\u00fcchen und Feuchtigkeit sch\u00fctzen.<\/p>\n<p data-start=\"4076\" data-end=\"4125\">Au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"4127\" data-end=\"4170\"><strong data-start=\"4127\" data-end=\"4154\">Mindestens haltbar bis:<\/strong> siehe Aufdruck.<\/p>\n<hr data-start=\"4172\" data-end=\"4175\" \/>\n<h4 data-start=\"4177\" data-end=\"4216\"><span class=\"ez-toc-section\" id=\"Protein_Snack_fur_Sport_und_Alltag\"><\/span>Protein Snack f\u00fcr Sport und Alltag<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"4218\" data-end=\"4386\">The <strong data-start=\"4222\" data-end=\"4263\">Proteinriegel Milchschokolade Erdnuss<\/strong> von Applied Nutrition bietet <strong data-start=\"4293\" data-end=\"4319\">21 g Eiwei\u00df pro Riegel<\/strong> und eignet sich als praktische Proteinquelle f\u00fcr Sport und Alltag.<\/p>\n<p data-start=\"4388\" data-end=\"4588\" data-is-last-node=\"\" data-is-only-node=\"\">Mit Milchschokolade, Karamell und Erdn\u00fcssen bietet der Protein Crunch Bar eine knusprige Alternative zu klassischen Eiwei\u00dfriegeln und l\u00e4sst sich dank des <strong data-start=\"4542\" data-end=\"4558\">62-g-Formats<\/strong> einfach unterwegs mitnehmen.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"236\" data-end=\"393\"><em>Proteinriegel Milchschokolade Erdnuss von Applied Nutrition mit 21 g Eiwei\u00df und nur 1,9 g Zucker pro 62-g-Riegel. Knuspriger Protein Snack f\u00fcr unterwegs.<\/em><\/p>","protected":false},"featured_media":63618,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[1648],"product_cat":[426],"product_tag":[],"class_list":["post-63617","product","type-product","status-publish","has-post-thumbnail","product_brand-applied-nutrition","product_cat-proteinriegel-snacks","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product\/63617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/comments?post=63617"}],"version-history":[{"count":1,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product\/63617\/revisions"}],"predecessor-version":[{"id":63620,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product\/63617\/revisions\/63620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/media\/63618"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/media?parent=63617"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product_brand?post=63617"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product_cat?post=63617"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/bg\/wp-json\/wp\/v2\/product_tag?post=63617"}],"curies":[{"name":"\u0440\u0430\u0431\u043e\u0442\u043d\u0430 \u0441\u0440\u0435\u0449\u0430","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}