{"id":61910,"date":"2026-08-14T09:44:46","date_gmt":"2026-08-14T09:44:46","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/cornmint-50ml-essential-oil\/"},"modified":"2026-09-01T09:16:58","modified_gmt":"2026-09-01T09:16:58","slug":"ackerminze-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/","title":{"rendered":"Ackerminze \u00e4therisches \u00d6l 50 ml Cornmint aus China f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Obsah<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"P\u0159epnout obsah\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">P\u0159epnout<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Ackerminze_atherisches_Ol_50_ml\" >Ackerminze \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Intensiver_und_kuhlender_Minzduft\" >Intensiver und k\u00fchlender Minzduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Belebender_Duft_fur_Aromatherapie\" >Belebender Duft f\u00fcr Aromatherapie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Cornmint_%E2%80%93_Mentha_arvensis\" >Cornmint \u2013 Mentha arvensis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Produktdetails\" >Detaily produktu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/cs\/produkt\/ackerminze-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Bezpe\u010dnostn\u00ed pokyny<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"393\" data-end=\"429\"><span class=\"ez-toc-section\" id=\"Ackerminze_atherisches_Ol_50_ml\"><\/span>Ackerminze \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"431\" data-end=\"626\">Ten\/Ta\/To <strong data-start=\"435\" data-end=\"470\">Ackerminze \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Bl\u00e4ttern von <em data-start=\"497\" data-end=\"514\">Mentha arvensis<\/em> gewonnen. Die Pflanze ist international auch als <strong data-start=\"564\" data-end=\"576\">Cornmint<\/strong> bekannt und geh\u00f6rt zur Familie der Lippenbl\u00fctler.<\/p>\n<p data-start=\"628\" data-end=\"722\">Das f\u00fcr dieses \u00e4therische \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"712\" data-end=\"721\">China<\/strong>.<\/p>\n<hr data-start=\"724\" data-end=\"727\" \/>\n<h4 data-start=\"729\" data-end=\"772\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"774\" data-end=\"901\">F\u00fcr die Herstellung des <strong data-start=\"798\" data-end=\"833\">Ackerminze \u00e4therisches \u00d6l 50 ml<\/strong> werden die Bl\u00e4tter mittels <strong data-start=\"861\" data-end=\"888\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"903\" data-end=\"1031\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Ackerminze gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1033\" data-end=\"1036\" \/>\n<h4 data-start=\"1038\" data-end=\"1076\"><span class=\"ez-toc-section\" id=\"Intensiver_und_kuhlender_Minzduft\"><\/span>Intensiver und k\u00fchlender Minzduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1078\" data-end=\"1310\">Ackerminze besitzt einen <strong data-start=\"1103\" data-end=\"1177\">kr\u00e4ftigen, frischen, minzigen und charakteristisch k\u00fchl wirkenden Duft<\/strong>. Das intensive Aroma erinnert an Pfefferminze und sorgt bereits in kleinen Mengen f\u00fcr einen deutlich wahrnehmbaren Frischecharakter.<\/p>\n<p data-start=\"1312\" data-end=\"1402\">Dadurch eignet sich Cornmint besonders gut f\u00fcr frische Minz- und Kr\u00e4uterduftkompositionen.<\/p>\n<hr data-start=\"1404\" data-end=\"1407\" \/>\n<h4 data-start=\"1409\" data-end=\"1447\"><span class=\"ez-toc-section\" id=\"Belebender_Duft_fur_Aromatherapie\"><\/span>Belebender Duft f\u00fcr Aromatherapie<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1449\" data-end=\"1590\">In der Aromatherapie wird der intensive Minzduft traditionell mit einer <strong data-start=\"1521\" data-end=\"1579\">erfrischenden, belebenden und aktivierenden Atmosph\u00e4re<\/strong> verbunden.<\/p>\n<p data-start=\"1592\" data-end=\"1781\">Ten\/Ta\/To <strong data-start=\"1596\" data-end=\"1631\">Ackerminze \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen und kann besonders gut eingesetzt werden, wenn eine klare und frische Raumatmosph\u00e4re gew\u00fcnscht ist.<\/p>\n<hr data-start=\"1783\" data-end=\"1786\" \/>\n<h4 data-start=\"1788\" data-end=\"1819\"><span class=\"ez-toc-section\" id=\"Cornmint_%E2%80%93_Mentha_arvensis\"><\/span>Cornmint \u2013 Mentha arvensis<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1821\" data-end=\"2056\"><em data-start=\"1821\" data-end=\"1838\">Mentha arvensis<\/em> wird neben Ackerminze auch als <strong data-start=\"1870\" data-end=\"1883\">Feldminze<\/strong> bezeichnet. Die Pflanze ist f\u00fcr ihren ausgepr\u00e4gten Minzcharakter bekannt und wird aufgrund ihres aromatischen Profils f\u00fcr verschiedene Duft- und Aromaanwendungen verwendet.<\/p>\n<p data-start=\"2058\" data-end=\"2298\">In traditionellen spirituellen Anwendungen werden Minzd\u00fcfte au\u00dferdem teilweise mit <strong data-start=\"2141\" data-end=\"2192\">Reinigung und dem Vertreiben negativer Energien<\/strong> verbunden. Diese Verwendung beruht auf \u00fcberlieferten Vorstellungen und ist wissenschaftlich nicht belegt.<\/p>\n<hr data-start=\"2300\" data-end=\"2303\" \/>\n<h4 data-start=\"2305\" data-end=\"2324\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Detaily produktu<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2326\" data-end=\"2824\">\n<li data-section-id=\"ykhv0\" data-start=\"2326\" data-end=\"2372\"><strong data-start=\"2328\" data-end=\"2340\">Produkt:<\/strong> Ackerminze \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"103kdv\" data-start=\"2373\" data-end=\"2422\"><strong data-start=\"2375\" data-end=\"2401\">Weitere Bezeichnungen:<\/strong> Cornmint \/ Feldminze<\/li>\n<li data-section-id=\"nttq90\" data-start=\"2423\" data-end=\"2470\"><strong data-start=\"2425\" data-end=\"2452\">Botanische Bezeichnung:<\/strong> <em data-start=\"2453\" data-end=\"2470\">Mentha arvensis<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2471\" data-end=\"2490\"><strong data-start=\"2473\" data-end=\"2484\">Obsah:<\/strong> 50 ml<\/li>\n<li data-section-id=\"ai3jk0\" data-start=\"2491\" data-end=\"2530\"><strong data-start=\"2493\" data-end=\"2522\">Verwendeter Pflanzenteil:<\/strong> Bl\u00e4tter<\/li>\n<li data-section-id=\"rbx1tu\" data-start=\"2531\" data-end=\"2552\"><strong data-start=\"2533\" data-end=\"2546\">P\u016fvod:<\/strong> China<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2553\" data-end=\"2593\"><strong data-start=\"2555\" data-end=\"2569\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"gfgt23\" data-start=\"2594\" data-end=\"2653\"><strong data-start=\"2596\" data-end=\"2611\">Profil v\u016fn\u011b:<\/strong> Intensiv minzig \/ frisch \/ k\u00fchl \/ krautig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2654\" data-end=\"2705\"><strong data-start=\"2656\" data-end=\"2671\">Pou\u017eit\u00ed:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2706\" data-end=\"2763\"><strong data-start=\"2708\" data-end=\"2741\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2764\" data-end=\"2795\"><strong data-start=\"2766\" data-end=\"2785\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1quu2j8\" data-start=\"2796\" data-end=\"2824\"><strong data-start=\"2798\" data-end=\"2810\">Barcode:<\/strong> 5055796530076<\/li>\n<\/ul>\n<hr data-start=\"2826\" data-end=\"2829\" \/>\n<h4 data-start=\"2831\" data-end=\"2855\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Bezpe\u010dnostn\u00ed pokyny<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2857\" data-end=\"3059\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2895\" data-end=\"2959\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3061\" data-end=\"3221\">Ackerminz\u00f6l aufgrund seines intensiven Minzcharakters sparsam dosieren. Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen.<\/p>\n<p data-start=\"3223\" data-end=\"3371\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Ackerminze \u00e4therisches \u00d6l 50 ml aus China, durch Wasserdampfdestillation der Bl\u00e4tter gewonnen. Intensiv minziger Duft f\u00fcr Aromatherapie und Raumduft.<\/em><\/p>","protected":false},"featured_media":61888,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61910","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/61910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/comments?post=61910"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/61910\/revisions"}],"predecessor-version":[{"id":63642,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/61910\/revisions\/63642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/media\/61888"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/media?parent=61910"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_brand?post=61910"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_cat?post=61910"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_tag?post=61910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}