{"id":62129,"date":"2026-08-14T09:48:03","date_gmt":"2026-08-14T09:48:03","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/palmarosa-50ml-essential-oil\/"},"modified":"2026-08-31T15:55:42","modified_gmt":"2026-08-31T15:55:42","slug":"palmarosa-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/","title":{"rendered":"Palmarosa \u00e4therisches \u00d6l 50 ml aus Indien f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Palmarosa_atherisches_Ol_50_ml\" >Palmarosa \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Rosiger_und_blumiger_Duft\" >Rosiger und blumiger Duft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Beliebt_in_kosmetischen_Duftmischungen\" >Beliebt in kosmetischen Duftmischungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_entspannende_Duftanwendungen\" >F\u00fcr Aromatherapie und entspannende Duftanwendungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/cs\/produkt\/palmarosa-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-3\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-3\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-3\" data-testid=\"conversation-turn-18\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"836ad202-3c61-4259-8aa9-56ae39373ae7\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"383\" data-end=\"418\"><span class=\"ez-toc-section\" id=\"Palmarosa_atherisches_Ol_50_ml\"><\/span>Palmarosa \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"420\" data-end=\"650\">Das <strong data-start=\"424\" data-end=\"458\">Palmarosa \u00e4therisches \u00d6l 50 ml<\/strong> wird aus dem Gras von <em data-start=\"481\" data-end=\"502\">Cymbopogon martinii<\/em> gewonnen. Palmarosa geh\u00f6rt zur Familie der S\u00fc\u00dfgr\u00e4ser und ist besonders f\u00fcr seinen <strong data-start=\"585\" data-end=\"641\">angenehm rosigen, blumigen und leicht s\u00fc\u00dflichen Duft<\/strong> bekannt.<\/p>\n<p data-start=\"652\" data-end=\"738\">Die f\u00fcr dieses \u00e4therische \u00d6l verwendete Pflanze stammt laut Hersteller aus <strong data-start=\"727\" data-end=\"737\">Indien<\/strong>.<\/p>\n<hr data-start=\"740\" data-end=\"743\" \/>\n<h4 data-start=\"745\" data-end=\"788\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"790\" data-end=\"911\">F\u00fcr die Herstellung des <strong data-start=\"814\" data-end=\"848\">Palmarosa \u00e4therisches \u00d6l 50 ml<\/strong> wird das Gras mittels <strong data-start=\"871\" data-end=\"898\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"913\" data-end=\"1047\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Pflanze schonend gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1049\" data-end=\"1052\" \/>\n<h4 data-start=\"1054\" data-end=\"1084\"><span class=\"ez-toc-section\" id=\"Rosiger_und_blumiger_Duft\"><\/span>Rosiger und blumiger Duft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1086\" data-end=\"1284\">Obwohl Palmarosa botanisch nicht mit der Rose verwandt ist, erinnert sein charakteristisches Aroma deutlich an einen <strong data-start=\"1203\" data-end=\"1224\">sanften Rosenduft<\/strong>. Dazu kommen frische, leicht krautige und s\u00fc\u00dfliche Nuancen.<\/p>\n<p data-start=\"1286\" data-end=\"1419\">Dieses vielseitige Duftprofil macht Palmarosa zu einer beliebten Komponente in <strong data-start=\"1365\" data-end=\"1418\">Parf\u00fcm-, Kosmetik- und nat\u00fcrlichen Duftmischungen<\/strong>.<\/p>\n<hr data-start=\"1421\" data-end=\"1424\" \/>\n<h4 data-start=\"1426\" data-end=\"1469\"><span class=\"ez-toc-section\" id=\"Beliebt_in_kosmetischen_Duftmischungen\"><\/span>Beliebt in kosmetischen Duftmischungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1471\" data-end=\"1609\">Palmarosa\u00f6l wird traditionell gerne als aromatischer Bestandteil von <strong data-start=\"1540\" data-end=\"1597\">Seifen, Cremes, K\u00f6rperpflege- und Massage\u00f6lmischungen<\/strong> eingesetzt.<\/p>\n<p data-start=\"1611\" data-end=\"1744\">Bei kosmetischen Anwendungen muss das konzentrierte \u00e4therische \u00d6l entsprechend der vorgesehenen Rezeptur ausreichend verd\u00fcnnt werden.<\/p>\n<hr data-start=\"1746\" data-end=\"1749\" \/>\n<h4 data-start=\"1751\" data-end=\"1806\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_entspannende_Duftanwendungen\"><\/span>F\u00fcr Aromatherapie und entspannende Duftanwendungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1808\" data-end=\"1927\">Das <strong data-start=\"1812\" data-end=\"1846\">Palmarosa \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser, Duftlampen und individuelle Aromamischungen.<\/p>\n<p data-start=\"1929\" data-end=\"2185\">In der Aromatherapie wird sein rosig-weicher Duft traditionell mit einer <strong data-start=\"2002\" data-end=\"2071\">ruhigen, harmonischen und zugleich angenehm belebenden Atmosph\u00e4re<\/strong> verbunden. Dadurch eignet er sich sowohl f\u00fcr entspannte Abendstunden als auch f\u00fcr eine ausgewogene Raumbeduftung.<\/p>\n<hr data-start=\"2187\" data-end=\"2190\" \/>\n<h4 data-start=\"2192\" data-end=\"2211\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2213\" data-end=\"2686\">\n<li data-section-id=\"13qdyl5\" data-start=\"2213\" data-end=\"2258\"><strong data-start=\"2215\" data-end=\"2227\">Produkt:<\/strong> Palmarosa \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"ijegpy\" data-start=\"2259\" data-end=\"2283\"><strong data-start=\"2261\" data-end=\"2273\">Pflanze:<\/strong> Palmarosa<\/li>\n<li data-section-id=\"14xqffa\" data-start=\"2284\" data-end=\"2335\"><strong data-start=\"2286\" data-end=\"2313\">Botanische Bezeichnung:<\/strong> <em data-start=\"2314\" data-end=\"2335\">Cymbopogon martinii<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2336\" data-end=\"2355\"><strong data-start=\"2338\" data-end=\"2349\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"zbyo3e\" data-start=\"2356\" data-end=\"2392\"><strong data-start=\"2358\" data-end=\"2387\">Verwendeter Pflanzenteil:<\/strong> Gras<\/li>\n<li data-section-id=\"1cav5hq\" data-start=\"2393\" data-end=\"2415\"><strong data-start=\"2395\" data-end=\"2408\">Herkunft:<\/strong> Indien<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2416\" data-end=\"2456\"><strong data-start=\"2418\" data-end=\"2432\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1fdsrw\" data-start=\"2457\" data-end=\"2515\"><strong data-start=\"2459\" data-end=\"2474\">Duftprofil:<\/strong> Rosig \/ blumig \/ leicht s\u00fc\u00dflich \/ frisch<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2516\" data-end=\"2567\"><strong data-start=\"2518\" data-end=\"2533\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2568\" data-end=\"2625\"><strong data-start=\"2570\" data-end=\"2603\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2626\" data-end=\"2657\"><strong data-start=\"2628\" data-end=\"2647\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswpcu\" data-start=\"2658\" data-end=\"2686\"><strong data-start=\"2660\" data-end=\"2672\">Barcode:<\/strong> 5055796529605<\/li>\n<\/ul>\n<hr data-start=\"2688\" data-end=\"2691\" \/>\n<h4 data-start=\"2693\" data-end=\"2717\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2719\" data-end=\"2921\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2757\" data-end=\"2821\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"2923\" data-end=\"3081\">Bei einer vorgesehenen kosmetischen oder \u00e4u\u00dferlichen Anwendung ausreichend mit einem geeigneten Basis\u00f6l oder entsprechend einer geeigneten Rezeptur verd\u00fcnnen.<\/p>\n<p data-start=\"3083\" data-end=\"3231\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"222\" data-end=\"376\"><em>Palmarosa \u00e4therisches \u00d6l 50 ml aus Indien, durch Wasserdampfdestillation aus Gras gewonnen. Rosig-blumiger Duft f\u00fcr Aromatherapie und Duftanwendungen.<\/em><\/p>","protected":false},"featured_media":62112,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62129","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/62129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/comments?post=62129"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/62129\/revisions"}],"predecessor-version":[{"id":63637,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product\/62129\/revisions\/63637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/media\/62112"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/media?parent=62129"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_brand?post=62129"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_cat?post=62129"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/cs\/wp-json\/wp\/v2\/product_tag?post=62129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}