{"id":61430,"date":"2026-08-05T11:03:54","date_gmt":"2026-08-05T11:03:54","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/tropical-paradise-soap-slice-pomelo\/"},"modified":"2026-08-27T15:16:26","modified_gmt":"2026-08-27T15:16:26","slug":"tropische-seife-pomeloduft-115-g","status":"publish","type":"product","link":"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/","title":{"rendered":"Tropische Seife Pomeloduft 115 g handgefertigte Naturseife"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Frische_Reinigung_mit_spritzigem_Pomeloduft\" >Frische Reinigung mit spritzigem Pomeloduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Sanfte_Pflege_mit_Glycerin_und_Kokosol\" >Sanfte Pflege mit Glycerin und Kokos\u00f6l<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Handgefertigte_Naturseife_mit_individuellem_Charakter\" >Handgefertigte Naturseife mit individuellem Charakter<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Ideal_fur_die_tagliche_Korperpflege\" >Ideal f\u00fcr die t\u00e4gliche K\u00f6rperpflege<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Anwendung\" >Anwendung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Inhaltsstoffe\" >Inhaltsstoffe<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/el\/product\/tropische-seife-pomeloduft-115-g\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-6\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-6\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-6\" data-testid=\"conversation-turn-1332\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"5c9eb17b-0781-439d-9378-2abc9b71c7a8\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"408\" data-end=\"456\"><span class=\"ez-toc-section\" id=\"Frische_Reinigung_mit_spritzigem_Pomeloduft\"><\/span>Frische Reinigung mit spritzigem Pomeloduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"458\" data-end=\"703\">Die <strong data-start=\"462\" data-end=\"492\">Tropische Seife Pomeloduft<\/strong> begeistert mit dem charakteristischen Duft der Pomelo \u2013 einer harmonischen Kombination aus s\u00fc\u00dfen und frischen Zitrusnoten. Sie sorgt f\u00fcr ein belebendes Pflegeerlebnis und bringt tropische Frische in den Alltag.<\/p>\n<hr data-start=\"705\" data-end=\"708\" \/>\n<h4 data-start=\"710\" data-end=\"753\"><span class=\"ez-toc-section\" id=\"Sanfte_Pflege_mit_Glycerin_und_Kokosol\"><\/span>Sanfte Pflege mit Glycerin und Kokos\u00f6l<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"755\" data-end=\"979\">Die <strong data-start=\"759\" data-end=\"789\">Tropische Seife Pomeloduft<\/strong> enth\u00e4lt hochwertiges Glycerin und pflegendes Kokos\u00f6l. Der cremige Schaum reinigt H\u00e4nde, Gesicht und K\u00f6rper besonders sanft und hinterl\u00e4sst die Haut angenehm weich, geschmeidig und gepflegt.<\/p>\n<hr data-start=\"981\" data-end=\"984\" \/>\n<h4 data-start=\"986\" data-end=\"1044\"><span class=\"ez-toc-section\" id=\"Handgefertigte_Naturseife_mit_individuellem_Charakter\"><\/span>Handgefertigte Naturseife mit individuellem Charakter<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1046\" data-end=\"1247\">Jede <strong data-start=\"1051\" data-end=\"1081\">Tropische Seife Pomeloduft<\/strong> wird sorgf\u00e4ltig von Hand hergestellt. Dadurch k\u00f6nnen Farbe und Muster leicht variieren, sodass jedes Seifenst\u00fcck ein einzigartiges Unikat mit nat\u00fcrlichem Charme ist.<\/p>\n<hr data-start=\"1249\" data-end=\"1252\" \/>\n<h4 data-start=\"1254\" data-end=\"1294\"><span class=\"ez-toc-section\" id=\"Ideal_fur_die_tagliche_Korperpflege\"><\/span>Ideal f\u00fcr die t\u00e4gliche K\u00f6rperpflege<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1296\" data-end=\"1563\">Ob f\u00fcr das Waschbecken, die Dusche oder als Geschenk \u2013 die <strong data-start=\"1355\" data-end=\"1385\">Tropische Seife Pomeloduft<\/strong> \u00fcberzeugt mit ihrem frischen Duft und ihrer hochwertigen Verarbeitung. Sie eignet sich hervorragend f\u00fcr die t\u00e4gliche Reinigung und als stilvolle Erg\u00e4nzung jeder Wellnessroutine.<\/p>\n<hr data-start=\"1565\" data-end=\"1568\" \/>\n<h4 data-start=\"1570\" data-end=\"1589\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"1591\" data-end=\"1834\">\n<li data-section-id=\"a1olhq\" data-start=\"1591\" data-end=\"1619\">Tropische Seife Pomeloduft<\/li>\n<li data-section-id=\"1quu53n\" data-start=\"1620\" data-end=\"1647\">Handgefertigte Naturseife<\/li>\n<li data-section-id=\"cvy17z\" data-start=\"1648\" data-end=\"1674\">Mit Glycerin und Kokos\u00f6l<\/li>\n<li data-section-id=\"spzhc1\" data-start=\"1675\" data-end=\"1708\">Frischer, fruchtiger Zitrusduft<\/li>\n<li data-section-id=\"djoz92\" data-start=\"1709\" data-end=\"1757\">Sanfte Reinigung f\u00fcr H\u00e4nde, Gesicht und K\u00f6rper<\/li>\n<li data-section-id=\"11xzy6h\" data-start=\"1758\" data-end=\"1775\">Cremiger Schaum<\/li>\n<li data-section-id=\"174zwl0\" data-start=\"1776\" data-end=\"1810\">Jedes Seifenst\u00fcck ist ein Unikat<\/li>\n<li data-section-id=\"a56wt6\" data-start=\"1811\" data-end=\"1834\">Inhalt: <strong data-start=\"1821\" data-end=\"1834\">ca. 115 g<\/strong><\/li>\n<\/ul>\n<hr data-start=\"1836\" data-end=\"1839\" \/>\n<h4 data-start=\"1841\" data-end=\"1855\"><span class=\"ez-toc-section\" id=\"Anwendung\"><\/span>Anwendung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1857\" data-end=\"2017\">Die <strong data-start=\"1861\" data-end=\"1891\">Tropische Seife Pomeloduft<\/strong> mit Wasser aufsch\u00e4umen, sanft auf H\u00e4nde, Gesicht oder K\u00f6rper auftragen und anschlie\u00dfend gr\u00fcndlich mit klarem Wasser absp\u00fclen.<\/p>\n<hr data-start=\"2019\" data-end=\"2022\" \/>\n<h4 data-start=\"2024\" data-end=\"2042\"><span class=\"ez-toc-section\" id=\"Inhaltsstoffe\"><\/span>Inhaltsstoffe<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2044\" data-end=\"2373\" data-is-last-node=\"\" data-is-only-node=\"\">Aqua, Glycerin, Sorbitol, Sodium Stearate, Sodium Laurate, Propylene Glycol, Sodium Oleate, Sodium Myristate, Sodium Chloride, Parfum, Cocos Nucifera (Coconut) Oil, Glyceryl Laurate, Cocamidopropyl Betaine, Sodium Citrate, Citric Acid, Tetrasodium Iminodisuccinate, Tetrasodium Etidronate, CI 77891, CI 42090, CI 19140, Limonene.<\/p>\n<hr data-start=\"1683\" data-end=\"1686\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Die Tropische Seife Pomeloduft reinigt die Haut sanft und verw\u00f6hnt mit einem frischen, fruchtigen Zitrusduft. Die handgefertigte Naturseife mit Glycerin und Kokos\u00f6l eignet sich f\u00fcr H\u00e4nde, Gesicht und K\u00f6rper.<\/em><\/p>","protected":false},"featured_media":61421,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[943],"product_tag":[],"class_list":["post-61430","product","type-product","status-publish","has-post-thumbnail","product_cat-handgemachte-seifen","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/61430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/comments?post=61430"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/61430\/revisions"}],"predecessor-version":[{"id":61459,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/61430\/revisions\/61459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/media\/61421"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/media?parent=61430"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_brand?post=61430"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_cat?post=61430"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_tag?post=61430"}],"curies":[{"name":"\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}