{"id":63551,"date":"2026-08-30T12:16:17","date_gmt":"2026-08-30T12:16:17","guid":{"rendered":"https:\/\/honigbee.com\/?post_type=product&#038;p=63551"},"modified":"2026-08-30T12:21:52","modified_gmt":"2026-08-30T12:21:52","slug":"agewell-40-organschutz-pfirsich-300-g","status":"publish","type":"product","link":"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/","title":{"rendered":"Applied Nutrition Agewell 40+ Organschutz Pfirsich 300 g \u2013 Vitamine &#038; Pflanzenextrakte"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u03a0\u03af\u03bd\u03b1\u03ba\u03b1\u03c2 \u03c0\u03b5\u03c1\u03b9\u03b5\u03c7\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u0395\u03bd\u03b1\u03bb\u03bb\u03b1\u03b3\u03ae \u03a0\u03af\u03bd\u03b1\u03ba\u03b1 \u03a0\u03b5\u03c1\u03b9\u03b5\u03c7\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">\u039c\u03c0\u03b1\u03c1\u03ad\u03c4\u03b1<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Agewell_40_Organschutz_Pfirsich\" >Agewell 40+ Organschutz Pfirsich<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Mit_Vitaminen_und_Mineralstoffen\" >Mit Vitaminen und Mineralstoffen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#NAC_Cholin_und_Coenzym_Q10\" >NAC, Cholin und Coenzym Q10<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Ausgewahlte_Pflanzenextrakte\" >Ausgew\u00e4hlte Pflanzenextrakte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Inhaltsstoffe_pro_Tagesportion\" >Inhaltsstoffe pro Tagesportion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Zutaten\" >\u03a3\u03c5\u03c3\u03c4\u03b1\u03c4\u03b9\u03ba\u03ac<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Einnahmeempfehlung\" >Einnahmeempfehlung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/el\/product\/agewell-40-organschutz-pfirsich-300-g\/#Wichtige_Hinweise\" >Wichtige Hinweise<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"939\" data-end=\"976\"><span class=\"ez-toc-section\" id=\"Agewell_40_Organschutz_Pfirsich\"><\/span>Agewell 40+ Organschutz Pfirsich<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"978\" data-end=\"1146\">\u039f <strong data-start=\"982\" data-end=\"1018\">Agewell 40+ Organschutz Pfirsich<\/strong> von Applied Nutrition ist ein vielseitiges Nahrungserg\u00e4nzungsmittel, das speziell f\u00fcr Erwachsene ab 40 Jahren entwickelt wurde.<\/p>\n<p data-start=\"1148\" data-end=\"1429\">Die umfangreiche Formel kombiniert ausgew\u00e4hlte <strong data-start=\"1195\" data-end=\"1263\">Vitamine, Mineralstoffe, Aminos\u00e4urederivate und Pflanzenextrakte<\/strong>. Enthalten sind unter anderem Vitamin C, Vitamin D3, Vitamin E, Vitamin K2, Zink, Selen, N-Acetyl-L-Cystein, Cholin, Coenzym Q10 sowie verschiedene Pflanzenextrakte.<\/p>\n<p data-start=\"1431\" data-end=\"1525\">Die 300-g-Dose enth\u00e4lt <strong data-start=\"1454\" data-end=\"1477\">30 Portionen \u00e0 10 g<\/strong> und besitzt einen fruchtigen Pfirsichgeschmack.<\/p>\n<hr data-start=\"1527\" data-end=\"1530\" \/>\n<h4 data-start=\"1532\" data-end=\"1569\"><span class=\"ez-toc-section\" id=\"Mit_Vitaminen_und_Mineralstoffen\"><\/span>Mit Vitaminen und Mineralstoffen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1571\" data-end=\"1685\">Eine Tagesportion des <strong data-start=\"1593\" data-end=\"1629\">Agewell 40+ Organschutz Pfirsich<\/strong> enth\u00e4lt eine Kombination verschiedener Mikron\u00e4hrstoffe.<\/p>\n<p data-start=\"1687\" data-end=\"1934\">Vitamin C und Selen tragen zum Schutz der Zellen vor oxidativem Stress bei. Vitamin D tr\u00e4gt zu einer normalen Funktion des Immunsystems bei. Zink tr\u00e4gt zu einem normalen S\u00e4ure-Basen-Stoffwechsel und zu einer normalen Funktion des Immunsystems bei.<\/p>\n<p data-start=\"1936\" data-end=\"2037\">Zus\u00e4tzlich enth\u00e4lt die Formel unter anderem Vitamin E, Vitamin K2, Vitamin B1, Vitamin B2 und Kalium.<\/p>\n<hr data-start=\"2039\" data-end=\"2042\" \/>\n<h4 data-start=\"2044\" data-end=\"2076\"><span class=\"ez-toc-section\" id=\"NAC_Cholin_und_Coenzym_Q10\"><\/span>NAC, Cholin und Coenzym Q10<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2078\" data-end=\"2152\">Die Rezeptur liefert pro Tagesportion <strong data-start=\"2116\" data-end=\"2151\">250 mg N-Acetyl-L-Cystein (NAC)<\/strong>.<\/p>\n<p data-start=\"2154\" data-end=\"2349\">Au\u00dferdem sind <strong data-start=\"2168\" data-end=\"2211\">200 mg Cholinbitartrat als VitaCholine\u00ae<\/strong> enthalten, davon <strong data-start=\"2229\" data-end=\"2246\">101 mg Cholin<\/strong>. Cholin tr\u00e4gt zur Erhaltung einer normalen Leberfunktion sowie zu einem normalen Fettstoffwechsel bei.<\/p>\n<p data-start=\"2351\" data-end=\"2429\">Erg\u00e4nzt wird die Zusammensetzung durch <strong data-start=\"2390\" data-end=\"2411\">50 mg Coenzym Q10<\/strong> pro Tagesportion.<\/p>\n<hr data-start=\"2431\" data-end=\"2434\" \/>\n<h4 data-start=\"2436\" data-end=\"2469\"><span class=\"ez-toc-section\" id=\"Ausgewahlte_Pflanzenextrakte\"><\/span>Ausgew\u00e4hlte Pflanzenextrakte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2471\" data-end=\"2563\">Neben Vitaminen und Mineralstoffen enth\u00e4lt die Formel verschiedene pflanzliche Bestandteile.<\/p>\n<p data-start=\"2565\" data-end=\"2611\">Pro Tagesportion sind unter anderem enthalten:<\/p>\n<ul data-start=\"2613\" data-end=\"2854\">\n<li data-section-id=\"r8zpcj\" data-start=\"2613\" data-end=\"2652\"><strong data-start=\"2615\" data-end=\"2652\">300 mg L\u00f6wenzahnwurzelextrakt 4:1<\/strong><\/li>\n<li data-section-id=\"n8l831\" data-start=\"2653\" data-end=\"2680\"><strong data-start=\"2655\" data-end=\"2680\">250 mg Wacholderbeere<\/strong><\/li>\n<li data-section-id=\"190ilp1\" data-start=\"2681\" data-end=\"2715\"><strong data-start=\"2683\" data-end=\"2715\">160 mg Rote-Bete-Extrakt 4:1<\/strong><\/li>\n<li data-section-id=\"q35no8\" data-start=\"2716\" data-end=\"2752\"><strong data-start=\"2718\" data-end=\"2752\">100 mg Goji-Beeren-Extrakt 5:1<\/strong><\/li>\n<li data-section-id=\"1mq5eyq\" data-start=\"2753\" data-end=\"2781\"><strong data-start=\"2755\" data-end=\"2781\">100 mg Hibiskus-Pulver<\/strong><\/li>\n<li data-section-id=\"1re6arv\" data-start=\"2782\" data-end=\"2822\"><strong data-start=\"2784\" data-end=\"2822\">70 mg Artischockenblattextrakt 5:1<\/strong><\/li>\n<li data-section-id=\"s4la6e\" data-start=\"2823\" data-end=\"2854\"><strong data-start=\"2825\" data-end=\"2854\">50 mg Traubenkern-Extrakt<\/strong><\/li>\n<\/ul>\n<p data-start=\"2856\" data-end=\"2957\">Damit verbindet das Produkt zahlreiche ausgew\u00e4hlte Inhaltsstoffe in einer einzigen t\u00e4glichen Portion.<\/p>\n<hr data-start=\"2959\" data-end=\"2962\" \/>\n<h4 data-start=\"2964\" data-end=\"2999\"><span class=\"ez-toc-section\" id=\"Inhaltsstoffe_pro_Tagesportion\"><\/span>Inhaltsstoffe pro Tagesportion<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3001\" data-end=\"3038\"><strong data-start=\"3001\" data-end=\"3038\">Tagesportion: 1 Messl\u00f6ffel (10 g)<\/strong><\/p>\n<div class=\"group TyagGW_tableContainer\">\n<div class=\"TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"3040\" data-end=\"3713\">\n<thead data-start=\"3040\" data-end=\"3075\">\n<tr data-start=\"3040\" data-end=\"3075\">\n<th class=\"last:pe-10\" data-start=\"3040\" data-end=\"3055\" data-col-size=\"sm\">Inhaltsstoff<\/th>\n<th class=\"last:pe-10\" data-start=\"3055\" data-end=\"3075\" data-col-size=\"sm\">Pro Tagesportion<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"3087\" data-end=\"3713\">\n<tr data-start=\"3087\" data-end=\"3108\">\n<td data-start=\"3087\" data-end=\"3100\" data-col-size=\"sm\">\u0392\u03b9\u03c4\u03b1\u03bc\u03af\u03bd\u03b7 D3<\/td>\n<td data-start=\"3100\" data-end=\"3108\" data-col-size=\"sm\">5 \u00b5g<\/td>\n<\/tr>\n<tr data-start=\"3109\" data-end=\"3132\">\n<td data-start=\"3109\" data-end=\"3121\" data-col-size=\"sm\">\u0392\u03b9\u03c4\u03b1\u03bc\u03af\u03bd\u03b7 \u0395<\/td>\n<td data-start=\"3121\" data-end=\"3132\" data-col-size=\"sm\">6,80 mg<\/td>\n<\/tr>\n<tr data-start=\"3133\" data-end=\"3154\">\n<td data-start=\"3133\" data-end=\"3145\" data-col-size=\"sm\">\u0392\u03b9\u03c4\u03b1\u03bc\u03af\u03bd\u03b7 C<\/td>\n<td data-start=\"3145\" data-end=\"3154\" data-col-size=\"sm\">80 mg<\/td>\n<\/tr>\n<tr data-start=\"3155\" data-end=\"3186\">\n<td data-start=\"3155\" data-end=\"3178\" data-col-size=\"sm\">Thiamin (Vitamin B1)<\/td>\n<td data-start=\"3178\" data-end=\"3186\" data-col-size=\"sm\">1 mg<\/td>\n<\/tr>\n<tr data-start=\"3187\" data-end=\"3221\">\n<td data-start=\"3187\" data-end=\"3213\" data-col-size=\"sm\">Riboflavin (Vitamin B2)<\/td>\n<td data-start=\"3213\" data-end=\"3221\" data-col-size=\"sm\">1 mg<\/td>\n<\/tr>\n<tr data-start=\"3222\" data-end=\"3241\">\n<td data-start=\"3222\" data-end=\"3231\" data-col-size=\"sm\">\u03ba\u03ac\u03bb\u03b9\u03bf<\/td>\n<td data-start=\"3231\" data-end=\"3241\" data-col-size=\"sm\">300 mg<\/td>\n<\/tr>\n<tr data-start=\"3242\" data-end=\"3258\">\n<td data-start=\"3242\" data-end=\"3249\" data-col-size=\"sm\">\u03c8\u03b5\u03c5\u03b4\u03ac\u03c1\u03b3\u03c5\u03c1\u03bf\u03c2<\/td>\n<td data-start=\"3249\" data-end=\"3258\" data-col-size=\"sm\">14 mg<\/td>\n<\/tr>\n<tr data-start=\"3259\" data-end=\"3277\">\n<td data-start=\"3259\" data-end=\"3267\" data-col-size=\"sm\">\u03c3\u03b5\u03bb\u03ae\u03bd\u03b9\u03bf<\/td>\n<td data-start=\"3267\" data-end=\"3277\" data-col-size=\"sm\">200 \u00b5g<\/td>\n<\/tr>\n<tr data-start=\"3278\" data-end=\"3311\">\n<td data-start=\"3278\" data-end=\"3301\" data-col-size=\"sm\">Palmitoylethanolamid<\/td>\n<td data-start=\"3301\" data-end=\"3311\" data-col-size=\"sm\">300 mg<\/td>\n<\/tr>\n<tr data-start=\"3312\" data-end=\"3351\">\n<td data-start=\"3312\" data-end=\"3341\" data-col-size=\"sm\">L\u00f6wenzahnwurzelextrakt 4:1<\/td>\n<td data-start=\"3341\" data-end=\"3351\" data-col-size=\"sm\">300 mg<\/td>\n<\/tr>\n<tr data-start=\"3352\" data-end=\"3379\">\n<td data-start=\"3352\" data-end=\"3369\" data-col-size=\"sm\">Wacholderbeere<\/td>\n<td data-start=\"3369\" data-end=\"3379\" data-col-size=\"sm\">250 mg<\/td>\n<\/tr>\n<tr data-start=\"3380\" data-end=\"3411\">\n<td data-start=\"3380\" data-end=\"3401\" data-col-size=\"sm\">N-Acetyl-L-Cystein<\/td>\n<td data-start=\"3401\" data-end=\"3411\" data-col-size=\"sm\">250 mg<\/td>\n<\/tr>\n<tr data-start=\"3412\" data-end=\"3457\">\n<td data-start=\"3412\" data-end=\"3447\" data-col-size=\"sm\">Cholinbitartrat als VitaCholine\u00ae<\/td>\n<td data-start=\"3447\" data-end=\"3457\" data-col-size=\"sm\">200 mg<\/td>\n<\/tr>\n<tr data-start=\"3458\" data-end=\"3483\">\n<td data-start=\"3458\" data-end=\"3473\" data-col-size=\"sm\">davon Cholin<\/td>\n<td data-start=\"3473\" data-end=\"3483\" data-col-size=\"sm\">101 mg<\/td>\n<\/tr>\n<tr data-start=\"3484\" data-end=\"3518\">\n<td data-start=\"3484\" data-end=\"3508\" data-col-size=\"sm\">Rote-Bete-Extrakt 4:1<\/td>\n<td data-start=\"3508\" data-end=\"3518\" data-col-size=\"sm\">160 mg<\/td>\n<\/tr>\n<tr data-start=\"3519\" data-end=\"3555\">\n<td data-start=\"3519\" data-end=\"3545\" data-col-size=\"sm\">Goji-Beeren-Extrakt 5:1<\/td>\n<td data-start=\"3545\" data-end=\"3555\" data-col-size=\"sm\">100 mg<\/td>\n<\/tr>\n<tr data-start=\"3556\" data-end=\"3584\">\n<td data-start=\"3556\" data-end=\"3574\" data-col-size=\"sm\">Hibiskus-Pulver<\/td>\n<td data-start=\"3574\" data-end=\"3584\" data-col-size=\"sm\">100 mg<\/td>\n<\/tr>\n<tr data-start=\"3585\" data-end=\"3625\">\n<td data-start=\"3585\" data-end=\"3616\" data-col-size=\"sm\">Artischockenblattextrakt 5:1<\/td>\n<td data-start=\"3616\" data-end=\"3625\" data-col-size=\"sm\">70 mg<\/td>\n<\/tr>\n<tr data-start=\"3626\" data-end=\"3649\">\n<td data-start=\"3626\" data-end=\"3640\" data-col-size=\"sm\">\u03a3\u03c5\u03bd\u03ad\u03bd\u03b6\u03c5\u03bc\u03bf Q10<\/td>\n<td data-start=\"3640\" data-end=\"3649\" data-col-size=\"sm\">50 mg<\/td>\n<\/tr>\n<tr data-start=\"3650\" data-end=\"3681\">\n<td data-start=\"3650\" data-end=\"3672\" data-col-size=\"sm\">Traubenkern-Extrakt<\/td>\n<td data-start=\"3672\" data-end=\"3681\" data-col-size=\"sm\">50 mg<\/td>\n<\/tr>\n<tr data-start=\"3682\" data-end=\"3713\">\n<td data-start=\"3682\" data-end=\"3704\" data-col-size=\"sm\">Vitamin K2 als MK-7<\/td>\n<td data-start=\"3704\" data-end=\"3713\" data-col-size=\"sm\">20 \u00b5g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<hr data-start=\"3715\" data-end=\"3718\" \/>\n<h4 data-start=\"3720\" data-end=\"3732\"><span class=\"ez-toc-section\" id=\"Zutaten\"><\/span>\u03a3\u03c5\u03c3\u03c4\u03b1\u03c4\u03b9\u03ba\u03ac<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3734\" data-end=\"4397\"><strong data-start=\"3734\" data-end=\"3746\">\u03a3\u03c5\u03c3\u03c4\u03b1\u03c4\u03b9\u03ba\u03ac:<\/strong> Inulin, Maltodextrin, S\u00e4ureregulator: Citronens\u00e4ure; Aroma, Trennmittel: Siliciumdioxid; Palmitoylethanolamid, L\u00f6wenzahnwurzelextrakt (4:1), S\u00e4ureregulator: Kaliumcitrate; N-Acetyl-L-Cystein, Cholinbitartrat als VitaCholine\u00ae, Wacholderbeere, S\u00fc\u00dfungsmittel: Sucralose; Rote-Bete-Extrakt (4:1), Traubenkernextrakt, Hibiskuspulver, Vitamin C (L-Ascorbins\u00e4ure), Artischockenblattextrakt (5:1), Vitamin E (DL-alpha-Tocopherylacetat), Goji-Beeren-Extrakt (5:1), Coenzym Q10, Vitamin K2 Menachinon-7 (MK7), Vitamin D3 (Cholecalciferol), Farbstoff: Carotin, Betenrot, Zinkbisglycinat, Thiamin (Vitamin B1), Riboflavin (Vitamin B2), Selen (L-Selenomethionin).<\/p>\n<p data-start=\"4399\" data-end=\"4532\"><strong data-start=\"4399\" data-end=\"4419\">Allergiehinweis:<\/strong> Kann <strong data-start=\"4425\" data-end=\"4488\">Milch, Soja, Eier, Fisch, Sellerie, glutenhaltiges Getreide<\/strong> und daraus hergestellte Produkte enthalten.<\/p>\n<hr data-start=\"4534\" data-end=\"4537\" \/>\n<h4 data-start=\"4539\" data-end=\"4562\"><span class=\"ez-toc-section\" id=\"Einnahmeempfehlung\"><\/span>Einnahmeempfehlung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"4564\" data-end=\"4679\"><strong data-start=\"4564\" data-end=\"4587\">1 Messl\u00f6ffel (10 g)<\/strong> \u03bc\u03b5 <strong data-start=\"4592\" data-end=\"4620\">250\u2013500 ml kaltem Wasser<\/strong> mischen, sch\u00fctteln oder umr\u00fchren und anschlie\u00dfend trinken.<\/p>\n<p data-start=\"4681\" data-end=\"4713\"><strong data-start=\"4681\" data-end=\"4713\">T\u00e4glich 1 Portion einnehmen.<\/strong><\/p>\n<hr data-start=\"4715\" data-end=\"4718\" \/>\n<h4 data-start=\"4720\" data-end=\"4742\"><span class=\"ez-toc-section\" id=\"Wichtige_Hinweise\"><\/span>Wichtige Hinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"4744\" data-end=\"4907\">Nicht f\u00fcr Personen unter 18 Jahren, Schwangere, Stillende, bei Vorerkrankungen oder bei Einnahme verschreibungspflichtiger oder rezeptfreier Medikamente empfohlen.<\/p>\n<p data-start=\"4909\" data-end=\"5073\">Dieses Produkt ist kein Ersatz f\u00fcr eine ausgewogene und abwechslungsreiche Ern\u00e4hrung. Eine abwechslungsreiche Ern\u00e4hrung sowie eine gesunde Lebensweise sind wichtig.<\/p>\n<p data-start=\"5075\" data-end=\"5228\">K\u00fchl und trocken sowie au\u00dferhalb der Reichweite von Kindern aufbewahren. Die angegebene empfohlene t\u00e4gliche Verzehrmenge darf nicht \u00fcberschritten werden.<\/p>\n<p data-start=\"5230\" data-end=\"5273\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"5230\" data-end=\"5257\">Mindestens haltbar bis:<\/strong> siehe Aufdruck.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"511\" data-end=\"657\"><em>Agewell 40+ Organschutz Pfirsich 300 g von Applied Nutrition mit Vitaminen, Mineralstoffen, NAC, Cholin, Pflanzenextrakten und Coenzym Q10.<\/em><\/p>","protected":false},"featured_media":63552,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[1648],"product_cat":[1030],"product_tag":[],"class_list":["post-63551","product","type-product","status-publish","has-post-thumbnail","product_brand-applied-nutrition","product_cat-detox-cleansing","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/63551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/comments?post=63551"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/63551\/revisions"}],"predecessor-version":[{"id":63561,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product\/63551\/revisions\/63561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/media\/63552"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/media?parent=63551"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_brand?post=63551"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_cat?post=63551"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/el\/wp-json\/wp\/v2\/product_tag?post=63551"}],"curies":[{"name":"\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}