{"id":56629,"date":"2026-07-11T16:55:22","date_gmt":"2026-07-11T16:55:22","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/melt-and-pour-475g-soap-kit\/"},"modified":"2026-07-14T16:55:36","modified_gmt":"2026-07-14T16:55:36","slug":"melt-and-pour-475g-soap-kit","status":"publish","type":"product","link":"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/","title":{"rendered":"Seife selber machen Set 475 g Melt &#038; Pour Seifenbasis"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Seife_selber_machen_Set_475_g_fur_kreative_DIY-Projekte\" >Seife selber machen Set 475 g f\u00fcr kreative DIY-Projekte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Einfache_Anwendung_fur_eigene_Seifenkreationen\" >Einfache Anwendung f\u00fcr eigene Seifenkreationen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Individuell_mit_Duften_und_naturlichen_Zutaten_gestalten\" >Individuell mit D\u00fcften und nat\u00fcrlichen Zutaten gestalten<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Ergiebige_Melt_Pour_Seifenbasis\" >Ergiebige Melt &amp; Pour Seifenbasis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Ideal_fur_DIY-Geschenke_und_kreative_Bastelideen\" >Ideal f\u00fcr DIY-Geschenke und kreative Bastelideen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Produktdetails\" >Detalles del producto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Anwendung\" >Solicitud<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Inhaltsstoffe_INCI\" >Inhaltsstoffe (INCI)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/honigbee.com\/es\/producto\/melt-and-pour-475g-soap-kit\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"398\" data-end=\"458\"><span class=\"ez-toc-section\" id=\"Seife_selber_machen_Set_475_g_fur_kreative_DIY-Projekte\"><\/span>Seife selber machen Set 475 g f\u00fcr kreative DIY-Projekte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"460\" data-end=\"696\">Con el <strong data-start=\"468\" data-end=\"501\">Seife selber machen Set 475 g<\/strong> gestalten Sie individuelle Seifen ganz nach Ihren Vorstellungen. Die hochwertige Melt &amp; Pour Seifenbasis l\u00e4sst sich einfach schmelzen und mit Farben, D\u00fcften oder nat\u00fcrlichen Zutaten kombinieren.<\/p>\n<hr data-start=\"698\" data-end=\"701\" \/>\n<h4 data-start=\"703\" data-end=\"754\"><span class=\"ez-toc-section\" id=\"Einfache_Anwendung_fur_eigene_Seifenkreationen\"><\/span>Einfache Anwendung f\u00fcr eigene Seifenkreationen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"756\" data-end=\"988\">El <strong data-start=\"760\" data-end=\"793\">Seife selber machen Set 475 g<\/strong> eignet sich sowohl f\u00fcr Einsteiger als auch f\u00fcr erfahrene DIY-Fans. Die Seifenbasis kann schonend im Wasserbad oder in der Mikrowelle geschmolzen und anschlie\u00dfend in Seifenformen gegossen werden.<\/p>\n<hr data-start=\"990\" data-end=\"993\" \/>\n<h4 data-start=\"995\" data-end=\"1056\"><span class=\"ez-toc-section\" id=\"Individuell_mit_Duften_und_naturlichen_Zutaten_gestalten\"><\/span>Individuell mit D\u00fcften und nat\u00fcrlichen Zutaten gestalten<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1058\" data-end=\"1303\">Con el <strong data-start=\"1066\" data-end=\"1099\">Seife selber machen Set 475 g<\/strong> lassen sich \u00e4therische \u00d6le, Seifenfarben, Bl\u00fcten, Kr\u00e4uter, Fruchtschalen oder andere dekorative Zus\u00e4tze ganz einfach einarbeiten. So entstehen einzigartige Seifen f\u00fcr den Eigengebrauch oder als Geschenk.<\/p>\n<hr data-start=\"1305\" data-end=\"1308\" \/>\n<h4 data-start=\"1310\" data-end=\"1348\"><span class=\"ez-toc-section\" id=\"Ergiebige_Melt_Pour_Seifenbasis\"><\/span>Ergiebige Melt &amp; Pour Seifenbasis<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1350\" data-end=\"1578\">El <strong data-start=\"1354\" data-end=\"1387\">Seife selber machen Set 475 g<\/strong> enth\u00e4lt ausreichend Seifenbasis f\u00fcr etwa vier bis f\u00fcnf Seifenst\u00fccke. Die glycerinhaltige Rezeptur sorgt f\u00fcr angenehme Verarbeitung und eine hochwertige Grundlage f\u00fcr kreative Seifenprojekte.<\/p>\n<hr data-start=\"1580\" data-end=\"1583\" \/>\n<h4 data-start=\"1585\" data-end=\"1638\"><span class=\"ez-toc-section\" id=\"Ideal_fur_DIY-Geschenke_und_kreative_Bastelideen\"><\/span>Ideal f\u00fcr DIY-Geschenke und kreative Bastelideen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1640\" data-end=\"1869\">El <strong data-start=\"1644\" data-end=\"1677\">Seife selber machen Set 475 g<\/strong> eignet sich hervorragend f\u00fcr kreative Bastelprojekte, selbstgemachte Geschenke oder gemeinsame DIY-Aktivit\u00e4ten. Der Fantasie sind bei der Gestaltung individueller Seifen kaum Grenzen gesetzt.<\/p>\n<hr data-start=\"1871\" data-end=\"1874\" \/>\n<h4 data-start=\"1876\" data-end=\"1895\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Detalles del producto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"1897\" data-end=\"2240\">\n<li data-section-id=\"5syvg5\" data-start=\"1897\" data-end=\"1927\">DIY-Set zum Seifenherstellen<\/li>\n<li data-section-id=\"1wvxi8u\" data-start=\"1928\" data-end=\"1953\">Melt &amp; Pour Seifenbasis<\/li>\n<li data-section-id=\"b57vxx\" data-start=\"1954\" data-end=\"1969\">Inhalt: 475 g<\/li>\n<li data-section-id=\"aoe6bh\" data-start=\"1970\" data-end=\"1999\">Ergibt ca. 4\u20135 Seifenst\u00fccke<\/li>\n<li data-section-id=\"6q4caw\" data-start=\"2000\" data-end=\"2051\">Zum Schmelzen im Wasserbad oder in der Mikrowelle<\/li>\n<li data-section-id=\"s5c1dk\" data-start=\"2052\" data-end=\"2110\">Mit Farben, D\u00fcften und nat\u00fcrlichen Zus\u00e4tzen kombinierbar<\/li>\n<li data-section-id=\"cvy17z\" data-start=\"2111\" data-end=\"2137\">Mit Glycerin und Kokos\u00f6l<\/li>\n<li data-section-id=\"q0ib1u\" data-start=\"2138\" data-end=\"2165\">F\u00fcr kreative DIY-Projekte<\/li>\n<li data-section-id=\"qqtmu5\" data-start=\"2166\" data-end=\"2205\">Hergestellt im Vereinigten K\u00f6nigreich<\/li>\n<li data-section-id=\"c6kzbc\" data-start=\"2206\" data-end=\"2240\">Herkunft: Vereinigtes K\u00f6nigreich<\/li>\n<\/ul>\n<hr data-start=\"2242\" data-end=\"2245\" \/>\n<h4 data-start=\"2247\" data-end=\"2261\"><span class=\"ez-toc-section\" id=\"Anwendung\"><\/span>Solicitud<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2263\" data-end=\"2478\">El <strong data-start=\"2267\" data-end=\"2300\">Seife selber machen Set 475 g<\/strong> im Wasserbad oder vorsichtig in der Mikrowelle schmelzen. Nach Wunsch Duft\u00f6le, Farben oder weitere Zutaten hinzuf\u00fcgen, in eine Seifenform gie\u00dfen und vollst\u00e4ndig abk\u00fchlen lassen.<\/p>\n<hr data-start=\"2480\" data-end=\"2483\" \/>\n<h4 data-start=\"2485\" data-end=\"2510\"><span class=\"ez-toc-section\" id=\"Inhaltsstoffe_INCI\"><\/span>Inhaltsstoffe (INCI)<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2512\" data-end=\"2793\" data-is-last-node=\"\" data-is-only-node=\"\">Aqua, Glycerin, Sorbitol, Sodium Stearate, Sodium Laurate, Propylene Glycol, Sodium Oleate, Sodium Myristate, Sodium Chloride, Cocos Nucifera (Coconut) Oil, Glyceryl Laurate, Cocamidopropyl Betaine, Citric Acid, Sodium Citrate, Tetrasodium Iminodisuccinate, Tetrasodium Etidronate.<\/p>\n<hr data-start=\"1683\" data-end=\"1686\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/es\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"147\" data-end=\"349\"><em>Das Seife selber machen Set 475 g enth\u00e4lt eine hochwertige Melt &amp; Pour Seifenbasis f\u00fcr bis zu f\u00fcnf Seifenst\u00fccke. Ideal zum Gestalten individueller Seifen mit D\u00fcften, Farben und nat\u00fcrlichen Zus\u00e4tzen.<\/em><\/p>","protected":false},"featured_media":56607,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1621],"product_tag":[],"class_list":["post-56629","product","type-product","status-publish","has-post-thumbnail","product_cat-seife-selber-machen","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product\/56629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/comments?post=56629"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product\/56629\/revisions"}],"predecessor-version":[{"id":57851,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product\/56629\/revisions\/57851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/media\/56607"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/media?parent=56629"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product_brand?post=56629"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product_cat?post=56629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/es\/wp-json\/wp\/v2\/product_tag?post=56629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}