{"id":61905,"date":"2026-08-14T09:44:38","date_gmt":"2026-08-14T09:44:38","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/cumin-seed-50ml-essential-oil\/"},"modified":"2026-09-02T14:51:09","modified_gmt":"2026-09-02T14:51:09","slug":"kreuzkuemmel-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/","title":{"rendered":"Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml aus \u00c4gypten f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Kreuzkummel_atherisches_Ol_50_ml\" >Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Aus_Kreuzkummelsamen_dampfdestilliert\" >Aus Kreuzk\u00fcmmelsamen dampfdestilliert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Intensiv_warm_wurzig_und_erdig\" >Intensiv warm, w\u00fcrzig und erdig<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Fur_orientalische_und_wurzige_Duftkompositionen\" >F\u00fcr orientalische und w\u00fcrzige Duftkompositionen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Kreuzkummel_als_traditionsreiche_Gewurzpflanze\" >Kreuzk\u00fcmmel als traditionsreiche Gew\u00fcrzpflanze<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/et\/toode\/kreuzkuemmel-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-testid=\"conversation-turn-28\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"9755d40a-4053-4605-b201-5dca143f5c42\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"393\" data-end=\"430\"><span class=\"ez-toc-section\" id=\"Kreuzkummel_atherisches_Ol_50_ml\"><\/span>Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"432\" data-end=\"712\">Das <strong data-start=\"436\" data-end=\"472\">Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Samen von <em data-start=\"496\" data-end=\"513\">Cuminum cyminum<\/em> gewonnen. Kreuzk\u00fcmmel, auch als Cumin bekannt, z\u00e4hlt zu den traditionsreichsten Gew\u00fcrzpflanzen und zeichnet sich als \u00e4therisches \u00d6l durch einen <strong data-start=\"658\" data-end=\"707\">intensiven, warmen, w\u00fcrzigen und erdigen Duft<\/strong> aus.<\/p>\n<p data-start=\"714\" data-end=\"812\">Die f\u00fcr dieses \u00e4therische \u00d6l verwendeten Kreuzk\u00fcmmelsamen stammen laut Hersteller aus <strong data-start=\"800\" data-end=\"811\">\u00c4gypten<\/strong>.<\/p>\n<hr data-start=\"814\" data-end=\"817\" \/>\n<h4 data-start=\"819\" data-end=\"861\"><span class=\"ez-toc-section\" id=\"Aus_Kreuzkummelsamen_dampfdestilliert\"><\/span>Aus Kreuzk\u00fcmmelsamen dampfdestilliert<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"863\" data-end=\"1074\">F\u00fcr die Herstellung des <strong data-start=\"887\" data-end=\"923\">Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<\/strong> werden die Samen mittels <strong data-start=\"949\" data-end=\"976\">Wasserdampfdestillation<\/strong> verarbeitet. Laut Hersteller werden sie vor der Destillation zun\u00e4chst getrocknet und zerkleinert.<\/p>\n<p data-start=\"1076\" data-end=\"1210\">Dadurch k\u00f6nnen die fl\u00fcchtigen aromatischen Pflanzenbestandteile gewonnen und als hochkonzentriertes \u00e4therisches \u00d6l aufgefangen werden.<\/p>\n<hr data-start=\"1212\" data-end=\"1215\" \/>\n<h4 data-start=\"1217\" data-end=\"1253\"><span class=\"ez-toc-section\" id=\"Intensiv_warm_wurzig_und_erdig\"><\/span>Intensiv warm, w\u00fcrzig und erdig<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1255\" data-end=\"1488\">Kreuzk\u00fcmmel\u00f6l besitzt einen ausgesprochen charakteristischen <strong data-start=\"1316\" data-end=\"1376\">warmen, kr\u00e4ftig-w\u00fcrzigen, erdigen und leicht herben Duft<\/strong>. Das Aroma erinnert deutlich an das bekannte Gew\u00fcrz, wirkt in konzentrierter Form jedoch wesentlich intensiver.<\/p>\n<p data-start=\"1490\" data-end=\"1722\">Aufgrund seiner starken Duftwirkung sollte Kreuzk\u00fcmmel\u00f6l in Aromamischungen sparsam eingesetzt werden. Es harmoniert beispielsweise mit <strong data-start=\"1626\" data-end=\"1721\">Orange, Bergamotte, Zitrone, Ingwer, Schwarzem Pfeffer, Weihrauch, Patchouli und Zedernholz<\/strong>.<\/p>\n<hr data-start=\"1724\" data-end=\"1727\" \/>\n<h4 data-start=\"1729\" data-end=\"1781\"><span class=\"ez-toc-section\" id=\"Fur_orientalische_und_wurzige_Duftkompositionen\"><\/span>F\u00fcr orientalische und w\u00fcrzige Duftkompositionen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1783\" data-end=\"1943\">Das <strong data-start=\"1787\" data-end=\"1823\">Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen sowie als charakteristische Komponente individueller Aromamischungen.<\/p>\n<p data-start=\"1945\" data-end=\"2114\">Sein warmer Gew\u00fcrzcharakter passt besonders gut zu <strong data-start=\"1996\" data-end=\"2054\">orientalischen, erdigen und w\u00fcrzigen Duftkompositionen<\/strong> und kann Zitrus- und Holznoten zus\u00e4tzliche Tiefe verleihen.<\/p>\n<hr data-start=\"2116\" data-end=\"2119\" \/>\n<h4 data-start=\"2121\" data-end=\"2172\"><span class=\"ez-toc-section\" id=\"Kreuzkummel_als_traditionsreiche_Gewurzpflanze\"><\/span>Kreuzk\u00fcmmel als traditionsreiche Gew\u00fcrzpflanze<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2174\" data-end=\"2336\"><em data-start=\"2174\" data-end=\"2191\">Cuminum cyminum<\/em> wird seit Jahrhunderten als aromatische Gew\u00fcrzpflanze gesch\u00e4tzt und ist heute ein wichtiger Bestandteil zahlreicher K\u00fcchen und Gew\u00fcrzmischungen.<\/p>\n<p data-start=\"2338\" data-end=\"2557\">Auch \u00c4gypten besitzt eine lange Verbindung zu aromatischen Gew\u00fcrz- und Duftpflanzen. Die traditionelle Verwendung von Kreuzk\u00fcmmel ist jedoch von den Eigenschaften des hochkonzentrierten \u00e4therischen \u00d6ls zu unterscheiden.<\/p>\n<p data-start=\"2559\" data-end=\"2771\">Die vom Lieferanten genannten antibakteriellen Wirkungen beziehungsweise Anwendungen gegen bestimmte Krankheitserreger und Infektionen werden daher nicht als medizinische Eigenschaften dieses Produkts \u00fcbernommen.<\/p>\n<hr data-start=\"2773\" data-end=\"2776\" \/>\n<h4 data-start=\"2778\" data-end=\"2797\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2799\" data-end=\"3311\">\n<li data-section-id=\"1o6aiyy\" data-start=\"2799\" data-end=\"2846\"><strong data-start=\"2801\" data-end=\"2813\">Produkt:<\/strong> Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"gwsy2j\" data-start=\"2847\" data-end=\"2879\"><strong data-start=\"2849\" data-end=\"2873\">Weitere Bezeichnung:<\/strong> Cumin<\/li>\n<li data-section-id=\"18i7v6d\" data-start=\"2880\" data-end=\"2906\"><strong data-start=\"2882\" data-end=\"2894\">Pflanze:<\/strong> Kreuzk\u00fcmmel<\/li>\n<li data-section-id=\"q7jiwk\" data-start=\"2907\" data-end=\"2954\"><strong data-start=\"2909\" data-end=\"2936\">Botanische Bezeichnung:<\/strong> <em data-start=\"2937\" data-end=\"2954\">Cuminum cyminum<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2955\" data-end=\"2974\"><strong data-start=\"2957\" data-end=\"2968\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"t8rx0p\" data-start=\"2975\" data-end=\"3012\"><strong data-start=\"2977\" data-end=\"3006\">Verwendeter Pflanzenteil:<\/strong> Samen<\/li>\n<li data-section-id=\"1oyh7iy\" data-start=\"3013\" data-end=\"3036\"><strong data-start=\"3015\" data-end=\"3028\">Herkunft:<\/strong> \u00c4gypten<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"3037\" data-end=\"3077\"><strong data-start=\"3039\" data-end=\"3053\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1l2lkqn\" data-start=\"3078\" data-end=\"3140\"><strong data-start=\"3080\" data-end=\"3095\">Duftprofil:<\/strong> Warm \/ intensiv w\u00fcrzig \/ erdig \/ leicht herb<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"3141\" data-end=\"3192\"><strong data-start=\"3143\" data-end=\"3158\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3193\" data-end=\"3250\"><strong data-start=\"3195\" data-end=\"3228\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3251\" data-end=\"3282\"><strong data-start=\"3253\" data-end=\"3272\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswl3q\" data-start=\"3283\" data-end=\"3311\"><strong data-start=\"3285\" data-end=\"3297\">Barcode:<\/strong> 5055796529902<\/li>\n<\/ul>\n<hr data-start=\"3313\" data-end=\"3316\" \/>\n<h4 data-start=\"3318\" data-end=\"3342\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3344\" data-end=\"3539\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"3382\" data-end=\"3446\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kreuzk\u00fcmmel\u00f6l sollte aufgrund seines intensiven Charakters besonders sparsam dosiert werden.<\/p>\n<p data-start=\"3541\" data-end=\"3761\">Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren. F\u00fcr Hautanwendungen ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vorab einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"3763\" data-end=\"3911\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Kreuzk\u00fcmmel \u00e4therisches \u00d6l 50 ml aus \u00c4gypten, aus den Samen dampfdestilliert. Intensiv warm-w\u00fcrziger, erdiger Duft f\u00fcr Aromatherapie und Duftmischungen.<\/em><\/p>","protected":false},"featured_media":61898,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61905","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product\/61905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/comments?post=61905"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product\/61905\/revisions"}],"predecessor-version":[{"id":63703,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product\/61905\/revisions\/63703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/media\/61898"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/media?parent=61905"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product_brand?post=61905"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product_cat?post=61905"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/et\/wp-json\/wp\/v2\/product_tag?post=61905"}],"curies":[{"name":"t\u00f6\u00f6leht","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}