{"id":62172,"date":"2026-08-14T09:48:44","date_gmt":"2026-08-14T09:48:44","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/juniperberry-50ml-essential-oil\/"},"modified":"2026-09-01T16:37:29","modified_gmt":"2026-09-01T16:37:29","slug":"wacholderbeere-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/","title":{"rendered":"Wacholderbeere \u00e4therisches \u00d6l 50 ml aus Mazedonien f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Basculer la table des mati\u00e8res\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Basculer<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Wacholderbeere_atherisches_Ol_50_ml\" >Wacholderbeere \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Aus_Wacholderbeeren_dampfdestilliert\" >Aus Wacholderbeeren dampfdestilliert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Frisch_holzig_und_wurzig\" >Frisch, holzig und w\u00fcrzig<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Fur_eine_klare_und_erdende_Duftatmosphare\" >F\u00fcr eine klare und erdende Duftatmosph\u00e4re<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Wacholder_als_traditionelle_Duft-_und_Raucherpflanze\" >Wacholder als traditionelle Duft- und R\u00e4ucherpflanze<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Produktdetails\" >D\u00e9tails du produit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/fr\/produit\/wacholderbeere-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Consignes de s\u00e9curit\u00e9<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"404\" data-end=\"444\"><span class=\"ez-toc-section\" id=\"Wacholderbeere_atherisches_Ol_50_ml\"><\/span>Wacholderbeere \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"446\" data-end=\"691\">Le <strong data-start=\"450\" data-end=\"489\">Wacholderbeere \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Beeren des Gemeinen Wacholders (<em data-start=\"535\" data-end=\"555\">Juniperus communis<\/em>) gewonnen. Wacholder ist ein immergr\u00fcnes Nadelgeh\u00f6lz und f\u00fcr seinen unverwechselbaren <strong data-start=\"642\" data-end=\"682\">frischen, holzigen und w\u00fcrzigen Duft<\/strong> bekannt.<\/p>\n<p data-start=\"693\" data-end=\"793\">Die f\u00fcr dieses \u00e4therische \u00d6l verwendeten Wacholderbeeren stammen laut Hersteller aus <strong data-start=\"778\" data-end=\"792\">Mazedonien<\/strong>.<\/p>\n<hr data-start=\"795\" data-end=\"798\" \/>\n<h4 data-start=\"800\" data-end=\"841\"><span class=\"ez-toc-section\" id=\"Aus_Wacholderbeeren_dampfdestilliert\"><\/span>Aus Wacholderbeeren dampfdestilliert<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"843\" data-end=\"973\">F\u00fcr die Herstellung des <strong data-start=\"867\" data-end=\"906\">Wacholderbeere \u00e4therisches \u00d6l 50 ml<\/strong> werden die Beeren mittels <strong data-start=\"933\" data-end=\"960\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"975\" data-end=\"1253\">Dabei werden die fl\u00fcchtigen aromatischen Pflanzenbestandteile gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen. Im Vergleich zu \u00d6len aus anderen Pflanzenteilen des Wacholders steht bei Wacholderbeeren\u00f6l der charakteristische aromatische Duft der Beeren im Mittelpunkt.<\/p>\n<hr data-start=\"1255\" data-end=\"1258\" \/>\n<h4 data-start=\"1260\" data-end=\"1290\"><span class=\"ez-toc-section\" id=\"Frisch_holzig_und_wurzig\"><\/span>Frisch, holzig und w\u00fcrzig<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1292\" data-end=\"1527\">Wacholderbeeren\u00f6l besitzt ein <strong data-start=\"1322\" data-end=\"1371\">klares, frisches, holziges und w\u00fcrziges Aroma<\/strong> mit gr\u00fcnen und leicht harzigen Nuancen. Sein Duft erinnert an Nadelw\u00e4lder und eignet sich besonders f\u00fcr nat\u00fcrliche, krautige und waldige Duftkompositionen.<\/p>\n<p data-start=\"1529\" data-end=\"1663\">Sehr gut harmoniert Wacholderbeere beispielsweise mit <strong data-start=\"1583\" data-end=\"1662\">Zitrone, Bergamotte, Lavendel, Rosmarin, Zypresse, Weihrauch und Zedernholz<\/strong>.<\/p>\n<hr data-start=\"1665\" data-end=\"1668\" \/>\n<h4 data-start=\"1670\" data-end=\"1716\"><span class=\"ez-toc-section\" id=\"Fur_eine_klare_und_erdende_Duftatmosphare\"><\/span>F\u00fcr eine klare und erdende Duftatmosph\u00e4re<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1718\" data-end=\"1865\">In der Aromatherapie wird der Duft der Wacholderbeere traditionell mit einer <strong data-start=\"1795\" data-end=\"1854\">ruhigen, erdenden und zugleich frisch-klaren Atmosph\u00e4re<\/strong> verbunden.<\/p>\n<p data-start=\"1867\" data-end=\"2127\">Le <strong data-start=\"1871\" data-end=\"1910\">Wacholderbeere \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen sowie f\u00fcr individuelle Raumduft- und Aromamischungen. Durch seinen frischen Waldcharakter l\u00e4sst es sich besonders gut mit Zitrus-, Kr\u00e4uter- und Holznoten kombinieren.<\/p>\n<hr data-start=\"2129\" data-end=\"2132\" \/>\n<h4 data-start=\"2134\" data-end=\"2191\"><span class=\"ez-toc-section\" id=\"Wacholder_als_traditionelle_Duft-_und_Raucherpflanze\"><\/span>Wacholder als traditionelle Duft- und R\u00e4ucherpflanze<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2193\" data-end=\"2418\">Wacholder besitzt in verschiedenen europ\u00e4ischen Kulturen eine lange Tradition als <strong data-start=\"2275\" data-end=\"2312\">Duft-, Gew\u00fcrz- und R\u00e4ucherpflanze<\/strong>. Sein kr\u00e4ftiger aromatischer Duft wurde traditionell auch zur Beduftung und f\u00fcr R\u00e4ucherrituale verwendet.<\/p>\n<p data-start=\"2420\" data-end=\"2603\">Historische oder traditionelle Vorstellungen einer \u201ereinigenden\u201c Wirkung sind dabei von wissenschaftlich nachgewiesenen antimikrobiellen oder medizinischen Wirkungen zu unterscheiden.<\/p>\n<hr data-start=\"2605\" data-end=\"2608\" \/>\n<h4 data-start=\"2610\" data-end=\"2629\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>D\u00e9tails du produit<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2631\" data-end=\"3123\">\n<li data-section-id=\"1ppvvi7\" data-start=\"2631\" data-end=\"2681\"><strong data-start=\"2633\" data-end=\"2645\">Produit:<\/strong> Wacholderbeere \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"g0oiq7\" data-start=\"2682\" data-end=\"2715\"><strong data-start=\"2684\" data-end=\"2696\">Usine:<\/strong> Gemeiner Wacholder<\/li>\n<li data-section-id=\"1mt3964\" data-start=\"2716\" data-end=\"2766\"><strong data-start=\"2718\" data-end=\"2745\">Botanische Bezeichnung:<\/strong> <em data-start=\"2746\" data-end=\"2766\">Juniperus communis<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2767\" data-end=\"2786\"><strong data-start=\"2769\" data-end=\"2780\">Contenu:<\/strong> 50 ml<\/li>\n<li data-section-id=\"1kdpdk6\" data-start=\"2787\" data-end=\"2825\"><strong data-start=\"2789\" data-end=\"2818\">Verwendeter Pflanzenteil:<\/strong> Beeren<\/li>\n<li data-section-id=\"1g2uymz\" data-start=\"2826\" data-end=\"2852\"><strong data-start=\"2828\" data-end=\"2841\">Origine:<\/strong> Mazedonien<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2853\" data-end=\"2893\"><strong data-start=\"2855\" data-end=\"2869\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"12lmjjr\" data-start=\"2894\" data-end=\"2952\"><strong data-start=\"2896\" data-end=\"2911\">Profil du parfum :<\/strong> Frisch \/ holzig \/ w\u00fcrzig \/ leicht harzig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2953\" data-end=\"3004\"><strong data-start=\"2955\" data-end=\"2970\">Utiliser:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3005\" data-end=\"3062\"><strong data-start=\"3007\" data-end=\"3040\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3063\" data-end=\"3094\"><strong data-start=\"3065\" data-end=\"3084\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswoje\" data-start=\"3095\" data-end=\"3123\"><strong data-start=\"3097\" data-end=\"3109\">Barcode:<\/strong> 5055796529513<\/li>\n<\/ul>\n<hr data-start=\"3125\" data-end=\"3128\" \/>\n<h4 data-start=\"3130\" data-end=\"3154\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Consignes de s\u00e9curit\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3156\" data-end=\"3358\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"3194\" data-end=\"3258\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3360\" data-end=\"3513\">F\u00fcr Haut- oder Massageanwendungen ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vor der ersten Anwendung einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"3515\" data-end=\"3700\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden \u2013 insbesondere bei Nierenproblemen \u2013 oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"241\" data-end=\"397\"><em>Wacholderbeere \u00e4therisches \u00d6l 50 ml aus Mazedonien, aus Wacholderbeeren dampfdestilliert. Frisch-holziger, w\u00fcrziger Duft f\u00fcr Aromatherapie und Raumduft.<\/em><\/p>","protected":false},"featured_media":62167,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62172","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product\/62172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/comments?post=62172"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product\/62172\/revisions"}],"predecessor-version":[{"id":63688,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product\/62172\/revisions\/63688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/media\/62167"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/media?parent=62172"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product_brand?post=62172"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product_cat?post=62172"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/fr\/wp-json\/wp\/v2\/product_tag?post=62172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}