{"id":62160,"date":"2026-08-14T09:48:34","date_gmt":"2026-08-14T09:48:34","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/neroli-dilute-50ml-essential-oil\/"},"modified":"2026-09-01T12:34:20","modified_gmt":"2026-09-01T12:34:20","slug":"nerolioel-5-prozent-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/","title":{"rendered":"Neroli\u00f6l 5% 50 ml verd\u00fcnnt in Traubenkern\u00f6l \u2013 Orangenbl\u00fcten\u00f6l aus Tunesien"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Neroliol_5_50_ml\" >Neroli\u00f6l 5% 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#5_Neroliol_in_Traubenkernol\" >5% Neroli\u00f6l in Traubenkern\u00f6l<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Aus_den_Bluten_der_Bitterorange_gewonnen\" >Aus den Bl\u00fcten der Bitterorange gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Blumig_suslich_und_zitrisch\" >Blumig, s\u00fc\u00dflich und zitrisch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Ein_traditionsreicher_Duft_der_Parfumerie\" >Ein traditionsreicher Duft der Parf\u00fcmerie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/nerolioel-5-prozent-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-4\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-4\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-4\" data-testid=\"conversation-turn-20\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"0c9ea17d-b2ab-431d-b8b9-4f5ab9730ba4\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"352\" data-end=\"374\"><span class=\"ez-toc-section\" id=\"Neroliol_5_50_ml\"><\/span>Neroli\u00f6l 5% 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"376\" data-end=\"533\">Das <strong data-start=\"380\" data-end=\"401\">Neroli\u00f6l 5% 50 ml<\/strong> enth\u00e4lt \u00e4therisches Neroli\u00f6l aus den Bl\u00fcten der Bitterorange (<em data-start=\"464\" data-end=\"482\">Citrus aurantium<\/em>) in einer <strong data-start=\"493\" data-end=\"532\">5%igen Verd\u00fcnnung mit Traubenkern\u00f6l<\/strong>.<\/p>\n<p data-start=\"535\" data-end=\"769\">Neroli z\u00e4hlt aufgrund seines eleganten <strong data-start=\"574\" data-end=\"619\">blumigen, s\u00fc\u00dflichen und zitrischen Duftes<\/strong> zu den besonders gesch\u00e4tzten \u00e4therischen Bl\u00fcten\u00f6len. Die f\u00fcr dieses Produkt verwendeten Bitterorangenbl\u00fcten stammen laut Hersteller aus <strong data-start=\"756\" data-end=\"768\">Tunesien<\/strong>.<\/p>\n<hr data-start=\"771\" data-end=\"774\" \/>\n<h4 data-start=\"776\" data-end=\"809\"><span class=\"ez-toc-section\" id=\"5_Neroliol_in_Traubenkernol\"><\/span>5% Neroli\u00f6l in Traubenkern\u00f6l<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"811\" data-end=\"990\">Bei diesem Produkt handelt es sich ausdr\u00fccklich <strong data-start=\"859\" data-end=\"892\">nicht um 100% reines Neroli\u00f6l<\/strong>. Das \u00e4therische Neroli\u00f6l ist bereits auf eine Konzentration von <strong data-start=\"957\" data-end=\"980\">5% in Traubenkern\u00f6l<\/strong> verd\u00fcnnt.<\/p>\n<p data-start=\"992\" data-end=\"1220\">Reines Neroli\u00f6l ist aufgrund der aufwendigen Gewinnung aus den empfindlichen Bl\u00fcten der Bitterorange besonders kostbar. Die 5%ige Mischung bietet das charakteristische Neroli-Aroma in Kombination mit einem pflanzlichen Tr\u00e4ger\u00f6l.<\/p>\n<hr data-start=\"1222\" data-end=\"1225\" \/>\n<h4 data-start=\"1227\" data-end=\"1272\"><span class=\"ez-toc-section\" id=\"Aus_den_Bluten_der_Bitterorange_gewonnen\"><\/span>Aus den Bl\u00fcten der Bitterorange gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1274\" data-end=\"1408\">Neroli wird aus den empfindlichen wei\u00dfen Bl\u00fcten des Bitterorangenbaums gewonnen, der botanisch als <em data-start=\"1373\" data-end=\"1391\">Citrus aurantium<\/em> bezeichnet wird.<\/p>\n<p data-start=\"1410\" data-end=\"1603\">Die Bl\u00fcten werden sorgf\u00e4ltig geerntet und anschlie\u00dfend destilliert, um ihr charakteristisches \u00e4therisches \u00d6l zu gewinnen. Laut Produktspezifikation erfolgt die Gewinnung durch <strong data-start=\"1586\" data-end=\"1602\">Destillation<\/strong>.<\/p>\n<hr data-start=\"1605\" data-end=\"1608\" \/>\n<h4 data-start=\"1610\" data-end=\"1643\"><span class=\"ez-toc-section\" id=\"Blumig_suslich_und_zitrisch\"><\/span>Blumig, s\u00fc\u00dflich und zitrisch<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1645\" data-end=\"1766\">Neroli besitzt einen unverwechselbaren Duft mit <strong data-start=\"1693\" data-end=\"1765\">intensiv blumigen, frischen, leicht s\u00fc\u00dflichen und zitrischen Nuancen<\/strong>.<\/p>\n<p data-start=\"1768\" data-end=\"2013\">In der Aromatherapie wird dieser elegante Duft traditionell mit einer <strong data-start=\"1838\" data-end=\"1892\">ruhigen, harmonischen und entspannenden Atmosph\u00e4re<\/strong> verbunden. Dadurch eignet sich Neroli besonders f\u00fcr bewusste Ruhephasen, Meditation und pers\u00f6nliche Entspannungsrituale.<\/p>\n<hr data-start=\"2015\" data-end=\"2018\" \/>\n<h4 data-start=\"2020\" data-end=\"2066\"><span class=\"ez-toc-section\" id=\"Ein_traditionsreicher_Duft_der_Parfumerie\"><\/span>Ein traditionsreicher Duft der Parf\u00fcmerie<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2068\" data-end=\"2332\">Neroli besitzt eine lange Geschichte als kostbarer Duftstoff. Besonders bekannt wurde der Duft im 17. Jahrhundert durch <strong data-start=\"2188\" data-end=\"2232\">Anna Maria Orsini, Prinzessin von Nerola<\/strong>, die Bitterorangenbl\u00fcten-Essenz zur Parf\u00fcmierung ihrer Handschuhe und ihres Badewassers verwendete.<\/p>\n<p data-start=\"2334\" data-end=\"2523\">Der Name <strong data-start=\"2343\" data-end=\"2353\">Neroli<\/strong> wird traditionell mit Nerola und dieser historischen Verwendung in Verbindung gebracht. Bis heute geh\u00f6rt Neroli zu den klassischen Duftnoten der hochwertigen Parf\u00fcmerie.<\/p>\n<hr data-start=\"2525\" data-end=\"2528\" \/>\n<h4 data-start=\"2530\" data-end=\"2549\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2551\" data-end=\"3127\">\n<li data-section-id=\"1727f2k\" data-start=\"2551\" data-end=\"2583\"><strong data-start=\"2553\" data-end=\"2565\">Produkt:<\/strong> Neroli\u00f6l 5% 50 ml<\/li>\n<li data-section-id=\"x1puyc\" data-start=\"2584\" data-end=\"2611\"><strong data-start=\"2586\" data-end=\"2598\">Pflanze:<\/strong> Bitterorange<\/li>\n<li data-section-id=\"1bkte2m\" data-start=\"2612\" data-end=\"2660\"><strong data-start=\"2614\" data-end=\"2641\">Botanische Bezeichnung:<\/strong> <em data-start=\"2642\" data-end=\"2660\">Citrus aurantium<\/em><\/li>\n<li data-section-id=\"ucj4eq\" data-start=\"2661\" data-end=\"2712\"><strong data-start=\"2663\" data-end=\"2687\">Weitere Bezeichnung:<\/strong> Neroli \/ Orangenbl\u00fcten\u00f6l<\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2713\" data-end=\"2732\"><strong data-start=\"2715\" data-end=\"2726\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"975dhf\" data-start=\"2733\" data-end=\"2777\"><strong data-start=\"2735\" data-end=\"2753\">Konzentration:<\/strong> 5% \u00e4therisches Neroli\u00f6l<\/li>\n<li data-section-id=\"1fh8zm1\" data-start=\"2778\" data-end=\"2807\"><strong data-start=\"2780\" data-end=\"2793\">Tr\u00e4ger\u00f6l:<\/strong> Traubenkern\u00f6l<\/li>\n<li data-section-id=\"1ka01w0\" data-start=\"2808\" data-end=\"2846\"><strong data-start=\"2810\" data-end=\"2839\">Verwendeter Pflanzenteil:<\/strong> Bl\u00fcten<\/li>\n<li data-section-id=\"1d94tg4\" data-start=\"2847\" data-end=\"2871\"><strong data-start=\"2849\" data-end=\"2862\">Herkunft:<\/strong> Tunesien<\/li>\n<li data-section-id=\"1oxesio\" data-start=\"2872\" data-end=\"2901\"><strong data-start=\"2874\" data-end=\"2888\">Gewinnung:<\/strong> Destillation<\/li>\n<li data-section-id=\"5rqxyv\" data-start=\"2902\" data-end=\"2956\"><strong data-start=\"2904\" data-end=\"2919\">Duftprofil:<\/strong> Blumig \/ s\u00fc\u00dflich \/ frisch \/ zitrisch<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2957\" data-end=\"3008\"><strong data-start=\"2959\" data-end=\"2974\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3009\" data-end=\"3066\"><strong data-start=\"3011\" data-end=\"3044\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3067\" data-end=\"3098\"><strong data-start=\"3069\" data-end=\"3088\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswoly\" data-start=\"3099\" data-end=\"3127\"><strong data-start=\"3101\" data-end=\"3113\">Barcode:<\/strong> 5055796529568<\/li>\n<\/ul>\n<hr data-start=\"3129\" data-end=\"3132\" \/>\n<h4 data-start=\"3134\" data-end=\"3158\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3160\" data-end=\"3328\">Nur zur \u00e4u\u00dferlichen und aromatischen Anwendung. <strong data-start=\"3208\" data-end=\"3228\">Nicht einnehmen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3330\" data-end=\"3492\">Das Neroli\u00f6l ist bereits auf <strong data-start=\"3359\" data-end=\"3391\">5% in Traubenkern\u00f6l verd\u00fcnnt<\/strong>. Bei empfindlicher Haut empfiehlt sich dennoch ein Vertr\u00e4glichkeitstest an einer kleinen Hautstelle.<\/p>\n<p data-start=\"3494\" data-end=\"3642\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"197\" data-end=\"345\"><em>Neroli\u00f6l 5% 50 ml aus den Bl\u00fcten der Bitterorange, verd\u00fcnnt in Traubenkern\u00f6l. Intensiv blumig-zitrischer Duft f\u00fcr Aromatherapie und Entspannung.<\/em><\/p>","protected":false},"featured_media":62152,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62160","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/comments?post=62160"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62160\/revisions"}],"predecessor-version":[{"id":63639,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62160\/revisions\/63639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/media\/62152"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/media?parent=62160"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_brand?post=62160"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_cat?post=62160"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_tag?post=62160"}],"curies":[{"name":"radni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}