{"id":62281,"date":"2026-08-14T09:50:07","date_gmt":"2026-08-14T09:50:07","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/chamomile-dilute-50ml-essential-oil\/"},"modified":"2026-08-31T16:14:22","modified_gmt":"2026-08-31T16:14:22","slug":"roemische-kamille-oel-5-prozent-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/","title":{"rendered":"R\u00f6mische Kamille \u00d6l 5% 50 ml verd\u00fcnnt in Traubenkern\u00f6l aus England"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Romische_Kamille_Ol_5_50_ml\" >R\u00f6mische Kamille \u00d6l 5% 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#5_Kamillenol_in_Traubenkernol\" >5% Kamillen\u00f6l in Traubenkern\u00f6l<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Aus_den_Bluten_der_Romischen_Kamille\" >Aus den Bl\u00fcten der R\u00f6mischen Kamille<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Sanfter_Duft_fur_entspannende_Momente\" >Sanfter Duft f\u00fcr entspannende Momente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Kamille_mit_langer_Tradition\" >Kamille mit langer Tradition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/hr\/proizvod\/roemische-kamille-oel-5-prozent-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-testid=\"conversation-turn-28\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"f2c3874d-6261-4af3-a80b-54c76df6ad0c\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"368\" data-end=\"401\"><span class=\"ez-toc-section\" id=\"Romische_Kamille_Ol_5_50_ml\"><\/span>R\u00f6mische Kamille \u00d6l 5% 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"403\" data-end=\"555\">Das <strong data-start=\"407\" data-end=\"439\">R\u00f6mische Kamille \u00d6l 5% 50 ml<\/strong> enth\u00e4lt \u00e4therisches \u00d6l der R\u00f6mischen Kamille (<em data-start=\"486\" data-end=\"504\">Anthemis nobilis<\/em>) in einer <strong data-start=\"515\" data-end=\"554\">5%igen Verd\u00fcnnung mit Traubenkern\u00f6l<\/strong>.<\/p>\n<p data-start=\"557\" data-end=\"752\">Die R\u00f6mische Kamille ist f\u00fcr ihr angenehm <strong data-start=\"599\" data-end=\"652\">blumiges, krautiges und leicht apfelartiges Aroma<\/strong> bekannt. Die f\u00fcr dieses Produkt verwendeten Kamillenbl\u00fcten stammen laut Hersteller aus <strong data-start=\"740\" data-end=\"751\">England<\/strong>.<\/p>\n<hr data-start=\"754\" data-end=\"757\" \/>\n<h4 data-start=\"759\" data-end=\"794\"><span class=\"ez-toc-section\" id=\"5_Kamillenol_in_Traubenkernol\"><\/span>5% Kamillen\u00f6l in Traubenkern\u00f6l<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"796\" data-end=\"994\">Bei diesem Produkt handelt es sich ausdr\u00fccklich <strong data-start=\"844\" data-end=\"891\">nicht um 100% reines \u00e4therisches Kamillen\u00f6l<\/strong>. Das \u00e4therische \u00d6l der R\u00f6mischen Kamille liegt in einer Konzentration von <strong data-start=\"966\" data-end=\"989\">5% in Traubenkern\u00f6l<\/strong> vor.<\/p>\n<p data-start=\"996\" data-end=\"1187\">Die Verd\u00fcnnung verbindet das charakteristische Aroma der Kamillenbl\u00fcten mit einem pflanzlichen Tr\u00e4ger\u00f6l und macht das Produkt besonders interessant f\u00fcr aromatische und \u00e4u\u00dferliche Anwendungen.<\/p>\n<hr data-start=\"1189\" data-end=\"1192\" \/>\n<h4 data-start=\"1194\" data-end=\"1235\"><span class=\"ez-toc-section\" id=\"Aus_den_Bluten_der_Romischen_Kamille\"><\/span>Aus den Bl\u00fcten der R\u00f6mischen Kamille<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1237\" data-end=\"1333\">Das enthaltene \u00e4therische Kamillen\u00f6l wird durch <strong data-start=\"1285\" data-end=\"1323\">Wasserdampfdestillation der Bl\u00fcten<\/strong> gewonnen.<\/p>\n<p data-start=\"1335\" data-end=\"1563\">Frisch destilliertes \u00e4therisches \u00d6l der R\u00f6mischen Kamille kann eine charakteristische hellblaue F\u00e4rbung besitzen. Besonders markant ist jedoch der sanfte Duft mit <strong data-start=\"1498\" data-end=\"1562\">blumigen, krautigen und an frische \u00c4pfel erinnernden Nuancen<\/strong>.<\/p>\n<hr data-start=\"1565\" data-end=\"1568\" \/>\n<h4 data-start=\"1570\" data-end=\"1612\"><span class=\"ez-toc-section\" id=\"Sanfter_Duft_fur_entspannende_Momente\"><\/span>Sanfter Duft f\u00fcr entspannende Momente<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1614\" data-end=\"1733\">In der Aromatherapie wird R\u00f6mische Kamille traditionell f\u00fcr ihren <strong data-start=\"1680\" data-end=\"1722\">sanften und beruhigenden Duftcharakter<\/strong> gesch\u00e4tzt.<\/p>\n<p data-start=\"1735\" data-end=\"1851\">Das harmonische Aroma eignet sich besonders f\u00fcr ruhige Abendstunden, Meditation und pers\u00f6nliche Entspannungsrituale.<\/p>\n<hr data-start=\"1853\" data-end=\"1856\" \/>\n<h4 data-start=\"1858\" data-end=\"1891\"><span class=\"ez-toc-section\" id=\"Kamille_mit_langer_Tradition\"><\/span>Kamille mit langer Tradition<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1893\" data-end=\"2087\">Kamille besitzt eine jahrtausendealte Geschichte als gesch\u00e4tzte aromatische Pflanze. Bereits bei den <strong data-start=\"1994\" data-end=\"2033\">alten \u00c4gyptern, Griechen und R\u00f6mern<\/strong> spielte sie eine Rolle in traditionellen Anwendungen.<\/p>\n<p data-start=\"2089\" data-end=\"2248\">Auch heute geh\u00f6rt Kamille aufgrund ihres unverwechselbaren Duftprofils zu den bekannten Pflanzen in Aromatherapie, K\u00f6rperpflege und nat\u00fcrlichen Duftmischungen.<\/p>\n<hr data-start=\"2250\" data-end=\"2253\" \/>\n<h4 data-start=\"2255\" data-end=\"2274\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2276\" data-end=\"2863\">\n<li data-section-id=\"spygix\" data-start=\"2276\" data-end=\"2319\"><strong data-start=\"2278\" data-end=\"2290\">Produkt:<\/strong> R\u00f6mische Kamille \u00d6l 5% 50 ml<\/li>\n<li data-section-id=\"nsefgu\" data-start=\"2320\" data-end=\"2351\"><strong data-start=\"2322\" data-end=\"2334\">Pflanze:<\/strong> R\u00f6mische Kamille<\/li>\n<li data-section-id=\"1vk02xx\" data-start=\"2352\" data-end=\"2400\"><strong data-start=\"2354\" data-end=\"2381\">Botanische Bezeichnung:<\/strong> <em data-start=\"2382\" data-end=\"2400\">Anthemis nobilis<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2401\" data-end=\"2420\"><strong data-start=\"2403\" data-end=\"2414\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"h89m5x\" data-start=\"2421\" data-end=\"2467\"><strong data-start=\"2423\" data-end=\"2441\">Konzentration:<\/strong> 5% \u00e4therisches Kamillen\u00f6l<\/li>\n<li data-section-id=\"1fh8zm1\" data-start=\"2468\" data-end=\"2497\"><strong data-start=\"2470\" data-end=\"2483\">Tr\u00e4ger\u00f6l:<\/strong> Traubenkern\u00f6l<\/li>\n<li data-section-id=\"1ka01w0\" data-start=\"2498\" data-end=\"2536\"><strong data-start=\"2500\" data-end=\"2529\">Verwendeter Pflanzenteil:<\/strong> Bl\u00fcten<\/li>\n<li data-section-id=\"14au62s\" data-start=\"2537\" data-end=\"2560\"><strong data-start=\"2539\" data-end=\"2552\">Herkunft:<\/strong> England<\/li>\n<li data-section-id=\"1rfnp81\" data-start=\"2561\" data-end=\"2621\"><strong data-start=\"2563\" data-end=\"2597\">Gewinnung des \u00e4therischen \u00d6ls:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1l42uoi\" data-start=\"2622\" data-end=\"2685\"><strong data-start=\"2624\" data-end=\"2639\">Duftprofil:<\/strong> Blumig \/ krautig \/ frisch \/ leicht apfelartig<\/li>\n<li data-section-id=\"1rr0se4\" data-start=\"2686\" data-end=\"2744\"><strong data-start=\"2688\" data-end=\"2703\">Verwendung:<\/strong> Aromatherapie und \u00e4u\u00dferliche Anwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2745\" data-end=\"2802\"><strong data-start=\"2747\" data-end=\"2780\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2803\" data-end=\"2834\"><strong data-start=\"2805\" data-end=\"2824\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswnq2\" data-start=\"2835\" data-end=\"2863\"><strong data-start=\"2837\" data-end=\"2849\">Barcode:<\/strong> 5055796529421<\/li>\n<\/ul>\n<hr data-start=\"2865\" data-end=\"2868\" \/>\n<h4 data-start=\"2870\" data-end=\"2894\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2896\" data-end=\"3064\">Nur zur \u00e4u\u00dferlichen und aromatischen Anwendung. <strong data-start=\"2944\" data-end=\"2964\">Nicht einnehmen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3066\" data-end=\"3241\">Das \u00e4therische Kamillen\u00f6l ist bereits auf <strong data-start=\"3108\" data-end=\"3140\">5% in Traubenkern\u00f6l verd\u00fcnnt<\/strong>. Bei empfindlicher Haut empfiehlt sich dennoch ein Vertr\u00e4glichkeitstest an einer kleinen Hautstelle.<\/p>\n<p data-start=\"3243\" data-end=\"3494\" data-is-last-node=\"\" data-is-only-node=\"\">Bei einer Anwendung bei <strong data-start=\"3267\" data-end=\"3289\">Babys oder Kindern<\/strong> vorher fachkundigen Rat einholen. Ebenso sollte bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundiger Rat eingeholt werden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>R\u00f6mische Kamille \u00d6l 5% 50 ml aus England, verd\u00fcnnt in Traubenkern\u00f6l. Blumig-frischer, leicht apfelartiger Duft f\u00fcr Aromatherapie und Entspannung.<\/em><\/p>","protected":false},"featured_media":62255,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62281","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/comments?post=62281"}],"version-history":[{"count":4,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62281\/revisions"}],"predecessor-version":[{"id":63646,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product\/62281\/revisions\/63646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/media\/62255"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/media?parent=62281"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_brand?post=62281"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_cat?post=62281"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/hr\/wp-json\/wp\/v2\/product_tag?post=62281"}],"curies":[{"name":"radni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}