{"id":61909,"date":"2026-08-14T09:44:46","date_gmt":"2026-08-14T09:44:46","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/cajaput-50ml-essential-oil\/"},"modified":"2026-08-31T16:36:12","modified_gmt":"2026-08-31T16:36:12","slug":"cajeput-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/","title":{"rendered":"Cajeput \u00e4therisches \u00d6l 50 ml aus Indonesien f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Cajeput_atherisches_Ol_50_ml\" >Cajeput \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Frischer_und_kampferartiger_Duft\" >Frischer und kampferartiger Duft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_frische_Raumdufte\" >F\u00fcr Aromatherapie und frische Raumd\u00fcfte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Cajeput_aus_der_Melaleuca-Familie\" >Cajeput aus der Melaleuca-Familie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/hu\/termek\/cajeput-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-11\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-11\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-11\" data-testid=\"conversation-turn-34\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"7e54b921-eeae-4a55-8c35-15186421d43c\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"386\" data-end=\"419\"><span class=\"ez-toc-section\" id=\"Cajeput_atherisches_Ol_50_ml\"><\/span>Cajeput \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"421\" data-end=\"682\">Das <strong data-start=\"425\" data-end=\"457\">Cajeput \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Bl\u00e4ttern und Zweigen von <em data-start=\"496\" data-end=\"516\">Melaleuca cajuputi<\/em> gewonnen. Die Pflanze geh\u00f6rt zur gleichen Gattung wie der bekannte Teebaum und liefert ein \u00e4therisches \u00d6l mit einem <strong data-start=\"633\" data-end=\"681\">intensiven, frischen und kampferartigen Duft<\/strong>.<\/p>\n<p data-start=\"684\" data-end=\"772\">Das f\u00fcr dieses \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"757\" data-end=\"771\">Indonesien<\/strong>.<\/p>\n<hr data-start=\"774\" data-end=\"777\" \/>\n<h4 data-start=\"779\" data-end=\"822\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"824\" data-end=\"955\">F\u00fcr die Herstellung des <strong data-start=\"848\" data-end=\"880\">Cajeput \u00e4therisches \u00d6l 50 ml<\/strong> werden Bl\u00e4tter und Zweige mittels <strong data-start=\"915\" data-end=\"942\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"957\" data-end=\"1082\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Pflanze gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1084\" data-end=\"1087\" \/>\n<h4 data-start=\"1089\" data-end=\"1126\"><span class=\"ez-toc-section\" id=\"Frischer_und_kampferartiger_Duft\"><\/span>Frischer und kampferartiger Duft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1128\" data-end=\"1364\">Cajeput\u00f6l besitzt ein charakteristisches <strong data-start=\"1169\" data-end=\"1248\">frisches, kampferartiges, krautiges und leicht medizinisch anmutendes Aroma<\/strong>. Sein Duft weist \u00c4hnlichkeiten mit Eukalyptus und Teebaum auf, besitzt jedoch einen eigenen aromatischen Charakter.<\/p>\n<p data-start=\"1366\" data-end=\"1454\">Bereits kleine Mengen sorgen f\u00fcr einen deutlich wahrnehmbaren, klaren und frischen Duft.<\/p>\n<hr data-start=\"1456\" data-end=\"1459\" \/>\n<h4 data-start=\"1461\" data-end=\"1505\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_frische_Raumdufte\"><\/span>F\u00fcr Aromatherapie und frische Raumd\u00fcfte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1507\" data-end=\"1624\">Das <strong data-start=\"1511\" data-end=\"1543\">Cajeput \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser, Duftlampen und individuelle Aromamischungen.<\/p>\n<p data-start=\"1626\" data-end=\"1823\">Sein intensiver Duft eignet sich besonders f\u00fcr eine <strong data-start=\"1678\" data-end=\"1714\">frische und klare Raumatmosph\u00e4re<\/strong> und l\u00e4sst sich gut mit Eukalyptus, Teebaum, Pfefferminze, Zitrone und verschiedenen Kr\u00e4uter\u00f6len kombinieren.<\/p>\n<hr data-start=\"1825\" data-end=\"1828\" \/>\n<h4 data-start=\"1830\" data-end=\"1868\"><span class=\"ez-toc-section\" id=\"Cajeput_aus_der_Melaleuca-Familie\"><\/span>Cajeput aus der Melaleuca-Familie<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1870\" data-end=\"2057\"><em data-start=\"1870\" data-end=\"1890\">Melaleuca cajuputi<\/em> geh\u00f6rt zur Gattung <strong data-start=\"1910\" data-end=\"1923\">Melaleuca<\/strong>, aus der verschiedene bekannte \u00e4therische \u00d6le gewonnen werden. Dazu z\u00e4hlt beispielsweise auch Teebaum\u00f6l aus <em data-start=\"2032\" data-end=\"2056\">Melaleuca alternifolia<\/em>.<\/p>\n<p data-start=\"2059\" data-end=\"2203\">Cajeput wird traditionell in verschiedenen aromatischen Anwendungen verwendet und ist besonders f\u00fcr sein kr\u00e4ftiges, frisches Duftprofil bekannt.<\/p>\n<hr data-start=\"2205\" data-end=\"2208\" \/>\n<h4 data-start=\"2210\" data-end=\"2229\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2231\" data-end=\"2719\">\n<li data-section-id=\"9oldcr\" data-start=\"2231\" data-end=\"2274\"><strong data-start=\"2233\" data-end=\"2245\">Produkt:<\/strong> Cajeput \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"ca0f38\" data-start=\"2275\" data-end=\"2297\"><strong data-start=\"2277\" data-end=\"2289\">Pflanze:<\/strong> Cajeput<\/li>\n<li data-section-id=\"3u91ty\" data-start=\"2298\" data-end=\"2348\"><strong data-start=\"2300\" data-end=\"2327\">Botanische Bezeichnung:<\/strong> <em data-start=\"2328\" data-end=\"2348\">Melaleuca cajuputi<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2349\" data-end=\"2368\"><strong data-start=\"2351\" data-end=\"2362\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"1d9nbuk\" data-start=\"2369\" data-end=\"2419\"><strong data-start=\"2371\" data-end=\"2400\">Verwendeter Pflanzenteil:<\/strong> Bl\u00e4tter und Zweige<\/li>\n<li data-section-id=\"1yxfgl5\" data-start=\"2420\" data-end=\"2446\"><strong data-start=\"2422\" data-end=\"2435\">Herkunft:<\/strong> Indonesien<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2447\" data-end=\"2487\"><strong data-start=\"2449\" data-end=\"2463\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1nhpy1\" data-start=\"2488\" data-end=\"2548\"><strong data-start=\"2490\" data-end=\"2505\">Duftprofil:<\/strong> Frisch \/ kampferartig \/ krautig \/ intensiv<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2549\" data-end=\"2600\"><strong data-start=\"2551\" data-end=\"2566\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2601\" data-end=\"2658\"><strong data-start=\"2603\" data-end=\"2636\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2659\" data-end=\"2690\"><strong data-start=\"2661\" data-end=\"2680\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswkba\" data-start=\"2691\" data-end=\"2719\"><strong data-start=\"2693\" data-end=\"2705\">Barcode:<\/strong> 5055796529803<\/li>\n<\/ul>\n<hr data-start=\"2721\" data-end=\"2724\" \/>\n<h4 data-start=\"2726\" data-end=\"2750\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2752\" data-end=\"2954\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2790\" data-end=\"2854\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"2956\" data-end=\"3110\">Cajeput\u00f6l aufgrund seines intensiven Charakters sparsam dosieren. Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen.<\/p>\n<p data-start=\"3112\" data-end=\"3260\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Cajeput \u00e4therisches \u00d6l 50 ml aus Indonesien, durch Wasserdampfdestillation aus Bl\u00e4ttern und Zweigen gewonnen. Frisch-kampferartiger Duft f\u00fcr Aromatherapie.<\/em><\/p>","protected":false},"featured_media":61902,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61909","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/61909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/comments?post=61909"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/61909\/revisions"}],"predecessor-version":[{"id":63650,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/61909\/revisions\/63650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/media\/61902"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/media?parent=61909"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_brand?post=61909"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_cat?post=61909"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_tag?post=61909"}],"curies":[{"name":"munkaf\u00fczet","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}