{"id":62168,"date":"2026-08-14T09:48:40","date_gmt":"2026-08-14T09:48:40","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/may-chang-50ml-essential-oil\/"},"modified":"2026-08-31T16:15:28","modified_gmt":"2026-08-31T16:15:28","slug":"may-chang-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/","title":{"rendered":"May Chang \u00e4therisches \u00d6l 50 ml Litsea Cubeba aus China f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tartalomjegyz\u00e9k<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Tartalomjegyz\u00e9k be-\/kikapcsol\u00e1sa\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">V\u00e1lt\u00e1s<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#May_Chang_atherisches_Ol_50_ml\" >May Chang \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Frischer_und_zitroniger_Duft\" >Frischer und zitroniger Duft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Fur_eine_frische_und_belebende_Atmosphare\" >F\u00fcr eine frische und belebende Atmosph\u00e4re<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Vielseitig_fur_naturliche_Duftmischungen\" >Vielseitig f\u00fcr nat\u00fcrliche Duftmischungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Produktdetails\" >Term\u00e9kadatok<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/hu\/termek\/may-chang-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Biztons\u00e1gi utas\u00edt\u00e1sok<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"394\" data-end=\"429\"><span class=\"ez-toc-section\" id=\"May_Chang_atherisches_Ol_50_ml\"><\/span>May Chang \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"431\" data-end=\"680\">A <strong data-start=\"435\" data-end=\"469\">May Chang \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Fr\u00fcchten von <em data-start=\"496\" data-end=\"511\">Litsea cubeba<\/em> gewonnen. Die aromatische Pflanze ist auch unter den Namen <strong data-start=\"571\" data-end=\"588\">Litsea Cubeba<\/strong> \u00e9s <strong data-start=\"593\" data-end=\"606\">May Chang<\/strong> bekannt und besitzt einen besonders frischen, intensiven Zitruscharakter.<\/p>\n<p data-start=\"682\" data-end=\"769\">Die f\u00fcr dieses \u00e4therische \u00d6l verwendeten Fr\u00fcchte stammen laut Hersteller aus <strong data-start=\"759\" data-end=\"768\">China<\/strong>.<\/p>\n<hr data-start=\"771\" data-end=\"774\" \/>\n<h4 data-start=\"776\" data-end=\"819\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"821\" data-end=\"947\">F\u00fcr die Herstellung des <strong data-start=\"845\" data-end=\"879\">May Chang \u00e4therisches \u00d6l 50 ml<\/strong> werden die Fr\u00fcchte mittels <strong data-start=\"907\" data-end=\"934\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"949\" data-end=\"1074\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Pflanze gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1076\" data-end=\"1079\" \/>\n<h4 data-start=\"1081\" data-end=\"1114\"><span class=\"ez-toc-section\" id=\"Frischer_und_zitroniger_Duft\"><\/span>Frischer und zitroniger Duft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1116\" data-end=\"1346\">May Chang besitzt ein charakteristisches <strong data-start=\"1157\" data-end=\"1220\">frisches, zitroniges, leicht s\u00fc\u00dfliches und fruchtiges Aroma<\/strong>. Sein lebendiger Zitruscharakter erinnert an Zitronengras, besitzt jedoch ein eigenst\u00e4ndiges, angenehm fruchtiges Duftprofil.<\/p>\n<p data-start=\"1348\" data-end=\"1431\">Dadurch eignet sich May Chang hervorragend f\u00fcr frische und klare Duftkompositionen.<\/p>\n<hr data-start=\"1433\" data-end=\"1436\" \/>\n<h4 data-start=\"1438\" data-end=\"1484\"><span class=\"ez-toc-section\" id=\"Fur_eine_frische_und_belebende_Atmosphare\"><\/span>F\u00fcr eine frische und belebende Atmosph\u00e4re<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1486\" data-end=\"1627\">In der Aromatherapie wird der Duft von May Chang traditionell mit einer <strong data-start=\"1558\" data-end=\"1616\">belebenden, aufmunternden und erfrischenden Atmosph\u00e4re<\/strong> verbunden.<\/p>\n<p data-start=\"1629\" data-end=\"1819\">Das Aroma eignet sich besonders f\u00fcr Diffuser und Duftlampen, wenn eine frische Raumatmosph\u00e4re gew\u00fcnscht ist \u2013 beispielsweise am Morgen, beim Arbeiten oder w\u00e4hrend konzentrierter T\u00e4tigkeiten.<\/p>\n<hr data-start=\"1821\" data-end=\"1824\" \/>\n<h4 data-start=\"1826\" data-end=\"1871\"><span class=\"ez-toc-section\" id=\"Vielseitig_fur_naturliche_Duftmischungen\"><\/span>Vielseitig f\u00fcr nat\u00fcrliche Duftmischungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1873\" data-end=\"1992\">A <strong data-start=\"1877\" data-end=\"1911\">May Chang \u00e4therisches \u00d6l 50 ml<\/strong> l\u00e4sst sich hervorragend mit anderen Zitrus-, Kr\u00e4uter- und Holznoten kombinieren.<\/p>\n<p data-start=\"1994\" data-end=\"2144\">Besonders interessante Duftkombinationen entstehen beispielsweise zusammen mit <strong data-start=\"2073\" data-end=\"2143\">Teebaum, Lavendel, Eukalyptus, Zitrone oder verschiedenen Holz\u00f6len<\/strong>.<\/p>\n<hr data-start=\"2146\" data-end=\"2149\" \/>\n<h4 data-start=\"2151\" data-end=\"2170\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Term\u00e9kadatok<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2172\" data-end=\"2661\">\n<li data-section-id=\"5yu6k1\" data-start=\"2172\" data-end=\"2217\"><strong data-start=\"2174\" data-end=\"2186\">Term\u00e9k:<\/strong> May Chang \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"wh21cl\" data-start=\"2218\" data-end=\"2258\"><strong data-start=\"2220\" data-end=\"2232\">N\u00f6v\u00e9ny:<\/strong> May Chang \/ Litsea Cubeba<\/li>\n<li data-section-id=\"7tligc\" data-start=\"2259\" data-end=\"2304\"><strong data-start=\"2261\" data-end=\"2288\">Botanische Bezeichnung:<\/strong> <em data-start=\"2289\" data-end=\"2304\">Litsea cubeba<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2305\" data-end=\"2324\"><strong data-start=\"2307\" data-end=\"2318\">Tartalom:<\/strong> 50 ml<\/li>\n<li data-section-id=\"1hkxa83\" data-start=\"2325\" data-end=\"2363\"><strong data-start=\"2327\" data-end=\"2356\">Verwendeter Pflanzenteil:<\/strong> Frucht<\/li>\n<li data-section-id=\"rbx1tu\" data-start=\"2364\" data-end=\"2385\"><strong data-start=\"2366\" data-end=\"2379\">Sz\u00e1rmaz\u00e1s:<\/strong> China<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2386\" data-end=\"2426\"><strong data-start=\"2388\" data-end=\"2402\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"10n2wji\" data-start=\"2427\" data-end=\"2490\"><strong data-start=\"2429\" data-end=\"2444\">Illatprofil:<\/strong> Frisch \/ zitronig \/ fruchtig \/ leicht s\u00fc\u00dflich<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2491\" data-end=\"2542\"><strong data-start=\"2493\" data-end=\"2508\">Haszn\u00e1lat:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2543\" data-end=\"2600\"><strong data-start=\"2545\" data-end=\"2578\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2601\" data-end=\"2632\"><strong data-start=\"2603\" data-end=\"2622\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswq6y\" data-start=\"2633\" data-end=\"2661\"><strong data-start=\"2635\" data-end=\"2647\">Barcode:<\/strong> 5055796529766<\/li>\n<\/ul>\n<hr data-start=\"2663\" data-end=\"2666\" \/>\n<h4 data-start=\"2668\" data-end=\"2692\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Biztons\u00e1gi utas\u00edt\u00e1sok<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2694\" data-end=\"2896\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2732\" data-end=\"2796\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"2898\" data-end=\"3135\" data-is-last-node=\"\" data-is-only-node=\"\">Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen. Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"235\" data-end=\"387\"><em>May Chang \u00e4therisches \u00d6l 50 ml aus China, durch Wasserdampfdestillation der Fr\u00fcchte gewonnen. Frisch-zitroniger Duft f\u00fcr Aromatherapie und Raumduft.<\/em><\/p>","protected":false},"featured_media":62154,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62168","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/62168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/comments?post=62168"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/62168\/revisions"}],"predecessor-version":[{"id":63641,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product\/62168\/revisions\/63641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/media\/62154"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/media?parent=62168"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_brand?post=62168"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_cat?post=62168"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/hu\/wp-json\/wp\/v2\/product_tag?post=62168"}],"curies":[{"name":"munkaf\u00fczet","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}