{"id":61985,"date":"2026-08-14T09:46:19","date_gmt":"2026-08-14T09:46:19","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/white-birch-50ml-essential-oil\/"},"modified":"2026-08-31T16:57:14","modified_gmt":"2026-08-31T16:57:14","slug":"weissbirke-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/","title":{"rendered":"Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml aus China f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Weisbirke_atherisches_Ol_50_ml\" >Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Aus_Blattknospen_durch_Wasserdampfdestillation\" >Aus Blattknospen durch Wasserdampfdestillation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Frischer_und_holziger_Birkenduft\" >Frischer und holziger Birkenduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_naturliche_Duftmischungen\" >F\u00fcr Aromatherapie und nat\u00fcrliche Duftmischungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Weisbirke_%E2%80%93_Betula_pendula\" >Wei\u00dfbirke \u2013 Betula pendula<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/it\/prodotto\/weissbirke-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-16\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-16\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-16\" data-testid=\"conversation-turn-44\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"e55065aa-bb72-4332-b8ec-bc3c3f8adbff\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"390\" data-end=\"425\"><span class=\"ez-toc-section\" id=\"Weisbirke_atherisches_Ol_50_ml\"><\/span>Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"427\" data-end=\"652\">Das <strong data-start=\"431\" data-end=\"465\">Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Blattknospen der Wei\u00dfbirke beziehungsweise H\u00e4ngebirke (<em data-start=\"534\" data-end=\"550\">Betula pendula<\/em>) gewonnen. Das \u00e4therische \u00d6l besitzt einen charakteristischen <strong data-start=\"613\" data-end=\"651\">frischen, gr\u00fcnen und holzigen Duft<\/strong>.<\/p>\n<p data-start=\"654\" data-end=\"737\">Das f\u00fcr dieses \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"727\" data-end=\"736\">China<\/strong>.<\/p>\n<hr data-start=\"739\" data-end=\"742\" \/>\n<h4 data-start=\"744\" data-end=\"795\"><span class=\"ez-toc-section\" id=\"Aus_Blattknospen_durch_Wasserdampfdestillation\"><\/span>Aus Blattknospen durch Wasserdampfdestillation<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"797\" data-end=\"928\">F\u00fcr die Herstellung des <strong data-start=\"821\" data-end=\"855\">Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<\/strong> werden die Blattknospen mittels <strong data-start=\"888\" data-end=\"915\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"930\" data-end=\"1065\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile des Pflanzenmaterials gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1067\" data-end=\"1070\" \/>\n<h4 data-start=\"1072\" data-end=\"1109\"><span class=\"ez-toc-section\" id=\"Frischer_und_holziger_Birkenduft\"><\/span>Frischer und holziger Birkenduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1111\" data-end=\"1316\">Wei\u00dfbirken\u00f6l besitzt ein <strong data-start=\"1136\" data-end=\"1196\">frisches, gr\u00fcnes, holziges und leicht erdiges Duftprofil<\/strong>. Der nat\u00fcrliche Pflanzencharakter macht es zu einer interessanten Erg\u00e4nzung f\u00fcr Wald-, Kr\u00e4uter- und Holzduftmischungen.<\/p>\n<p data-start=\"1318\" data-end=\"1426\">Besonders harmonisch l\u00e4sst sich der Duft mit Nadelholz-, Kr\u00e4uter- und verschiedenen Zitrusnoten kombinieren.<\/p>\n<hr data-start=\"1428\" data-end=\"1431\" \/>\n<h4 data-start=\"1433\" data-end=\"1485\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_naturliche_Duftmischungen\"><\/span>F\u00fcr Aromatherapie und nat\u00fcrliche Duftmischungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1487\" data-end=\"1609\">Das <strong data-start=\"1491\" data-end=\"1525\">Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser, Duftlampen und weitere aromatische Anwendungen.<\/p>\n<p data-start=\"1611\" data-end=\"1811\">Sein klarer, naturverbundener Duft eignet sich besonders f\u00fcr <strong data-start=\"1672\" data-end=\"1717\">frische und waldige Raumduftkompositionen<\/strong> und kann sowohl allein als auch in Kombination mit anderen \u00e4therischen \u00d6len verwendet werden.<\/p>\n<hr data-start=\"1813\" data-end=\"1816\" \/>\n<h4 data-start=\"1818\" data-end=\"1849\"><span class=\"ez-toc-section\" id=\"Weisbirke_%E2%80%93_Betula_pendula\"><\/span>Wei\u00dfbirke \u2013 Betula pendula<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1851\" data-end=\"2033\">Die Wei\u00dfbirke, auch <strong data-start=\"1871\" data-end=\"1885\">H\u00e4ngebirke<\/strong> genannt, ist unter der botanischen Bezeichnung <em data-start=\"1933\" data-end=\"1949\">Betula pendula<\/em> bekannt und an ihrer charakteristischen hellen bis wei\u00dfen Rinde leicht zu erkennen.<\/p>\n<p data-start=\"2035\" data-end=\"2266\">Birkenbestandteile besitzen eine lange Tradition in verschiedenen pflanzlichen Anwendungen. Bei diesem Produkt steht jedoch die Verwendung als <strong data-start=\"2178\" data-end=\"2250\">konzentriertes aromatisches \u00d6l f\u00fcr Aromatherapie und Duftanwendungen<\/strong> im Vordergrund.<\/p>\n<hr data-start=\"2268\" data-end=\"2271\" \/>\n<h4 data-start=\"2273\" data-end=\"2292\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2294\" data-end=\"2800\">\n<li data-section-id=\"1q88uic\" data-start=\"2294\" data-end=\"2339\"><strong data-start=\"2296\" data-end=\"2308\">Produkt:<\/strong> Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"vr9a6r\" data-start=\"2340\" data-end=\"2377\"><strong data-start=\"2342\" data-end=\"2354\">Pflanze:<\/strong> Wei\u00dfbirke \/ H\u00e4ngebirke<\/li>\n<li data-section-id=\"rf2ovn\" data-start=\"2378\" data-end=\"2445\"><strong data-start=\"2380\" data-end=\"2423\">Botanische Bezeichnung laut Hersteller:<\/strong> <em data-start=\"2424\" data-end=\"2445\">Betula pendula Roth<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2446\" data-end=\"2465\"><strong data-start=\"2448\" data-end=\"2459\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"s6tuz4\" data-start=\"2466\" data-end=\"2510\"><strong data-start=\"2468\" data-end=\"2497\">Verwendeter Pflanzenteil:<\/strong> Blattknospen<\/li>\n<li data-section-id=\"rbx1tu\" data-start=\"2511\" data-end=\"2532\"><strong data-start=\"2513\" data-end=\"2526\">Herkunft:<\/strong> China<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2533\" data-end=\"2573\"><strong data-start=\"2535\" data-end=\"2549\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1jwpsbz\" data-start=\"2574\" data-end=\"2629\"><strong data-start=\"2576\" data-end=\"2591\">Duftprofil:<\/strong> Frisch \/ gr\u00fcn \/ holzig \/ leicht erdig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2630\" data-end=\"2681\"><strong data-start=\"2632\" data-end=\"2647\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2682\" data-end=\"2739\"><strong data-start=\"2684\" data-end=\"2717\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2740\" data-end=\"2771\"><strong data-start=\"2742\" data-end=\"2761\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1quu2nm\" data-start=\"2772\" data-end=\"2800\"><strong data-start=\"2774\" data-end=\"2786\">Barcode:<\/strong> 5055796530007<\/li>\n<\/ul>\n<hr data-start=\"2802\" data-end=\"2805\" \/>\n<h4 data-start=\"2807\" data-end=\"2831\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2833\" data-end=\"3035\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2871\" data-end=\"2935\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3037\" data-end=\"3221\">Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vor der ersten Anwendung einen Vertr\u00e4glichkeitstest an einer kleinen Hautstelle durchf\u00fchren.<\/p>\n<p data-start=\"3223\" data-end=\"3371\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Wei\u00dfbirke \u00e4therisches \u00d6l 50 ml aus China, durch Wasserdampfdestillation der Blattknospen gewonnen. Frisch-holziger Duft f\u00fcr Aromatherapie und Duftmischungen.<\/em><\/p>","protected":false},"featured_media":61978,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61985","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/61985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/comments?post=61985"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/61985\/revisions"}],"predecessor-version":[{"id":63657,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/61985\/revisions\/63657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media\/61978"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media?parent=61985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_brand?post=61985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_cat?post=61985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_tag?post=61985"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}