{"id":62236,"date":"2026-08-14T09:49:38","date_gmt":"2026-08-14T09:49:38","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/lemon-verbena-50ml-essential-oil\/"},"modified":"2026-08-31T16:57:28","modified_gmt":"2026-08-31T16:57:28","slug":"zitronenverbene-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/","title":{"rendered":"Zitronenverbene \u00e4therisches \u00d6l 50 ml aus Spanien f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommario<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Attiva\/disattiva la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Attiva\/disattiva<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Zitronenverbene_atherisches_Ol_50_ml\" >Zitronenverbene \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Frisch-zitroniger_Duft_mit_Krauternoten\" >Frisch-zitroniger Duft mit Kr\u00e4uternoten<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Naturlich_charakteristischer_Citral-Gehalt\" >Nat\u00fcrlich charakteristischer Citral-Gehalt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_belebende_Raumdufte\" >F\u00fcr Aromatherapie und belebende Raumd\u00fcfte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Produktdetails\" >Dettagli del prodotto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/it\/prodotto\/zitronenverbene-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Istruzioni di sicurezza<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"403\" data-end=\"444\"><span class=\"ez-toc-section\" id=\"Zitronenverbene_atherisches_Ol_50_ml\"><\/span>Zitronenverbene \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"446\" data-end=\"678\">IL <strong data-start=\"450\" data-end=\"490\">Zitronenverbene \u00e4therisches \u00d6l 50 ml<\/strong> wird aus dem Kraut der Zitronenverbene (<em data-start=\"531\" data-end=\"550\">Aloysia triphylla<\/em>) gewonnen. Die aromatische Pflanze ist besonders f\u00fcr ihren <strong data-start=\"610\" data-end=\"669\">intensiv frischen, zitronigen und leicht krautigen Duft<\/strong> bekannt.<\/p>\n<p data-start=\"680\" data-end=\"776\">Das f\u00fcr dieses \u00e4therische \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"764\" data-end=\"775\">Spagna<\/strong>.<\/p>\n<hr data-start=\"778\" data-end=\"781\" \/>\n<h4 data-start=\"783\" data-end=\"826\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"828\" data-end=\"956\">F\u00fcr die Herstellung des <strong data-start=\"852\" data-end=\"892\">Zitronenverbene \u00e4therisches \u00d6l 50 ml<\/strong> wird das Kraut mittels <strong data-start=\"916\" data-end=\"943\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"958\" data-end=\"1083\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Pflanze gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1085\" data-end=\"1088\" \/>\n<h4 data-start=\"1090\" data-end=\"1134\"><span class=\"ez-toc-section\" id=\"Frisch-zitroniger_Duft_mit_Krauternoten\"><\/span>Frisch-zitroniger Duft mit Kr\u00e4uternoten<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1136\" data-end=\"1274\">Zitronenverbene besitzt ein charakteristisches <strong data-start=\"1183\" data-end=\"1233\">frisches, klares und intensiv zitroniges Aroma<\/strong> mit feinen gr\u00fcnen und krautigen Nuancen.<\/p>\n<p data-start=\"1276\" data-end=\"1445\">Das Duftprofil wirkt leichter und pflanzlicher als viele klassische Zitrus\u00f6le und eignet sich hervorragend f\u00fcr frische, sommerliche und kr\u00e4uterbetonte Duftkompositionen.<\/p>\n<hr data-start=\"1447\" data-end=\"1450\" \/>\n<h4 data-start=\"1452\" data-end=\"1499\"><span class=\"ez-toc-section\" id=\"Naturlich_charakteristischer_Citral-Gehalt\"><\/span>Nat\u00fcrlich charakteristischer Citral-Gehalt<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1501\" data-end=\"1698\">Das \u00e4therische \u00d6l der Zitronenverbene ist f\u00fcr seinen nat\u00fcrlichen Gehalt an <strong data-start=\"1576\" data-end=\"1586\">Citral<\/strong> bekannt. Dieser aromatische Bestandteil tr\u00e4gt wesentlich zum ausgepr\u00e4gten zitronigen Duftcharakter des \u00d6ls bei.<\/p>\n<p data-start=\"1700\" data-end=\"1886\">Gerade die Kombination aus frischen Zitrusnoten und einem gr\u00fcnen Kr\u00e4utercharakter macht Zitronenverbene zu einer interessanten Komponente f\u00fcr Aromatherapie und nat\u00fcrliche Duftmischungen.<\/p>\n<hr data-start=\"1888\" data-end=\"1891\" \/>\n<h4 data-start=\"1893\" data-end=\"1939\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_belebende_Raumdufte\"><\/span>F\u00fcr Aromatherapie und belebende Raumd\u00fcfte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1941\" data-end=\"2065\">IL <strong data-start=\"1945\" data-end=\"1985\">Zitronenverbene \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser, Duftlampen und individuelle Duftmischungen.<\/p>\n<p data-start=\"2067\" data-end=\"2320\">In der Aromatherapie wird der Duft traditionell mit einer <strong data-start=\"2125\" data-end=\"2190\">positiven, harmonischen und zugleich erfrischenden Atmosph\u00e4re<\/strong> verbunden. Das Aroma eignet sich sowohl f\u00fcr entspannte Momente als auch f\u00fcr eine frische Raumbeduftung beim Arbeiten oder Lernen.<\/p>\n<hr data-start=\"2322\" data-end=\"2325\" \/>\n<h4 data-start=\"2327\" data-end=\"2346\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Dettagli del prodotto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2348\" data-end=\"2878\">\n<li data-section-id=\"15kk779\" data-start=\"2348\" data-end=\"2399\"><strong data-start=\"2350\" data-end=\"2362\">Prodotto:<\/strong> Zitronenverbene \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"gmzrey\" data-start=\"2400\" data-end=\"2430\"><strong data-start=\"2402\" data-end=\"2414\">Pianta:<\/strong> Zitronenverbene<\/li>\n<li data-section-id=\"3lj6ev\" data-start=\"2431\" data-end=\"2480\"><strong data-start=\"2433\" data-end=\"2460\">Botanische Bezeichnung:<\/strong> <em data-start=\"2461\" data-end=\"2480\">Aloysia triphylla<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2481\" data-end=\"2500\"><strong data-start=\"2483\" data-end=\"2494\">Contenuto:<\/strong> 50 ml<\/li>\n<li data-section-id=\"te5j0k\" data-start=\"2501\" data-end=\"2538\"><strong data-start=\"2503\" data-end=\"2532\">Verwendeter Pflanzenteil:<\/strong> Kraut<\/li>\n<li data-section-id=\"1hulq01\" data-start=\"2539\" data-end=\"2562\"><strong data-start=\"2541\" data-end=\"2554\">Origine:<\/strong> Spagna<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2563\" data-end=\"2603\"><strong data-start=\"2565\" data-end=\"2579\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"fyv734\" data-start=\"2604\" data-end=\"2663\"><strong data-start=\"2606\" data-end=\"2621\">Profilo della fragranza:<\/strong> Frisch \/ zitronig \/ gr\u00fcn \/ leicht krautig<\/li>\n<li data-section-id=\"idm0dx\" data-start=\"2664\" data-end=\"2708\"><strong data-start=\"2666\" data-end=\"2701\">Charakteristischer Bestandteil:<\/strong> Citral<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2709\" data-end=\"2760\"><strong data-start=\"2711\" data-end=\"2726\">Utilizzo:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"1nuk2t\" data-start=\"2761\" data-end=\"2817\"><strong data-start=\"2763\" data-end=\"2796\">Nettogewicht laut Hersteller:<\/strong> ca. 60 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2818\" data-end=\"2849\"><strong data-start=\"2820\" data-end=\"2839\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswkic\" data-start=\"2850\" data-end=\"2878\"><strong data-start=\"2852\" data-end=\"2864\">Barcode:<\/strong> 5055796529889<\/li>\n<\/ul>\n<hr data-start=\"2880\" data-end=\"2883\" \/>\n<h4 data-start=\"2885\" data-end=\"2909\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Istruzioni di sicurezza<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2911\" data-end=\"3113\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2949\" data-end=\"3013\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3115\" data-end=\"3345\">Aufgrund des nat\u00fcrlichen <strong data-start=\"3140\" data-end=\"3158\">Citral-Gehalts<\/strong> kann das \u00d6l bei empfindlicher Haut reizend wirken. F\u00fcr eine vorgesehene Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vorab einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"3347\" data-end=\"3495\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Zitronenverbene \u00e4therisches \u00d6l 50 ml aus Spanien, durch Wasserdampfdestillation gewonnen. Frisch-zitroniger Kr\u00e4uterduft f\u00fcr Aromatherapie und Raumduft.<\/em><\/p>","protected":false},"featured_media":62214,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62236","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/comments?post=62236"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62236\/revisions"}],"predecessor-version":[{"id":63656,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62236\/revisions\/63656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media\/62214"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media?parent=62236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_brand?post=62236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_cat?post=62236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_tag?post=62236"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}