{"id":62338,"date":"2026-08-14T09:50:48","date_gmt":"2026-08-14T09:50:48","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/carrot-seed-50ml-essential-oil\/"},"modified":"2026-09-01T16:38:06","modified_gmt":"2026-09-01T16:38:06","slug":"karottensamen-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/","title":{"rendered":"Karottensamen \u00e4therisches \u00d6l 50 ml aus Ungarn f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Karottensamen_atherisches_Ol_50_ml\" >Karottensamen \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Aus_getrockneten_Karottensamen_dampfdestilliert\" >Aus getrockneten Karottensamen dampfdestilliert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Warm_erdig_und_holzig\" >Warm, erdig und holzig<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Fur_erdende_Aromamischungen\" >F\u00fcr erdende Aromamischungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Traditionell_auch_in_der_Aromapflege_geschatzt\" >Traditionell auch in der Aromapflege gesch\u00e4tzt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/it\/prodotto\/karottensamen-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-15\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-15\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-15\" data-testid=\"conversation-turn-42\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"0b21b2fb-91bc-469d-8436-338029a0252a\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"398\" data-end=\"437\"><span class=\"ez-toc-section\" id=\"Karottensamen_atherisches_Ol_50_ml\"><\/span>Karottensamen \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"439\" data-end=\"727\">Das <strong data-start=\"443\" data-end=\"481\">Karottensamen \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den getrockneten Samen von <em data-start=\"518\" data-end=\"540\">Daucus carota sativa<\/em> gewonnen. Anders als der Name zun\u00e4chst vermuten l\u00e4sst, besitzt das \u00d6l keinen typisch s\u00fc\u00dfen Karottenduft, sondern ein charakteristisches <strong data-start=\"677\" data-end=\"726\">warmes, erdiges, holziges und krautiges Aroma<\/strong>.<\/p>\n<p data-start=\"729\" data-end=\"815\">Die f\u00fcr dieses \u00e4therische \u00d6l verwendeten Samen stammen laut Hersteller aus <strong data-start=\"804\" data-end=\"814\">Ungarn<\/strong>.<\/p>\n<hr data-start=\"817\" data-end=\"820\" \/>\n<h4 data-start=\"822\" data-end=\"874\"><span class=\"ez-toc-section\" id=\"Aus_getrockneten_Karottensamen_dampfdestilliert\"><\/span>Aus getrockneten Karottensamen dampfdestilliert<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"876\" data-end=\"1017\">F\u00fcr die Herstellung des <strong data-start=\"900\" data-end=\"938\">Karottensamen \u00e4therisches \u00d6l 50 ml<\/strong> werden die getrockneten Samen mittels <strong data-start=\"977\" data-end=\"1004\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"1019\" data-end=\"1236\">Dabei werden die fl\u00fcchtigen aromatischen Pflanzenbestandteile gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen. Das Ergebnis ist ein intensiv duftendes \u00d6l mit einem ausgepr\u00e4gt nat\u00fcrlichen, erdigen Charakter.<\/p>\n<hr data-start=\"1238\" data-end=\"1241\" \/>\n<h4 data-start=\"1243\" data-end=\"1270\"><span class=\"ez-toc-section\" id=\"Warm_erdig_und_holzig\"><\/span>Warm, erdig und holzig<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1272\" data-end=\"1492\">Karottensamen\u00f6l zeichnet sich durch einen <strong data-start=\"1314\" data-end=\"1369\">warmen, erdigen, holzigen und leicht krautigen Duft<\/strong> aus. Seine ungew\u00f6hnliche Aromatik eignet sich besonders f\u00fcr naturverbundene, holzige und kr\u00e4uterbetonte Duftkompositionen.<\/p>\n<p data-start=\"1494\" data-end=\"1640\">Es l\u00e4sst sich beispielsweise mit <strong data-start=\"1527\" data-end=\"1627\">Lavendel, Bergamotte, Geranie, Weihrauch, Zedernholz und anderen erdigen oder holzigen Duftnoten<\/strong> kombinieren.<\/p>\n<hr data-start=\"1642\" data-end=\"1645\" \/>\n<h4 data-start=\"1647\" data-end=\"1679\"><span class=\"ez-toc-section\" id=\"Fur_erdende_Aromamischungen\"><\/span>F\u00fcr erdende Aromamischungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1681\" data-end=\"1819\">In der Aromatherapie wird der Duft von Karottensamen traditionell mit einer <strong data-start=\"1757\" data-end=\"1808\">ruhigen, ausgleichenden und erdenden Atmosph\u00e4re<\/strong> verbunden.<\/p>\n<p data-start=\"1821\" data-end=\"2054\">Das <strong data-start=\"1825\" data-end=\"1863\">Karottensamen \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen sowie als aromatische Komponente individueller Duftmischungen. Aufgrund seines kr\u00e4ftigen Duftprofils empfiehlt sich eine sparsame Dosierung.<\/p>\n<hr data-start=\"2056\" data-end=\"2059\" \/>\n<h4 data-start=\"2061\" data-end=\"2112\"><span class=\"ez-toc-section\" id=\"Traditionell_auch_in_der_Aromapflege_geschatzt\"><\/span>Traditionell auch in der Aromapflege gesch\u00e4tzt<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2114\" data-end=\"2263\">Karottensamen\u00f6l findet aufgrund seines besonderen Duftprofils traditionell auch Verwendung in <strong data-start=\"2208\" data-end=\"2262\">kosmetischen und aromatischen Pflegeformulierungen<\/strong>.<\/p>\n<p data-start=\"2265\" data-end=\"2630\">F\u00fcr die Anwendung auf der Haut muss das konzentrierte \u00e4therische \u00d6l mit einem geeigneten Basis\u00f6l oder entsprechend einer gepr\u00fcften kosmetischen Rezeptur verd\u00fcnnt werden. Die vom Lieferanten genannten therapeutischen Wirkungen auf Haut, Organe, Infektionen oder andere Erkrankungen sind nicht als medizinisch nachgewiesene Eigenschaften dieses Produkts zu verstehen.<\/p>\n<hr data-start=\"2632\" data-end=\"2635\" \/>\n<h4 data-start=\"2637\" data-end=\"2656\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2658\" data-end=\"3146\">\n<li data-section-id=\"f3ixin\" data-start=\"2658\" data-end=\"2707\"><strong data-start=\"2660\" data-end=\"2672\">Produkt:<\/strong> Karottensamen \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"1j4njdt\" data-start=\"2708\" data-end=\"2738\"><strong data-start=\"2710\" data-end=\"2722\">Pflanze:<\/strong> Karotte \/ M\u00f6hre<\/li>\n<li data-section-id=\"pehnnj\" data-start=\"2739\" data-end=\"2791\"><strong data-start=\"2741\" data-end=\"2768\">Botanische Bezeichnung:<\/strong> <em data-start=\"2769\" data-end=\"2791\">Daucus carota sativa<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2792\" data-end=\"2811\"><strong data-start=\"2794\" data-end=\"2805\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"1ucyqhc\" data-start=\"2812\" data-end=\"2861\"><strong data-start=\"2814\" data-end=\"2843\">Verwendeter Pflanzenteil:<\/strong> Getrocknete Samen<\/li>\n<li data-section-id=\"1p2znta\" data-start=\"2862\" data-end=\"2884\"><strong data-start=\"2864\" data-end=\"2877\">Herkunft:<\/strong> Ungarn<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2885\" data-end=\"2925\"><strong data-start=\"2887\" data-end=\"2901\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1mhr43w\" data-start=\"2926\" data-end=\"2975\"><strong data-start=\"2928\" data-end=\"2943\">Duftprofil:<\/strong> Warm \/ erdig \/ holzig \/ krautig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2976\" data-end=\"3027\"><strong data-start=\"2978\" data-end=\"2993\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3028\" data-end=\"3085\"><strong data-start=\"3030\" data-end=\"3063\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3086\" data-end=\"3117\"><strong data-start=\"3088\" data-end=\"3107\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswq0k\" data-start=\"3118\" data-end=\"3146\"><strong data-start=\"3120\" data-end=\"3132\">Barcode:<\/strong> 5055796529797<\/li>\n<\/ul>\n<hr data-start=\"3148\" data-end=\"3151\" \/>\n<h4 data-start=\"3153\" data-end=\"3177\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3179\" data-end=\"3381\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"3217\" data-end=\"3281\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3383\" data-end=\"3536\">F\u00fcr Haut- oder Massageanwendungen ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vor der ersten Anwendung einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"3538\" data-end=\"3686\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Karottensamen \u00e4therisches \u00d6l 50 ml aus Ungarn, aus getrockneten Samen dampfdestilliert. Warm-erdiger, holziger Duft f\u00fcr Aromatherapie und Duftmischungen.<\/em><\/p>","protected":false},"featured_media":62330,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62338","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/comments?post=62338"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62338\/revisions"}],"predecessor-version":[{"id":63684,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product\/62338\/revisions\/63684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media\/62330"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/media?parent=62338"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_brand?post=62338"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_cat?post=62338"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/it\/wp-json\/wp\/v2\/product_tag?post=62338"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}