{"id":62343,"date":"2026-08-14T09:50:54","date_gmt":"2026-08-14T09:50:54","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/benzoin-dilute-dpg-50ml-essential-oil\/"},"modified":"2026-08-31T16:35:59","modified_gmt":"2026-08-31T16:35:59","slug":"benzoe-duftoel-50-ml-in-dpg","status":"publish","type":"product","link":"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/","title":{"rendered":"Benzoe Duft\u00f6l 50 ml in DPG \u2013 Benzoeharz aus den Philippinen f\u00fcr Aromatherapie"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Turinys<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Perjungti turin\u012f\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Perjungti<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Benzoe_Duftol_50_ml\" >Benzoe Duft\u00f6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Benzoe_in_DPG_verdunnt\" >Benzoe in DPG verd\u00fcnnt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Aus_aromatischem_Benzoeharz_gewonnen\" >Aus aromatischem Benzoeharz gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Beliebter_Duft_in_der_Parfumerie\" >Beliebter Duft in der Parf\u00fcmerie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Fur_warme_und_entspannende_Duftkompositionen\" >F\u00fcr warme und entspannende Duftkompositionen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Produktdetails\" >Produkto informacija<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/lt\/produktas\/benzoe-duftoel-50-ml-in-dpg\/#Sicherheitshinweise\" >Saugos instrukcijos<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"354\" data-end=\"378\"><span class=\"ez-toc-section\" id=\"Benzoe_Duftol_50_ml\"><\/span>Benzoe Duft\u00f6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"380\" data-end=\"636\">The <strong data-start=\"384\" data-end=\"407\">Benzoe Duft\u00f6l 50 ml<\/strong> wird aus dem aromatischen Harz von <em data-start=\"443\" data-end=\"459\">Styrax benzoin<\/em> hergestellt. Benzoe ist besonders f\u00fcr seinen <strong data-start=\"505\" data-end=\"567\">warmen, s\u00fc\u00dfen, balsamischen und leicht vanilleartigen Duft<\/strong> bekannt und wird seit Jahrhunderten als aromatisches Harz gesch\u00e4tzt.<\/p>\n<p data-start=\"638\" data-end=\"730\">Das f\u00fcr dieses Produkt verwendete Benzoeharz stammt laut Hersteller aus den <strong data-start=\"714\" data-end=\"729\">Philippinen<\/strong>.<\/p>\n<hr data-start=\"732\" data-end=\"735\" \/>\n<h4 data-start=\"737\" data-end=\"764\"><span class=\"ez-toc-section\" id=\"Benzoe_in_DPG_verdunnt\"><\/span>Benzoe in DPG verd\u00fcnnt<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"766\" data-end=\"977\">Bei diesem Produkt handelt es sich <strong data-start=\"801\" data-end=\"846\">nicht um 100% reines \u00e4therisches Benzoe\u00f6l<\/strong>. Der Hersteller bezeichnet das Produkt als \u201eDilute\/DPG\u201c, das Benzoe-Extrakt liegt also <strong data-start=\"934\" data-end=\"972\">verd\u00fcnnt in DPG (Dipropylenglykol)<\/strong> vor.<\/p>\n<p data-start=\"979\" data-end=\"1061\">Eine genaue Konzentration des Benzoe-Anteils wurde vom Hersteller nicht angegeben.<\/p>\n<hr data-start=\"1063\" data-end=\"1066\" \/>\n<h4 data-start=\"1068\" data-end=\"1109\"><span class=\"ez-toc-section\" id=\"Aus_aromatischem_Benzoeharz_gewonnen\"><\/span>Aus aromatischem Benzoeharz gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1111\" data-end=\"1214\">F\u00fcr die Herstellung wird das Harz von <em data-start=\"1149\" data-end=\"1165\">Styrax benzoin<\/em> mittels <strong data-start=\"1174\" data-end=\"1201\">L\u00f6sungsmittelextraktion<\/strong> verarbeitet.<\/p>\n<p data-start=\"1216\" data-end=\"1381\">Das daraus gewonnene aromatische Material besitzt den f\u00fcr Benzoe typischen intensiven Duft mit <strong data-start=\"1311\" data-end=\"1380\">balsamischen, warmen, s\u00fc\u00dflichen und leicht vanilleartigen Nuancen<\/strong>.<\/p>\n<hr data-start=\"1383\" data-end=\"1386\" \/>\n<h4 data-start=\"1388\" data-end=\"1425\"><span class=\"ez-toc-section\" id=\"Beliebter_Duft_in_der_Parfumerie\"><\/span>Beliebter Duft in der Parf\u00fcmerie<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1427\" data-end=\"1621\">Benzoe besitzt eine lange Tradition als <strong data-start=\"1467\" data-end=\"1493\">R\u00e4ucher- und Duftstoff<\/strong>. Auch heute wird das charakteristische Aroma h\u00e4ufig in der Parf\u00fcmerie und bei der Herstellung von Duftkompositionen eingesetzt.<\/p>\n<p data-start=\"1623\" data-end=\"1734\">Seine warme S\u00fc\u00dfe harmoniert besonders gut mit <strong data-start=\"1669\" data-end=\"1733\">Vanille-, Holz-, Gew\u00fcrz-, Harz- und orientalischen Duftnoten<\/strong>.<\/p>\n<hr data-start=\"1736\" data-end=\"1739\" \/>\n<h4 data-start=\"1741\" data-end=\"1790\"><span class=\"ez-toc-section\" id=\"Fur_warme_und_entspannende_Duftkompositionen\"><\/span>F\u00fcr warme und entspannende Duftkompositionen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1792\" data-end=\"1902\">The <strong data-start=\"1796\" data-end=\"1819\">Benzoe Duft\u00f6l 50 ml<\/strong> eignet sich f\u00fcr geeignete aromatische Anwendungen und individuelle Duftmischungen.<\/p>\n<p data-start=\"1904\" data-end=\"2117\">Der warme und balsamische Duft wird traditionell mit einer <strong data-start=\"1963\" data-end=\"2020\">gem\u00fctlichen, beruhigenden und harmonischen Atmosph\u00e4re<\/strong> verbunden und eignet sich besonders f\u00fcr entspannte Abendstunden und warme Raumduftkompositionen.<\/p>\n<hr data-start=\"2119\" data-end=\"2122\" \/>\n<h4 data-start=\"2124\" data-end=\"2143\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produkto informacija<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2145\" data-end=\"2720\">\n<li data-section-id=\"y4bcz9\" data-start=\"2145\" data-end=\"2179\"><strong data-start=\"2147\" data-end=\"2159\">Produktas:<\/strong> Benzoe Duft\u00f6l 50 ml<\/li>\n<li data-section-id=\"1itxq4h\" data-start=\"2180\" data-end=\"2201\"><strong data-start=\"2182\" data-end=\"2194\">Augalas:<\/strong> Benzoe<\/li>\n<li data-section-id=\"yo8c6\" data-start=\"2202\" data-end=\"2248\"><strong data-start=\"2204\" data-end=\"2231\">Botanische Bezeichnung:<\/strong> <em data-start=\"2232\" data-end=\"2248\">Styrax benzoin<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2249\" data-end=\"2268\"><strong data-start=\"2251\" data-end=\"2262\">Turinys:<\/strong> 50 ml<\/li>\n<li data-section-id=\"zbwni4\" data-start=\"2269\" data-end=\"2305\"><strong data-start=\"2271\" data-end=\"2300\">Verwendeter Pflanzenteil:<\/strong> Harz<\/li>\n<li data-section-id=\"576dsn\" data-start=\"2306\" data-end=\"2333\"><strong data-start=\"2308\" data-end=\"2321\">Kilm\u0117:<\/strong> Philippinen<\/li>\n<li data-section-id=\"43i7is\" data-start=\"2334\" data-end=\"2374\"><strong data-start=\"2336\" data-end=\"2350\">Gewinnung:<\/strong> L\u00f6sungsmittelextraktion<\/li>\n<li data-section-id=\"ppasvl\" data-start=\"2375\" data-end=\"2415\"><strong data-start=\"2377\" data-end=\"2392\">Verd\u00fcnnung:<\/strong> DPG (Dipropylenglykol)<\/li>\n<li data-section-id=\"1y4fcoi\" data-start=\"2416\" data-end=\"2467\"><strong data-start=\"2418\" data-end=\"2436\">Konzentration:<\/strong> Vom Hersteller nicht angegeben<\/li>\n<li data-section-id=\"1acn7hn\" data-start=\"2468\" data-end=\"2540\"><strong data-start=\"2470\" data-end=\"2485\">Kvapo profilis:<\/strong> Warm \/ s\u00fc\u00df \/ balsamisch \/ harzig \/ leicht vanilleartig<\/li>\n<li data-section-id=\"1xht984\" data-start=\"2541\" data-end=\"2601\"><strong data-start=\"2543\" data-end=\"2558\">Naudojimas:<\/strong> Aromatische Duftanwendungen und Parf\u00fcmerie<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2602\" data-end=\"2659\"><strong data-start=\"2604\" data-end=\"2637\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2660\" data-end=\"2691\"><strong data-start=\"2662\" data-end=\"2681\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswkdu\" data-start=\"2692\" data-end=\"2720\"><strong data-start=\"2694\" data-end=\"2706\">Barcode:<\/strong> 5055796529834<\/li>\n<\/ul>\n<hr data-start=\"2722\" data-end=\"2725\" \/>\n<h4 data-start=\"2727\" data-end=\"2751\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Saugos instrukcijos<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2753\" data-end=\"2945\">Dieses Produkt ist eine <strong data-start=\"2777\" data-end=\"2823\">konzentrierte aromatische Mischung mit DPG<\/strong>. <strong data-start=\"2825\" data-end=\"2845\">Nicht einnehmen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"2947\" data-end=\"3153\">Vor einer Anwendung auf der Haut sollte gepr\u00fcft werden, ob das Produkt laut Hersteller f\u00fcr die vorgesehene kosmetische Anwendung geeignet ist. Bei empfindlicher Haut empfiehlt sich ein Vertr\u00e4glichkeitstest.<\/p>\n<p data-start=\"3155\" data-end=\"3303\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Benzoe Duft\u00f6l 50 ml aus Benzoeharz von den Philippinen, in DPG verd\u00fcnnt. Warm-s\u00fc\u00dfer, balsamischer Duft f\u00fcr Aromatherapie, Parf\u00fcmerie und Raumduft.<\/em><\/p>","protected":false},"featured_media":62336,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62343","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product\/62343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/comments?post=62343"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product\/62343\/revisions"}],"predecessor-version":[{"id":63652,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product\/62343\/revisions\/63652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/media\/62336"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/media?parent=62343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product_brand?post=62343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product_cat?post=62343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/lt\/wp-json\/wp\/v2\/product_tag?post=62343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}