{"id":63597,"date":"2026-08-30T12:44:20","date_gmt":"2026-08-30T12:44:20","guid":{"rendered":"https:\/\/honigbee.com\/?post_type=product&#038;p=63597"},"modified":"2026-08-30T12:46:19","modified_gmt":"2026-08-30T12:46:19","slug":"agewell-40-schlaf-unterstuetzung-beerenmix","status":"publish","type":"product","link":"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/","title":{"rendered":"Applied Nutrition Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix 300 g \u2013 mit Glycin, Magnesium &#038; Pflanzenextrakten"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Satura r\u0101d\u012bt\u0101js<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"P\u0101rsl\u0113gt satura r\u0101d\u012bt\u0101ju\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">P\u0101rsl\u0113gt<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Agewell_40_Schlaf_Unterstutzung_Beerenmix\" >Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Mit_3000_mg_Glycin_und_Magnesium\" >Mit 3000 mg Glycin und Magnesium<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Mit_Sauerkirsche_L-Theanin_und_Zitronenmelisse\" >Mit Sauerkirsche, L-Theanin und Zitronenmelisse<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Mit_Griffonia_5-HTP_und_L-Tryptophan\" >Mit Griffonia, 5-HTP und L-Tryptophan<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Inhaltsstoffe_pro_Tagesportion\" >Inhaltsstoffe pro Tagesportion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Zutaten\" >Sast\u0101vda\u013cas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Einnahmeempfehlung\" >Ieteicam\u0101 deva<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/lv\/products\/agewell-40-schlaf-unterstuetzung-beerenmix\/#Wichtige_Hinweise\" >Wichtige Hinweise<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"804\" data-end=\"851\"><span class=\"ez-toc-section\" id=\"Agewell_40_Schlaf_Unterstutzung_Beerenmix\"><\/span>Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"853\" data-end=\"1032\">The <strong data-start=\"857\" data-end=\"903\">Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix<\/strong> von Applied Nutrition ist ein Nahrungserg\u00e4nzungsmittel in Pulverform, das speziell f\u00fcr Erwachsene ab 40 Jahren entwickelt wurde.<\/p>\n<p data-start=\"1034\" data-end=\"1247\">Die umfangreiche Rezeptur kombiniert <strong data-start=\"1071\" data-end=\"1101\">Glycin, Magnesium und Zink<\/strong> mit ausgew\u00e4hlten Pflanzenextrakten und Aminos\u00e4uren wie Sauerkirsche, L-Theanin, Zitronenmelisse, Reishi, Ashwagandha, Griffonia und L-Tryptophan.<\/p>\n<p data-start=\"1249\" data-end=\"1364\">Die Dose enth\u00e4lt <strong data-start=\"1266\" data-end=\"1318\">300 g Pulver beziehungsweise 30 Portionen \u00e0 10 g<\/strong> und besitzt einen fruchtigen Beerengeschmack.<\/p>\n<hr data-start=\"1366\" data-end=\"1369\" \/>\n<h4 data-start=\"1371\" data-end=\"1408\"><span class=\"ez-toc-section\" id=\"Mit_3000_mg_Glycin_und_Magnesium\"><\/span>Mit 3000 mg Glycin und Magnesium<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1410\" data-end=\"1484\">Eine Tagesportion enth\u00e4lt <strong data-start=\"1436\" data-end=\"1456\">3000 mg L-Glycin<\/strong> k\u0101 ar\u012b <strong data-start=\"1463\" data-end=\"1483\">400 mg Magnesium<\/strong>.<\/p>\n<p data-start=\"1486\" data-end=\"1641\">Magnesium tr\u00e4gt zu einer normalen Funktion des Nervensystems und einer normalen psychischen Funktion sowie zur Verringerung von M\u00fcdigkeit und Erm\u00fcdung bei.<\/p>\n<p data-start=\"1643\" data-end=\"1705\">Zus\u00e4tzlich enth\u00e4lt die Formel <strong data-start=\"1673\" data-end=\"1704\">14 mg Zink pro Tagesportion<\/strong>.<\/p>\n<hr data-start=\"1707\" data-end=\"1710\" \/>\n<h4 data-start=\"1712\" data-end=\"1764\"><span class=\"ez-toc-section\" id=\"Mit_Sauerkirsche_L-Theanin_und_Zitronenmelisse\"><\/span>Mit Sauerkirsche, L-Theanin und Zitronenmelisse<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1766\" data-end=\"1894\">The <strong data-start=\"1770\" data-end=\"1816\">Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix<\/strong> kombiniert verschiedene ausgew\u00e4hlte Inhaltsstoffe in einer t\u00e4glichen Portion.<\/p>\n<p data-start=\"1896\" data-end=\"1925\">Enthalten sind unter anderem:<\/p>\n<ul data-start=\"1927\" data-end=\"2144\">\n<li data-section-id=\"yvxjwa\" data-start=\"1927\" data-end=\"1977\"><strong data-start=\"1929\" data-end=\"1977\">500 mg Sauerkirsche aus Montmorency-Kirschen<\/strong><\/li>\n<li data-section-id=\"m0y0xl\" data-start=\"1978\" data-end=\"2020\"><strong data-start=\"1980\" data-end=\"2020\">250 mg L-Theanin aus Gr\u00fcntee-Extrakt<\/strong><\/li>\n<li data-section-id=\"2ru6zn\" data-start=\"2021\" data-end=\"2062\"><strong data-start=\"2023\" data-end=\"2062\">250 mg Zitronenmelissenextrakt 10:1<\/strong><\/li>\n<li data-section-id=\"5uizj\" data-start=\"2063\" data-end=\"2100\"><strong data-start=\"2065\" data-end=\"2100\">100 mg Reishi-Pilz-Extrakt 10:1<\/strong><\/li>\n<li data-section-id=\"1j4n26z\" data-start=\"2101\" data-end=\"2144\"><strong data-start=\"2103\" data-end=\"2144\">100 mg Ashwagandha-Wurzelextrakt 10:1<\/strong><\/li>\n<\/ul>\n<p data-start=\"2146\" data-end=\"2251\">Damit verbindet die Rezeptur Aminos\u00e4uren und Mineralstoffe mit verschiedenen Pflanzen- und Pilzextrakten.<\/p>\n<hr data-start=\"2253\" data-end=\"2256\" \/>\n<h4 data-start=\"2258\" data-end=\"2300\"><span class=\"ez-toc-section\" id=\"Mit_Griffonia_5-HTP_und_L-Tryptophan\"><\/span>Mit Griffonia, 5-HTP und L-Tryptophan<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2302\" data-end=\"2451\">Die Rezeptur enth\u00e4lt au\u00dferdem <strong data-start=\"2332\" data-end=\"2365\">100 mg Griffonia-Samenextrakt<\/strong>, standardisiert auf <strong data-start=\"2386\" data-end=\"2400\">30 % 5-HTP<\/strong>. Dies entspricht <strong data-start=\"2418\" data-end=\"2450\">30 mg 5-HTP pro Tagesportion<\/strong>.<\/p>\n<p data-start=\"2453\" data-end=\"2532\">Erg\u00e4nzt wird die Zusammensetzung durch <strong data-start=\"2492\" data-end=\"2514\">50 mg L-Tryptophan<\/strong> sowie Vitamin B6.<\/p>\n<p data-start=\"2534\" data-end=\"2640\">Vitamin B6 tr\u00e4gt zu einer normalen Funktion des Nervensystems und einer normalen psychischen Funktion bei.<\/p>\n<hr data-start=\"2642\" data-end=\"2645\" \/>\n<h4 data-start=\"2647\" data-end=\"2682\"><span class=\"ez-toc-section\" id=\"Inhaltsstoffe_pro_Tagesportion\"><\/span>Inhaltsstoffe pro Tagesportion<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2684\" data-end=\"2721\"><strong data-start=\"2684\" data-end=\"2721\">Tagesportion: 1 Messl\u00f6ffel (10 g)<\/strong><\/p>\n<div class=\"group TyagGW_tableContainer\">\n<div class=\"TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"2723\" data-end=\"3231\">\n<thead data-start=\"2723\" data-end=\"2764\">\n<tr data-start=\"2723\" data-end=\"2764\">\n<th class=\"last:pe-10\" data-start=\"2723\" data-end=\"2738\" data-col-size=\"sm\">Inhaltsstoff<\/th>\n<th class=\"last:pe-10\" data-start=\"2738\" data-end=\"2757\" data-col-size=\"sm\">Pro Tagesportion<\/th>\n<th class=\"last:pe-10\" data-start=\"2757\" data-end=\"2764\" data-col-size=\"sm\">NRV<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"2781\" data-end=\"3231\">\n<tr data-start=\"2781\" data-end=\"2813\">\n<td data-start=\"2781\" data-end=\"2794\" data-col-size=\"sm\">B6 vitam\u012bns<\/td>\n<td data-start=\"2794\" data-end=\"2804\" data-col-size=\"sm\">1,40 mg<\/td>\n<td data-start=\"2804\" data-end=\"2813\" data-col-size=\"sm\">100 %<\/td>\n<\/tr>\n<tr data-start=\"2814\" data-end=\"2844\">\n<td data-start=\"2814\" data-end=\"2826\" data-col-size=\"sm\">magnijs<\/td>\n<td data-start=\"2826\" data-end=\"2835\" data-col-size=\"sm\">400 mg<\/td>\n<td data-start=\"2835\" data-end=\"2844\" data-col-size=\"sm\">107 %<\/td>\n<\/tr>\n<tr data-start=\"2845\" data-end=\"2869\">\n<td data-start=\"2845\" data-end=\"2852\" data-col-size=\"sm\">cinks<\/td>\n<td data-start=\"2852\" data-end=\"2860\" data-col-size=\"sm\">14 mg<\/td>\n<td data-start=\"2860\" data-end=\"2869\" data-col-size=\"sm\">140 %<\/td>\n<\/tr>\n<tr data-start=\"2870\" data-end=\"2896\">\n<td data-start=\"2870\" data-end=\"2881\" data-col-size=\"sm\">L-Glycin<\/td>\n<td data-start=\"2881\" data-end=\"2891\" data-col-size=\"sm\">3000 mg<\/td>\n<td data-start=\"2891\" data-end=\"2896\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"2897\" data-end=\"2951\">\n<td data-start=\"2897\" data-end=\"2937\" data-col-size=\"sm\">Sauerkirsche aus Montmorency-Kirschen<\/td>\n<td data-start=\"2937\" data-end=\"2946\" data-col-size=\"sm\">500 mg<\/td>\n<td data-start=\"2946\" data-end=\"2951\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"2952\" data-end=\"2998\">\n<td data-start=\"2952\" data-end=\"2984\" data-col-size=\"sm\">L-Theanin aus Gr\u00fcntee-Extrakt<\/td>\n<td data-start=\"2984\" data-end=\"2993\" data-col-size=\"sm\">250 mg<\/td>\n<td data-start=\"2993\" data-end=\"2998\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"2999\" data-end=\"3044\">\n<td data-start=\"2999\" data-end=\"3030\" data-col-size=\"sm\">Zitronenmelissenextrakt 10:1<\/td>\n<td data-start=\"3030\" data-end=\"3039\" data-col-size=\"sm\">250 mg<\/td>\n<td data-start=\"3039\" data-end=\"3044\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"3045\" data-end=\"3086\">\n<td data-start=\"3045\" data-end=\"3072\" data-col-size=\"sm\">Reishi-Pilz-Extrakt 10:1<\/td>\n<td data-start=\"3072\" data-end=\"3081\" data-col-size=\"sm\">100 mg<\/td>\n<td data-start=\"3081\" data-end=\"3086\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"3087\" data-end=\"3134\">\n<td data-start=\"3087\" data-end=\"3120\" data-col-size=\"sm\">Ashwagandha-Wurzelextrakt 10:1<\/td>\n<td data-start=\"3120\" data-end=\"3129\" data-col-size=\"sm\">100 mg<\/td>\n<td data-start=\"3129\" data-end=\"3134\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"3135\" data-end=\"3174\">\n<td data-start=\"3135\" data-end=\"3160\" data-col-size=\"sm\">Griffonia-Samenextrakt<\/td>\n<td data-start=\"3160\" data-end=\"3169\" data-col-size=\"sm\">100 mg<\/td>\n<td data-start=\"3169\" data-end=\"3174\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"3175\" data-end=\"3202\">\n<td data-start=\"3175\" data-end=\"3189\" data-col-size=\"sm\">davon 5-HTP<\/td>\n<td data-start=\"3189\" data-end=\"3197\" data-col-size=\"sm\">30 mg<\/td>\n<td data-start=\"3197\" data-end=\"3202\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<tr data-start=\"3203\" data-end=\"3231\">\n<td data-start=\"3203\" data-end=\"3218\" data-col-size=\"sm\">L-Tryptophan<\/td>\n<td data-start=\"3218\" data-end=\"3226\" data-col-size=\"sm\">50 mg<\/td>\n<td data-start=\"3226\" data-end=\"3231\" data-col-size=\"sm\">\u2013<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<hr data-start=\"3233\" data-end=\"3236\" \/>\n<h4 data-start=\"3238\" data-end=\"3250\"><span class=\"ez-toc-section\" id=\"Zutaten\"><\/span>Sast\u0101vda\u013cas<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3252\" data-end=\"3720\"><strong data-start=\"3252\" data-end=\"3264\">Sast\u0101vda\u013cas:<\/strong> L-Glycin, Magnesiumbisglycinat, Inulin, Maltodextrin, S\u00e4ureregulator: Citronens\u00e4ure; Montmorency-Sauerkirschpulver, Aroma, Zitronenmelissenextrakt (10:1), L-Theanin (aus Gr\u00fcntee-Extrakt <em data-start=\"3451\" data-end=\"3470\">Camellia sinensis<\/em> L.), Trennmittel: Siliciumdioxid; Reishi-Pilzextrakt (10:1), Ashwagandha-Wurzelextrakt (10:1), Griffonia-Samenextrakt (30 %), Farbstoff: Betanin (Betenrot); L-Tryptophan, Zinkbisglycinat, S\u00fc\u00dfungsmittel: Sucralose; Vitamin B6 (Pyridoxinhydrochlorid).<\/p>\n<p data-start=\"3722\" data-end=\"3871\"><strong data-start=\"3722\" data-end=\"3742\">Allergiehinweis:<\/strong> Kann Spuren von <strong data-start=\"3759\" data-end=\"3826\">Milch, Soja, Eiern, Fisch, Sellerie und glutenhaltigem Getreide<\/strong> sowie daraus gewonnenen Produkten enthalten.<\/p>\n<hr data-start=\"3873\" data-end=\"3876\" \/>\n<h4 data-start=\"3878\" data-end=\"3901\"><span class=\"ez-toc-section\" id=\"Einnahmeempfehlung\"><\/span>Ieteicam\u0101 deva<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3903\" data-end=\"4013\"><strong data-start=\"3903\" data-end=\"3926\">1 Messl\u00f6ffel (10 g)<\/strong> ar <strong data-start=\"3931\" data-end=\"3959\">250\u2013500 ml kaltem Wasser<\/strong> mischen, gut umr\u00fchren oder sch\u00fctteln und konsumieren.<\/p>\n<p data-start=\"4015\" data-end=\"4085\"><strong data-start=\"4015\" data-end=\"4085\">T\u00e4glich 1 Portion etwa 30 Minuten vor dem Schlafengehen einnehmen.<\/strong><\/p>\n<hr data-start=\"4087\" data-end=\"4090\" \/>\n<h4 data-start=\"4092\" data-end=\"4114\"><span class=\"ez-toc-section\" id=\"Wichtige_Hinweise\"><\/span>Wichtige Hinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"4116\" data-end=\"4318\">Nicht empfohlen f\u00fcr Personen unter 18 Jahren, Schwangere oder Stillende sowie bei bekannten oder vermuteten Vorerkrankungen und bei Einnahme von verschreibungspflichtigen oder rezeptfreien Medikamenten.<\/p>\n<p data-start=\"4320\" data-end=\"4477\">Dieses Produkt ist kein Ersatz f\u00fcr eine ausgewogene und abwechslungsreiche Ern\u00e4hrung. Eine ausgewogene Ern\u00e4hrung sowie eine gesunde Lebensweise sind wichtig.<\/p>\n<p data-start=\"4479\" data-end=\"4632\">K\u00fchl und trocken sowie au\u00dferhalb der Reichweite von Kindern aufbewahren. Die angegebene empfohlene t\u00e4gliche Verzehrmenge darf nicht \u00fcberschritten werden.<\/p>\n<p data-start=\"4634\" data-end=\"4677\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"4634\" data-end=\"4661\">Mindestens haltbar bis:<\/strong> siehe Aufdruck.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"281\" data-end=\"419\"><em>Agewell 40+ Schlaf Unterst\u00fctzung Beerenmix 300 g mit Glycin, Magnesium, Sauerkirsche, L-Theanin, Ashwagandha, Reishi und L-Tryptophan.<\/em><\/p>","protected":false},"featured_media":63598,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[1648],"product_cat":[1515],"product_tag":[],"class_list":["post-63597","product","type-product","status-publish","has-post-thumbnail","product_brand-applied-nutrition","product_cat-5-htp","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product\/63597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/comments?post=63597"}],"version-history":[{"count":1,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product\/63597\/revisions"}],"predecessor-version":[{"id":63599,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product\/63597\/revisions\/63599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/media\/63598"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/media?parent=63597"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product_brand?post=63597"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product_cat?post=63597"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/lv\/wp-json\/wp\/v2\/product_tag?post=63597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}