{"id":23708,"date":"2025-05-31T12:08:45","date_gmt":"2025-05-31T12:08:45","guid":{"rendered":"https:\/\/honigbee.com\/?post_type=product&#038;p=23708"},"modified":"2026-03-08T18:16:25","modified_gmt":"2026-03-08T18:16:25","slug":"mango-scheiben-ohne-so2-1000g","status":"publish","type":"product","link":"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/","title":{"rendered":"1kg Mango Scheiben ohne SO2 \u2013 Nat\u00fcrlich getrocknete Mango aus Thailand"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Spis tre\u015bci<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Prze\u0142\u0105cznik Spisu Tre\u015bci\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">D\u017awignia kolankowa<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Produktmerkmale\" >Cechy produktu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Geschmack_Konsistenz\" >Smak i konsystencja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Verwendung\" >u\u017cywa\u0107<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Nahrwerte_pro_100_g\" >Warto\u015bci od\u017cywcze (na 100 g)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Produktdetails\" >Szczeg\u00f3\u0142y produktu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Lagerung\" >sk\u0142adowanie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/pl\/produkt\/mango-scheiben-ohne-so2-1000g\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<p data-start=\"771\" data-end=\"967\">Ten <strong data-start=\"775\" data-end=\"808\">1kg Mango Scheiben ohne SO2<\/strong> bestehen aus nat\u00fcrlich getrockneten Mangofr\u00fcchten ohne Zusatz von Schwefeldioxid. Durch die schonende Trocknung bleibt das fruchtige Aroma der Mango erhalten.<\/p>\n<p data-start=\"969\" data-end=\"1065\">Die getrockneten Mango-Scheiben eignen sich als Snack sowie als Zutat in verschiedenen Rezepten.<\/p>\n<hr data-start=\"1067\" data-end=\"1070\" \/>\n<h4 data-start=\"1072\" data-end=\"1092\"><span class=\"ez-toc-section\" id=\"Produktmerkmale\"><\/span>Cechy produktu<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1094\" data-end=\"1260\">1000g Mango Scheiben ohne SO2<br data-start=\"1123\" data-end=\"1126\" \/>Nat\u00fcrlich getrocknete Mango<br data-start=\"1153\" data-end=\"1156\" \/>Ohne Schwefeldioxid (SO2)<br data-start=\"1181\" data-end=\"1184\" \/>Wega\u0144skie i bezglutenowe<br data-start=\"1204\" data-end=\"1207\" \/>Bez dodatk\u00f3w<br data-start=\"1224\" data-end=\"1227\" \/>Opakowanie z mo\u017cliwo\u015bci\u0105 ponownego zamkni\u0119cia<\/p>\n<hr data-start=\"1262\" data-end=\"1265\" \/>\n<h4 data-start=\"1267\" data-end=\"1294\"><span class=\"ez-toc-section\" id=\"Geschmack_Konsistenz\"><\/span>Smak i konsystencja<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1296\" data-end=\"1375\">Fruchtig-s\u00fc\u00dfes Mangoaroma<br data-start=\"1321\" data-end=\"1324\" \/>Weiche, leicht z\u00e4he Textur<br data-start=\"1350\" data-end=\"1353\" \/>Intensive Fruchtnote<\/p>\n<hr data-start=\"1377\" data-end=\"1380\" \/>\n<h4 data-start=\"1382\" data-end=\"1397\"><span class=\"ez-toc-section\" id=\"Verwendung\"><\/span>u\u017cywa\u0107<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1399\" data-end=\"1453\">Ten <strong data-start=\"775\" data-end=\"808\">1kg <\/strong><strong data-start=\"1403\" data-end=\"1436\">Mango Scheiben ohne SO2<\/strong> nadaj\u0105 si\u0119 do:<\/p>\n<p data-start=\"1455\" data-end=\"1545\">\u2022 Snack f\u00fcr unterwegs<br data-start=\"1476\" data-end=\"1479\" \/>\u2022 M\u00fcsli oder Porridge<br data-start=\"1500\" data-end=\"1503\" \/>\u2022 Smoothies<br data-start=\"1514\" data-end=\"1517\" \/>\u2022 Backrezepte<br data-start=\"1530\" data-end=\"1533\" \/>\u2022 Desserts<\/p>\n<hr data-start=\"1547\" data-end=\"1550\" \/>\n<h4 data-start=\"1552\" data-end=\"1578\"><span class=\"ez-toc-section\" id=\"Nahrwerte_pro_100_g\"><\/span>Warto\u015bci od\u017cywcze (na 100 g)<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1580\" data-end=\"1719\">Energie: 360 kcal \/ 1507 kJ<br data-start=\"1607\" data-end=\"1610\" \/>Eiwei\u00df: 1 g<br data-start=\"1621\" data-end=\"1624\" \/>Kohlenhydrate: 89 g<br data-start=\"1643\" data-end=\"1646\" \/>davon Zucker: 42 g<br data-start=\"1664\" data-end=\"1667\" \/>T\u0142uszcz: 0 g<br data-start=\"1676\" data-end=\"1679\" \/>Kwasy t\u0142uszczowe nasycone: 0 g<br data-start=\"1705\" data-end=\"1708\" \/>S\u00f3l: 0 g<\/p>\n<hr data-start=\"1721\" data-end=\"1724\" \/>\n<h4 data-start=\"1726\" data-end=\"1745\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Szczeg\u00f3\u0142y produktu<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1747\" data-end=\"1883\">Produktname: 1kg Mango Scheiben ohne SO2<br data-start=\"1789\" data-end=\"1792\" \/>Inhalt: 1000 g<br data-start=\"1806\" data-end=\"1809\" \/>Pochodzenie: Tajlandia<br data-start=\"1827\" data-end=\"1830\" \/>Verarbeitung: Nat\u00fcrlich getrocknet<br data-start=\"1864\" data-end=\"1867\" \/>Zutaten: Mango<\/p>\n<hr data-start=\"1885\" data-end=\"1888\" \/>\n<h4 data-start=\"1890\" data-end=\"1903\"><span class=\"ez-toc-section\" id=\"Lagerung\"><\/span>sk\u0142adowanie<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1905\" data-end=\"1979\" data-is-last-node=\"\" data-is-only-node=\"\">Trocken, k\u00fchl und lichtgesch\u00fctzt lagern. Nach dem \u00d6ffnen gut verschlie\u00dfen.<\/p>\n<hr data-start=\"1931\" data-end=\"1934\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/pl\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1931\" data-end=\"1934\" \/>\n<p>Produktbilder dienen der Veranschaulichung. Verpackungsdesign kann abweichen.<\/p>","protected":false},"excerpt":{"rendered":"<p data-start=\"557\" data-end=\"688\"><em>Mango Scheiben 1kg ohne SO2, nat\u00fcrlich getrocknet und ohne Schwefeldioxid. Ideal als Snack, f\u00fcr M\u00fcsli, Backrezepte oder Desserts.<\/em><\/p>\n<p data-start=\"456\" data-end=\"506\">","protected":false},"featured_media":43410,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[694],"product_tag":[],"class_list":{"0":"post-23708","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-getrocknete-mango","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple","13":"add-to-wishlist-before_image"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product\/23708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/comments?post=23708"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product\/23708\/revisions"}],"predecessor-version":[{"id":43411,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product\/23708\/revisions\/43411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/media\/43410"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/media?parent=23708"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product_brand?post=23708"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product_cat?post=23708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/pl\/wp-json\/wp\/v2\/product_tag?post=23708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}