{"id":56603,"date":"2026-07-11T16:54:58","date_gmt":"2026-07-11T16:54:58","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/melt-and-pour-soap-base-2kg\/"},"modified":"2026-07-14T16:58:41","modified_gmt":"2026-07-14T16:58:41","slug":"melt-pour-seifenbasis-2-kg-zum-seife-selber-machen","status":"publish","type":"product","link":"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/","title":{"rendered":"Melt &#038; Pour Seifenbasis 2 kg zum Seife selber machen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Melt_Pour_Seifenbasis_2_kg_fur_kreative_DIY-Seifen\" >Melt &amp; Pour Seifenbasis 2 kg f\u00fcr kreative DIY-Seifen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Einfache_Verarbeitung_fur_kreative_Projekte\" >Einfache Verarbeitung f\u00fcr kreative Projekte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Individuell_mit_Duften_und_naturlichen_Zusatzen\" >Individuell mit D\u00fcften und nat\u00fcrlichen Zus\u00e4tzen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Ergiebige_Seifenbasis_fur_zahlreiche_Seifenstucke\" >Ergiebige Seifenbasis f\u00fcr zahlreiche Seifenst\u00fccke<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Perfekt_fur_DIY-Geschenke_und_kreative_Ideen\" >Perfekt f\u00fcr DIY-Geschenke und kreative Ideen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Produktdetails\" >Detalhes do produto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Anwendung\" >Aplicativo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Inhaltsstoffe_INCI\" >Inhaltsstoffe (INCI)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/honigbee.com\/pt\/produto\/melt-pour-seifenbasis-2-kg-zum-seife-selber-machen\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"374\" data-end=\"431\"><span class=\"ez-toc-section\" id=\"Melt_Pour_Seifenbasis_2_kg_fur_kreative_DIY-Seifen\"><\/span>Melt &amp; Pour Seifenbasis 2 kg f\u00fcr kreative DIY-Seifen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"433\" data-end=\"663\">Com o <strong data-start=\"441\" data-end=\"473\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> lassen sich individuelle Seifen ganz einfach selbst herstellen. Die hochwertige Glycerinseife kann geschmolzen und nach Belieben mit D\u00fcften, Farben oder nat\u00fcrlichen Zutaten veredelt werden.<\/p>\n<hr data-start=\"665\" data-end=\"668\" \/>\n<h4 data-start=\"670\" data-end=\"718\"><span class=\"ez-toc-section\" id=\"Einfache_Verarbeitung_fur_kreative_Projekte\"><\/span>Einfache Verarbeitung f\u00fcr kreative Projekte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"720\" data-end=\"915\">O <strong data-start=\"724\" data-end=\"756\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> kann schonend im Wasserbad oder in der Mikrowelle geschmolzen werden. Anschlie\u00dfend l\u00e4sst sie sich problemlos in Seifenformen gie\u00dfen und individuell gestalten.<\/p>\n<hr data-start=\"917\" data-end=\"920\" \/>\n<h4 data-start=\"922\" data-end=\"974\"><span class=\"ez-toc-section\" id=\"Individuell_mit_Duften_und_naturlichen_Zusatzen\"><\/span>Individuell mit D\u00fcften und nat\u00fcrlichen Zus\u00e4tzen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"976\" data-end=\"1179\">Com o <strong data-start=\"984\" data-end=\"1016\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> entstehen einzigartige DIY-Seifen. \u00c4therische \u00d6le, Seifenfarben, Kr\u00e4uter, Bl\u00fcten, Fruchtschalen oder andere dekorative Zutaten lassen sich problemlos einarbeiten.<\/p>\n<hr data-start=\"1181\" data-end=\"1184\" \/>\n<h4 data-start=\"1186\" data-end=\"1240\"><span class=\"ez-toc-section\" id=\"Ergiebige_Seifenbasis_fur_zahlreiche_Seifenstucke\"><\/span>Ergiebige Seifenbasis f\u00fcr zahlreiche Seifenst\u00fccke<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1242\" data-end=\"1435\">O <strong data-start=\"1246\" data-end=\"1278\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> bietet ausreichend Material f\u00fcr viele selbstgemachte Seifen. Sie eignet sich ideal f\u00fcr Hobby-Seifensieder, kreative Bastelprojekte oder kleine Manufakturen.<\/p>\n<hr data-start=\"1437\" data-end=\"1440\" \/>\n<h4 data-start=\"1442\" data-end=\"1491\"><span class=\"ez-toc-section\" id=\"Perfekt_fur_DIY-Geschenke_und_kreative_Ideen\"><\/span>Perfekt f\u00fcr DIY-Geschenke und kreative Ideen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1493\" data-end=\"1704\">O <strong data-start=\"1497\" data-end=\"1529\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> ist ideal f\u00fcr alle, die individuelle Seifen herstellen m\u00f6chten. Ob f\u00fcr den Eigengebrauch, als Geschenk oder f\u00fcr kreative Workshops \u2013 Ihrer Fantasie sind kaum Grenzen gesetzt.<\/p>\n<hr data-start=\"1706\" data-end=\"1709\" \/>\n<h4 data-start=\"1711\" data-end=\"1730\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Detalhes do produto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"1732\" data-end=\"2043\">\n<li data-section-id=\"1wvxi8u\" data-start=\"1732\" data-end=\"1757\">Melt &amp; Pour Seifenbasis<\/li>\n<li data-section-id=\"19jjna2\" data-start=\"1758\" data-end=\"1772\">Inhalt: 2 kg<\/li>\n<li data-section-id=\"6q4caw\" data-start=\"1773\" data-end=\"1824\">Zum Schmelzen im Wasserbad oder in der Mikrowelle<\/li>\n<li data-section-id=\"14o0j5l\" data-start=\"1825\" data-end=\"1852\">F\u00fcr selbstgemachte Seifen<\/li>\n<li data-section-id=\"1j8l5bf\" data-start=\"1853\" data-end=\"1913\">Mit Duft\u00f6len, Farben und nat\u00fcrlichen Zus\u00e4tzen kombinierbar<\/li>\n<li data-section-id=\"1h7fgar\" data-start=\"1914\" data-end=\"1929\">Glycerinbasis<\/li>\n<li data-section-id=\"1l9e8vl\" data-start=\"1930\" data-end=\"1943\">Mit Kokos\u00f6l<\/li>\n<li data-section-id=\"1vmemj7\" data-start=\"1944\" data-end=\"1968\">F\u00fcr DIY-Seifenprojekte<\/li>\n<li data-section-id=\"qqtmu5\" data-start=\"1969\" data-end=\"2008\">Hergestellt im Vereinigten K\u00f6nigreich<\/li>\n<li data-section-id=\"c6kzbc\" data-start=\"2009\" data-end=\"2043\">Herkunft: Vereinigtes K\u00f6nigreich<\/li>\n<\/ul>\n<hr data-start=\"2045\" data-end=\"2048\" \/>\n<h4 data-start=\"2050\" data-end=\"2064\"><span class=\"ez-toc-section\" id=\"Anwendung\"><\/span>Aplicativo<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2066\" data-end=\"2278\">O <strong data-start=\"2070\" data-end=\"2102\">Melt &amp; Pour Seifenbasis 2 kg<\/strong> im Wasserbad oder vorsichtig in der Mikrowelle schmelzen. Anschlie\u00dfend Duft\u00f6le, Farben oder weitere Zutaten hinzuf\u00fcgen, in Seifenformen f\u00fcllen und vollst\u00e4ndig abk\u00fchlen lassen.<\/p>\n<hr data-start=\"2280\" data-end=\"2283\" \/>\n<h4 data-start=\"2285\" data-end=\"2310\"><span class=\"ez-toc-section\" id=\"Inhaltsstoffe_INCI\"><\/span>Inhaltsstoffe (INCI)<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2312\" data-end=\"2593\" data-is-last-node=\"\" data-is-only-node=\"\">Aqua, Glycerin, Sorbitol, Sodium Stearate, Sodium Laurate, Propylene Glycol, Sodium Oleate, Sodium Myristate, Sodium Chloride, Cocos Nucifera (Coconut) Oil, Glyceryl Laurate, Cocamidopropyl Betaine, Citric Acid, Sodium Citrate, Tetrasodium Iminodisuccinate, Tetrasodium Etidronate.<\/p>\n<hr data-start=\"1683\" data-end=\"1686\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/pt\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><em>Die Melt &amp; Pour Seifenbasis 2 kg eignet sich ideal zum Seife selber machen. Einfach schmelzen und mit Duft\u00f6len, Farben, Bl\u00fcten oder Kr\u00e4utern zu individuellen DIY-Seifen gestalten.<\/em><\/p>","protected":false},"featured_media":56602,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1621],"product_tag":[],"class_list":["post-56603","product","type-product","status-publish","has-post-thumbnail","product_cat-seife-selber-machen","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/56603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/comments?post=56603"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/56603\/revisions"}],"predecessor-version":[{"id":57853,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/56603\/revisions\/57853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media\/56602"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media?parent=56603"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_brand?post=56603"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_cat?post=56603"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_tag?post=56603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}