{"id":61973,"date":"2026-08-14T09:46:06","date_gmt":"2026-08-14T09:46:06","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/spruce-50ml-essential-oil\/"},"modified":"2026-08-31T16:36:37","modified_gmt":"2026-08-31T16:36:37","slug":"fichtenoel-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/","title":{"rendered":"Fichten\u00f6l \u00e4therisches \u00d6l 50 ml aus den USA f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Fichtenol_atherisches_Ol_50_ml\" >Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Durch_Wasserdampfdestillation_gewonnen\" >Durch Wasserdampfdestillation gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Frischer_und_waldiger_Duft\" >Frischer und waldiger Duft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_Raumduft\" >F\u00fcr Aromatherapie und Raumduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Beliebter_Duft_fur_Seifen_und_Raumdufte\" >Beliebter Duft f\u00fcr Seifen und Raumd\u00fcfte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/pt\/produto\/fichtenoel-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-10\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-10\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-10\" data-testid=\"conversation-turn-32\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"679d98f5-cc67-4f72-ae21-d5b612468266\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"381\" data-end=\"416\"><span class=\"ez-toc-section\" id=\"Fichtenol_atherisches_Ol_50_ml\"><\/span>Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"418\" data-end=\"628\">Das <strong data-start=\"422\" data-end=\"456\">Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Nadeln und Zweigen von <em data-start=\"493\" data-end=\"511\">Tsuga canadensis<\/em> gewonnen. Das \u00e4therische \u00d6l besitzt einen charakteristisch <strong data-start=\"571\" data-end=\"627\">frischen, waldigen, erdigen und leicht harzigen Duft<\/strong>.<\/p>\n<p data-start=\"630\" data-end=\"715\">Das f\u00fcr dieses \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus den <strong data-start=\"707\" data-end=\"714\">USA<\/strong>.<\/p>\n<hr data-start=\"717\" data-end=\"720\" \/>\n<h4 data-start=\"722\" data-end=\"765\"><span class=\"ez-toc-section\" id=\"Durch_Wasserdampfdestillation_gewonnen\"><\/span>Durch Wasserdampfdestillation gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"767\" data-end=\"899\">F\u00fcr die Herstellung des <strong data-start=\"791\" data-end=\"825\">Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<\/strong> werden Nadeln und Zweige mittels <strong data-start=\"859\" data-end=\"886\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"901\" data-end=\"1036\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile des Pflanzenmaterials gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1038\" data-end=\"1041\" \/>\n<h4 data-start=\"1043\" data-end=\"1074\"><span class=\"ez-toc-section\" id=\"Frischer_und_waldiger_Duft\"><\/span>Frischer und waldiger Duft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1076\" data-end=\"1194\">Das \u00d6l besitzt ein ausgepr\u00e4gt <strong data-start=\"1106\" data-end=\"1156\">waldiges, gr\u00fcnes und erdig-harziges Duftprofil<\/strong>, das an frische Nadelw\u00e4lder erinnert.<\/p>\n<p data-start=\"1196\" data-end=\"1363\">Sein nat\u00fcrlicher Waldduft eignet sich hervorragend f\u00fcr Raumduftmischungen und l\u00e4sst sich besonders gut mit anderen Nadel-, Holz-, Kr\u00e4uter- und Zitrusnoten kombinieren.<\/p>\n<hr data-start=\"1365\" data-end=\"1368\" \/>\n<h4 data-start=\"1370\" data-end=\"1405\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_Raumduft\"><\/span>F\u00fcr Aromatherapie und Raumduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1407\" data-end=\"1529\">Das <strong data-start=\"1411\" data-end=\"1445\">Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser, Duftlampen und weitere aromatische Anwendungen.<\/p>\n<p data-start=\"1531\" data-end=\"1779\">In der Aromatherapie wird der frische Waldduft traditionell mit einer <strong data-start=\"1601\" data-end=\"1666\">ruhigen, ausgleichenden und zugleich erfrischenden Atmosph\u00e4re<\/strong> verbunden. Das macht ihn zu einer sch\u00f6nen Wahl f\u00fcr entspannte Momente und eine nat\u00fcrlich wirkende Raumbeduftung.<\/p>\n<hr data-start=\"1781\" data-end=\"1784\" \/>\n<h4 data-start=\"1786\" data-end=\"1830\"><span class=\"ez-toc-section\" id=\"Beliebter_Duft_fur_Seifen_und_Raumdufte\"><\/span>Beliebter Duft f\u00fcr Seifen und Raumd\u00fcfte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1832\" data-end=\"2007\">Aufgrund seines charakteristischen frischen Waldaromas wird dieses \u00e4therische \u00d6l auch als Duftkomponente f\u00fcr <strong data-start=\"1941\" data-end=\"1996\">Seifen, Raumd\u00fcfte und andere aromatische Rezepturen<\/strong> verwendet.<\/p>\n<p data-start=\"2009\" data-end=\"2149\">Besonders in Kombination mit Zitrus- oder weiteren Nadelholznoten lassen sich frische, klare und naturverbundene Duftkompositionen kreieren.<\/p>\n<hr data-start=\"2151\" data-end=\"2154\" \/>\n<h4 data-start=\"2156\" data-end=\"2175\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2177\" data-end=\"2654\">\n<li data-section-id=\"gpfiyu\" data-start=\"2177\" data-end=\"2222\"><strong data-start=\"2179\" data-end=\"2191\">Produkt:<\/strong> Fichten\u00f6l \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"1h5i1mp\" data-start=\"2223\" data-end=\"2287\"><strong data-start=\"2225\" data-end=\"2268\">Botanische Bezeichnung laut Hersteller:<\/strong> <em data-start=\"2269\" data-end=\"2287\">Tsuga canadensis<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2288\" data-end=\"2307\"><strong data-start=\"2290\" data-end=\"2301\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"htlbhp\" data-start=\"2308\" data-end=\"2357\"><strong data-start=\"2310\" data-end=\"2339\">Verwendeter Pflanzenteil:<\/strong> Nadeln und Zweige<\/li>\n<li data-section-id=\"ijs6nc\" data-start=\"2358\" data-end=\"2377\"><strong data-start=\"2360\" data-end=\"2373\">Herkunft:<\/strong> USA<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2378\" data-end=\"2418\"><strong data-start=\"2380\" data-end=\"2394\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"u5uuio\" data-start=\"2419\" data-end=\"2483\"><strong data-start=\"2421\" data-end=\"2436\">Duftprofil:<\/strong> Waldig \/ frisch \/ erdig \/ gr\u00fcn \/ leicht harzig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2484\" data-end=\"2535\"><strong data-start=\"2486\" data-end=\"2501\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2536\" data-end=\"2593\"><strong data-start=\"2538\" data-end=\"2571\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2594\" data-end=\"2625\"><strong data-start=\"2596\" data-end=\"2615\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswl5c\" data-start=\"2626\" data-end=\"2654\"><strong data-start=\"2628\" data-end=\"2640\">Barcode:<\/strong> 5055796529926<\/li>\n<\/ul>\n<hr data-start=\"2656\" data-end=\"2659\" \/>\n<h4 data-start=\"2661\" data-end=\"2685\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2687\" data-end=\"2889\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2725\" data-end=\"2789\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"2891\" data-end=\"3128\" data-is-last-node=\"\" data-is-only-node=\"\">Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen. Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"224\" data-end=\"374\"><em>Fichten\u00f6l \u00e4therisches \u00d6l 50 ml aus den USA, durch Wasserdampfdestillation aus Nadeln und Zweigen gewonnen. Frisch-waldiger Duft f\u00fcr Aromatherapie.<\/em><\/p>","protected":false},"featured_media":61967,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61973","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/61973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/comments?post=61973"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/61973\/revisions"}],"predecessor-version":[{"id":63648,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/61973\/revisions\/63648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media\/61967"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media?parent=61973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_brand?post=61973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_cat?post=61973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_tag?post=61973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}