{"id":62023,"date":"2026-08-14T09:46:54","date_gmt":"2026-08-14T09:46:54","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/bay-leaf-50ml-essential-oil\/"},"modified":"2026-09-02T14:51:56","modified_gmt":"2026-09-02T14:51:56","slug":"westindischer-lorbeer-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/","title":{"rendered":"Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml aus der Karibik f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Westindischer_Lorbeer_atherisches_Ol_50_ml\" >Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Aus_den_Blattern_von_Pimenta_racemosa_dampfdestilliert\" >Aus den Bl\u00e4ttern von Pimenta racemosa dampfdestilliert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Warm_wurzig_und_aromatisch\" >Warm, w\u00fcrzig und aromatisch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#West_Indian_Bay_%E2%80%93_nicht_mit_echtem_Lorbeer_verwechseln\" >West Indian Bay \u2013 nicht mit echtem Lorbeer verwechseln<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_wurzige_Raumdufte\" >F\u00fcr Aromatherapie und w\u00fcrzige Raumd\u00fcfte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Tradition_in_der_Karibik\" >Tradition in der Karibik<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Produktdetails\" >Detalhes do produto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/pt\/produto\/westindischer-lorbeer-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Instru\u00e7\u00f5es de seguran\u00e7a<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"427\" data-end=\"474\"><span class=\"ez-toc-section\" id=\"Westindischer_Lorbeer_atherisches_Ol_50_ml\"><\/span>Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"476\" data-end=\"739\">O <strong data-start=\"480\" data-end=\"526\">Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<\/strong> wird aus den Bl\u00e4ttern von <em data-start=\"553\" data-end=\"571\">Pimenta racemosa<\/em> gewonnen. Die auch als <strong data-start=\"595\" data-end=\"614\">West Indian Bay<\/strong> bekannte Pflanze ist in der Karibik beheimatet und wird dort traditionell als aromatische Duft- und Gew\u00fcrzpflanze gesch\u00e4tzt.<\/p>\n<p data-start=\"741\" data-end=\"892\">Das \u00e4therische \u00d6l besitzt einen charakteristischen <strong data-start=\"792\" data-end=\"834\">warmen, w\u00fcrzigen und aromatischen Duft<\/strong> mit frischen, leicht s\u00fc\u00dflichen und nelkenartigen Nuancen.<\/p>\n<hr data-start=\"894\" data-end=\"897\" \/>\n<h4 data-start=\"899\" data-end=\"958\"><span class=\"ez-toc-section\" id=\"Aus_den_Blattern_von_Pimenta_racemosa_dampfdestilliert\"><\/span>Aus den Bl\u00e4ttern von Pimenta racemosa dampfdestilliert<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"960\" data-end=\"1111\">F\u00fcr die Herstellung des <strong data-start=\"984\" data-end=\"1030\">Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<\/strong> werden die aromatischen Bl\u00e4tter mittels <strong data-start=\"1071\" data-end=\"1098\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"1113\" data-end=\"1318\">Dabei werden die fl\u00fcchtigen Duftbestandteile der Bl\u00e4tter gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen. Aufgrund seines kr\u00e4ftigen Aromas sollte das \u00d6l in Duftmischungen sparsam dosiert werden.<\/p>\n<hr data-start=\"1320\" data-end=\"1323\" \/>\n<h4 data-start=\"1325\" data-end=\"1357\"><span class=\"ez-toc-section\" id=\"Warm_wurzig_und_aromatisch\"><\/span>Warm, w\u00fcrzig und aromatisch<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1359\" data-end=\"1504\">Westindisches Lorbeer\u00f6l besitzt ein deutlich <strong data-start=\"1404\" data-end=\"1449\">w\u00fcrziges, warmes und krautiges Duftprofil<\/strong> mit charakteristischen s\u00fc\u00dflich-nelkenartigen Akzenten.<\/p>\n<p data-start=\"1506\" data-end=\"1743\">Das intensive Aroma eignet sich besonders f\u00fcr w\u00fcrzige, holzige und exotisch inspirierte Duftkompositionen. Es l\u00e4sst sich beispielsweise mit <strong data-start=\"1646\" data-end=\"1730\">Bergamotte, Orange, Limette, Schwarzem Pfeffer, Ingwer, Zedernholz und Patchouli<\/strong> combinar.<\/p>\n<hr data-start=\"1745\" data-end=\"1748\" \/>\n<h4 data-start=\"1750\" data-end=\"1809\"><span class=\"ez-toc-section\" id=\"West_Indian_Bay_%E2%80%93_nicht_mit_echtem_Lorbeer_verwechseln\"><\/span>West Indian Bay \u2013 nicht mit echtem Lorbeer verwechseln<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1811\" data-end=\"2000\">Obwohl <em data-start=\"1818\" data-end=\"1836\">Pimenta racemosa<\/em> h\u00e4ufig als <strong data-start=\"1848\" data-end=\"1905\">Westindischer Lorbeer beziehungsweise West Indian Bay<\/strong> bezeichnet wird, handelt es sich botanisch <strong data-start=\"1949\" data-end=\"1999\">nicht um den Echten Lorbeer (<em data-start=\"1980\" data-end=\"1996\">Laurus nobilis<\/em>)<\/strong>.<\/p>\n<p data-start=\"2002\" data-end=\"2216\"><em data-start=\"2002\" data-end=\"2020\">Pimenta racemosa<\/em> geh\u00f6rt zur Familie der Myrtengew\u00e4chse und besitzt ein deutlich anderes Duftprofil. Die botanische Bezeichnung ist deshalb besonders wichtig, um beide \u00e4therischen \u00d6le voneinander zu unterscheiden.<\/p>\n<hr data-start=\"2218\" data-end=\"2221\" \/>\n<h4 data-start=\"2223\" data-end=\"2267\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_wurzige_Raumdufte\"><\/span>F\u00fcr Aromatherapie und w\u00fcrzige Raumd\u00fcfte<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2269\" data-end=\"2412\">O <strong data-start=\"2273\" data-end=\"2319\">Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen sowie f\u00fcr individuelle Aromakompositionen.<\/p>\n<p data-start=\"2414\" data-end=\"2630\">Sein kr\u00e4ftiger, warmer Duft passt besonders zu <strong data-start=\"2461\" data-end=\"2537\">w\u00fcrzigen, maskulinen, holzigen und karibisch inspirierten Duftmischungen<\/strong> und kann bereits in geringer Dosierung eine deutlich wahrnehmbare aromatische Note erzeugen.<\/p>\n<hr data-start=\"2632\" data-end=\"2635\" \/>\n<h4 data-start=\"2637\" data-end=\"2666\"><span class=\"ez-toc-section\" id=\"Tradition_in_der_Karibik\"><\/span>Tradition in der Karibik<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2668\" data-end=\"2918\"><em data-start=\"2668\" data-end=\"2686\">Pimenta racemosa<\/em> besitzt eine lange Verwendungsgeschichte in der Karibik. Besonders bekannt ist die Pflanze als charakteristischer Bestandteil traditioneller <strong data-start=\"2828\" data-end=\"2864\">Bay-Rum-Duft- und Pflegeprodukte<\/strong>, die f\u00fcr ihr warmes, w\u00fcrziges Aroma gesch\u00e4tzt werden.<\/p>\n<p data-start=\"2920\" data-end=\"3208\">Auch die Verwendung in traditionellen Haar- und K\u00f6rperpflegezubereitungen hat eine lange Geschichte. Aussagen \u00fcber Haarwachstum, Durchblutung, rheumatische Beschwerden oder das Immunsystem sind jedoch nicht als wissenschaftlich nachgewiesene Wirkungen dieses \u00e4therischen \u00d6ls zu verstehen.<\/p>\n<hr data-start=\"3210\" data-end=\"3213\" \/>\n<h4 data-start=\"3215\" data-end=\"3234\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Detalhes do produto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"3236\" data-end=\"3807\">\n<li data-section-id=\"1r7chiu\" data-start=\"3236\" data-end=\"3293\"><strong data-start=\"3238\" data-end=\"3250\">Produto:<\/strong> Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"16fw1ml\" data-start=\"3294\" data-end=\"3349\"><strong data-start=\"3296\" data-end=\"3322\">Weitere Bezeichnungen:<\/strong> West Indian Bay \/ Bay Leaf<\/li>\n<li data-section-id=\"9246ax\" data-start=\"3350\" data-end=\"3386\"><strong data-start=\"3352\" data-end=\"3364\">Plantar:<\/strong> Westindischer Lorbeer<\/li>\n<li data-section-id=\"7yeb9z\" data-start=\"3387\" data-end=\"3435\"><strong data-start=\"3389\" data-end=\"3416\">Botanische Bezeichnung:<\/strong> <em data-start=\"3417\" data-end=\"3435\">Pimenta racemosa<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"3436\" data-end=\"3455\"><strong data-start=\"3438\" data-end=\"3449\">Conte\u00fado:<\/strong> 50 ml<\/li>\n<li data-section-id=\"ai3jk0\" data-start=\"3456\" data-end=\"3495\"><strong data-start=\"3458\" data-end=\"3487\">Verwendeter Pflanzenteil:<\/strong> Bl\u00e4tter<\/li>\n<li data-section-id=\"1co3jge\" data-start=\"3496\" data-end=\"3519\"><strong data-start=\"3498\" data-end=\"3511\">Origem:<\/strong> Karibik<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"3520\" data-end=\"3560\"><strong data-start=\"3522\" data-end=\"3536\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"1g926co\" data-start=\"3561\" data-end=\"3636\"><strong data-start=\"3563\" data-end=\"3578\">Perfil da fragr\u00e2ncia:<\/strong> Warm \/ w\u00fcrzig \/ aromatisch \/ krautig \/ leicht nelkenartig<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"3637\" data-end=\"3688\"><strong data-start=\"3639\" data-end=\"3654\">Usar:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3689\" data-end=\"3746\"><strong data-start=\"3691\" data-end=\"3724\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3747\" data-end=\"3778\"><strong data-start=\"3749\" data-end=\"3768\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswl4i\" data-start=\"3779\" data-end=\"3807\"><strong data-start=\"3781\" data-end=\"3793\">Barcode:<\/strong> 5055796529971<\/li>\n<\/ul>\n<hr data-start=\"3809\" data-end=\"3812\" \/>\n<h4 data-start=\"3814\" data-end=\"3838\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Instru\u00e7\u00f5es de seguran\u00e7a<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3840\" data-end=\"4044\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"3878\" data-end=\"3942\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Aufgrund des kr\u00e4ftigen Charakters von West Indian Bay sollte das \u00d6l besonders sparsam dosiert werden.<\/p>\n<p data-start=\"4046\" data-end=\"4309\">F\u00fcr kosmetische oder k\u00f6rpernahe Anwendungen ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vor der ersten Anwendung einen Vertr\u00e4glichkeitstest durchf\u00fchren. Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"4311\" data-end=\"4459\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"263\" data-end=\"420\"><em>Westindischer Lorbeer \u00e4therisches \u00d6l 50 ml aus der Karibik, aus den Bl\u00e4ttern von Pimenta racemosa dampfdestilliert. Warm-w\u00fcrziger Duft f\u00fcr Aromatherapie.<\/em><\/p>","protected":false},"featured_media":62017,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62023","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/62023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/comments?post=62023"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/62023\/revisions"}],"predecessor-version":[{"id":63708,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product\/62023\/revisions\/63708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media\/62017"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/media?parent=62023"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_brand?post=62023"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_cat?post=62023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/pt\/wp-json\/wp\/v2\/product_tag?post=62023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}