{"id":61744,"date":"2026-08-10T20:07:25","date_gmt":"2026-08-10T20:07:25","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/smudge-stick-white-sage-cedar-10cm\/"},"modified":"2026-08-25T15:29:17","modified_gmt":"2026-08-25T15:29:17","slug":"weisser-salbei-zeder-raeucherbuendel-10-cm","status":"publish","type":"product","link":"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/","title":{"rendered":"Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel 10 cm Smudge Stick Meditation R\u00e4ucherwerk"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Weiser_Salbei_und_Zeder_zum_Rauchern\" >Wei\u00dfer Salbei und Zeder zum R\u00e4uchern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Fur_Meditation_und_spirituelle_Rituale\" >F\u00fcr Meditation und spirituelle Rituale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Kompakter_Smudge_Stick_mit_10_cm_Lange\" >Kompakter Smudge Stick mit 10 cm L\u00e4nge<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Fur_Zuhause_Meditation_und_Wellness\" >F\u00fcr Zuhause, Meditation und Wellness<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Anwendung\" >Anwendung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Hinweis\" >Hinweis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/ro\/produs\/weisser-salbei-zeder-raeucherbuendel-10-cm\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-8\" data-testid=\"conversation-turn-28\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"aa1fa52c-da71-4af3-8f49-62e2252359cb\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"397\" data-end=\"438\"><span class=\"ez-toc-section\" id=\"Weiser_Salbei_und_Zeder_zum_Rauchern\"><\/span>Wei\u00dfer Salbei und Zeder zum R\u00e4uchern<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"440\" data-end=\"660\">Das <strong data-start=\"444\" data-end=\"481\">Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/strong> kombiniert wei\u00dfen Salbei mit Zeder zu einem besonderen Smudge Stick. Die Pflanzenkombination eignet sich f\u00fcr pers\u00f6nliche R\u00e4ucherrituale, Meditation und bewusste Momente der Ruhe.<\/p>\n<hr data-start=\"662\" data-end=\"665\" \/>\n<h4 data-start=\"667\" data-end=\"710\"><span class=\"ez-toc-section\" id=\"Fur_Meditation_und_spirituelle_Rituale\"><\/span>F\u00fcr Meditation und spirituelle Rituale<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"712\" data-end=\"942\">Wei\u00dfer Salbei und Zeder werden traditionell bei verschiedenen R\u00e4ucherpraktiken eingesetzt. Das <strong data-start=\"807\" data-end=\"844\">Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/strong> eignet sich als Begleiter f\u00fcr Meditation, Gebet, Achtsamkeit und pers\u00f6nliche spirituelle Rituale.<\/p>\n<hr data-start=\"944\" data-end=\"947\" \/>\n<h4 data-start=\"949\" data-end=\"992\"><span class=\"ez-toc-section\" id=\"Kompakter_Smudge_Stick_mit_10_cm_Lange\"><\/span>Kompakter Smudge Stick mit 10 cm L\u00e4nge<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"994\" data-end=\"1263\">Mit einer L\u00e4nge von <strong data-start=\"1014\" data-end=\"1023\">10 cm<\/strong> und einem Durchmesser von etwa <strong data-start=\"1055\" data-end=\"1063\">3 cm<\/strong> besitzt das <strong data-start=\"1076\" data-end=\"1113\">Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/strong> eine kompakte und handliche Gr\u00f6\u00dfe. Das gebundene Pflanzenmaterial l\u00e4sst sich einfach verwenden und kann je nach Anwendung mehrfach angez\u00fcndet werden.<\/p>\n<hr data-start=\"1265\" data-end=\"1268\" \/>\n<h4 data-start=\"1270\" data-end=\"1311\"><span class=\"ez-toc-section\" id=\"Fur_Zuhause_Meditation_und_Wellness\"><\/span>F\u00fcr Zuhause, Meditation und Wellness<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1313\" data-end=\"1579\">Ob f\u00fcr die pers\u00f6nliche R\u00e4ucherroutine, Meditation oder bewusste Auszeiten \u2013 das <strong data-start=\"1393\" data-end=\"1430\">Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/strong> ist vielseitig einsetzbar. Die Kombination aus wei\u00dfem Salbei und Zeder macht es auch zu einer besonderen Geschenkidee f\u00fcr Liebhaber von R\u00e4ucherwerk.<\/p>\n<hr data-start=\"1581\" data-end=\"1584\" \/>\n<h4 data-start=\"1586\" data-end=\"1605\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"1607\" data-end=\"1932\">\n<li data-section-id=\"sj8g4c\" data-start=\"1607\" data-end=\"1655\"><strong data-start=\"1609\" data-end=\"1621\">Produkt:<\/strong> Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/li>\n<li data-section-id=\"147n1k0\" data-start=\"1656\" data-end=\"1690\"><strong data-start=\"1658\" data-end=\"1671\">Variante:<\/strong> White Sage &amp; Cedar<\/li>\n<li data-section-id=\"1t23ohf\" data-start=\"1691\" data-end=\"1730\"><strong data-start=\"1693\" data-end=\"1701\">Art:<\/strong> Smudge Stick \/ R\u00e4ucherb\u00fcndel<\/li>\n<li data-section-id=\"1vkdkwp\" data-start=\"1731\" data-end=\"1749\"><strong data-start=\"1733\" data-end=\"1743\">L\u00e4nge:<\/strong> 10 cm<\/li>\n<li data-section-id=\"g9ar5g\" data-start=\"1750\" data-end=\"1777\"><strong data-start=\"1752\" data-end=\"1768\">Durchmesser:<\/strong> ca. 3 cm<\/li>\n<li data-section-id=\"4c9sin\" data-start=\"1778\" data-end=\"1801\"><strong data-start=\"1780\" data-end=\"1792\">Gewicht:<\/strong> ca. 27 g<\/li>\n<li data-section-id=\"1m1a8un\" data-start=\"1802\" data-end=\"1840\"><strong data-start=\"1804\" data-end=\"1833\">Material laut Hersteller:<\/strong> Salbei<\/li>\n<li data-section-id=\"12q7py3\" data-start=\"1841\" data-end=\"1903\"><strong data-start=\"1843\" data-end=\"1858\">Verwendung:<\/strong> R\u00e4uchern, Meditation und spirituelle Rituale<\/li>\n<li data-section-id=\"1uw1rps\" data-start=\"1904\" data-end=\"1932\"><strong data-start=\"1906\" data-end=\"1918\">Barcode:<\/strong> 5056422951364<\/li>\n<\/ul>\n<hr data-start=\"1934\" data-end=\"1937\" \/>\n<h4 data-start=\"1939\" data-end=\"1953\"><span class=\"ez-toc-section\" id=\"Anwendung\"><\/span>Anwendung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1955\" data-end=\"2264\">Das Ende des <strong data-start=\"1968\" data-end=\"2005\">Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel<\/strong> vorsichtig anz\u00fcnden und kurz brennen lassen. Anschlie\u00dfend die Flamme ausblasen und das B\u00fcndel langsam glimmen lassen. Eine feuerfeste Schale zum Auffangen der Asche verwenden. Nach der Anwendung vollst\u00e4ndig l\u00f6schen und niemals unbeaufsichtigt brennen lassen.<\/p>\n<hr data-start=\"2266\" data-end=\"2269\" \/>\n<h4 data-start=\"2271\" data-end=\"2283\"><span class=\"ez-toc-section\" id=\"Hinweis\"><\/span>Hinweis<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2285\" data-end=\"2450\" data-is-last-node=\"\" data-is-only-node=\"\">Die beschriebenen spirituellen und energetischen Verwendungen beruhen auf traditionellen \u00dcberlieferungen und Praktiken. Sie sind wissenschaftlich nicht nachgewiesen.<\/p>\n<hr data-start=\"1683\" data-end=\"1686\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Das Wei\u00dfer Salbei Zeder R\u00e4ucherb\u00fcndel mit 10 cm kombiniert wei\u00dfen Salbei und Zeder. Ideal f\u00fcr R\u00e4ucherrituale, Meditation und eine besondere Raumatmosph\u00e4re.<\/em><\/p>","protected":false},"featured_media":61742,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1650],"product_tag":[],"class_list":["post-61744","product","type-product","status-publish","has-post-thumbnail","product_cat-raeucherwerk","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/comments?post=61744"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61744\/revisions"}],"predecessor-version":[{"id":63459,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61744\/revisions\/63459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/media\/61742"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/media?parent=61744"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_brand?post=61744"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_cat?post=61744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_tag?post=61744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}