{"id":61944,"date":"2026-08-14T09:45:44","date_gmt":"2026-08-14T09:45:44","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/myrrh-50ml-essential-oil\/"},"modified":"2026-09-02T14:50:54","modified_gmt":"2026-09-02T14:50:54","slug":"myrrhe-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/","title":{"rendered":"Myrrhe \u00e4therisches \u00d6l 50 ml aus Somalia \u2013 Myrrhen\u00f6l f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Myrrhe_atherisches_Ol_50_ml\" >Myrrhe \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Aus_naturlichem_Myrrhenharz_dampfdestilliert\" >Aus nat\u00fcrlichem Myrrhenharz dampfdestilliert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Warm_harzig_und_balsamisch\" >Warm, harzig und balsamisch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Fur_Meditation_und_warme_Duftatmospharen\" >F\u00fcr Meditation und warme Duftatmosph\u00e4ren<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Jahrtausendealte_Duft-_und_Rauchertradition\" >Jahrtausendealte Duft- und R\u00e4uchertradition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Kostbares_atherisches_Ol_aus_Somalia\" >Kostbares \u00e4therisches \u00d6l aus Somalia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/ro\/produs\/myrrhe-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-7\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-7\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-7\" data-testid=\"conversation-turn-26\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"f5069288-a350-4a6b-9d75-8ab8536d8a2d\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"390\" data-end=\"422\"><span class=\"ez-toc-section\" id=\"Myrrhe_atherisches_Ol_50_ml\"><\/span>Myrrhe \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"424\" data-end=\"691\">Das <strong data-start=\"428\" data-end=\"459\">Myrrhe \u00e4therisches \u00d6l 50 ml<\/strong> wird aus dem aromatischen Harz von <em data-start=\"495\" data-end=\"514\">Commiphora myrrha<\/em> gewonnen. Myrrhe geh\u00f6rt zu den \u00e4ltesten bekannten Duftstoffen und wird seit Jahrtausenden wegen ihres charakteristischen <strong data-start=\"636\" data-end=\"680\">warmen, harzigen und balsamischen Aromas<\/strong> gesch\u00e4tzt.<\/p>\n<p data-start=\"693\" data-end=\"852\">Das f\u00fcr dieses \u00e4therische \u00d6l verwendete Myrrhenharz stammt laut Hersteller aus <strong data-start=\"772\" data-end=\"783\">Somalia<\/strong>, einer der traditionellen Herkunftsregionen von <em data-start=\"832\" data-end=\"851\">Commiphora myrrha<\/em>.<\/p>\n<hr data-start=\"854\" data-end=\"857\" \/>\n<h4 data-start=\"859\" data-end=\"908\"><span class=\"ez-toc-section\" id=\"Aus_naturlichem_Myrrhenharz_dampfdestilliert\"><\/span>Aus nat\u00fcrlichem Myrrhenharz dampfdestilliert<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"910\" data-end=\"1028\">F\u00fcr die Herstellung des <strong data-start=\"934\" data-end=\"965\">Myrrhe \u00e4therisches \u00d6l 50 ml<\/strong> wird das Harz mittels <strong data-start=\"988\" data-end=\"1015\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"1030\" data-end=\"1291\">Das Harz entsteht nat\u00fcrlicherweise beziehungsweise nach Verletzung der Rinde des Myrrhenbaums und h\u00e4rtet nach dem Austreten aus. Durch die Destillation werden seine fl\u00fcchtigen aromatischen Bestandteile gewonnen und als konzentriertes \u00e4therisches \u00d6l aufgefangen.<\/p>\n<hr data-start=\"1293\" data-end=\"1296\" \/>\n<h4 data-start=\"1298\" data-end=\"1330\"><span class=\"ez-toc-section\" id=\"Warm_harzig_und_balsamisch\"><\/span>Warm, harzig und balsamisch<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1332\" data-end=\"1485\">Myrrhen\u00f6l besitzt ein unverwechselbares <strong data-start=\"1372\" data-end=\"1440\">warmes, trocken-harziges, balsamisches und leicht w\u00fcrziges Aroma<\/strong> mit erdigen und teilweise rauchigen Nuancen.<\/p>\n<p data-start=\"1487\" data-end=\"1751\">Als tiefe Basisnote eignet es sich hervorragend f\u00fcr orientalische, holzige und harzige Duftkompositionen. Besonders harmonisch l\u00e4sst sich Myrrhe mit <strong data-start=\"1636\" data-end=\"1738\">Weihrauch, Orange, Bergamotte, Patchouli, Zedernholz, Sandelholznoten und verschiedenen Gew\u00fcrz\u00f6len<\/strong> kombinieren.<\/p>\n<hr data-start=\"1753\" data-end=\"1756\" \/>\n<h4 data-start=\"1758\" data-end=\"1803\"><span class=\"ez-toc-section\" id=\"Fur_Meditation_und_warme_Duftatmospharen\"><\/span>F\u00fcr Meditation und warme Duftatmosph\u00e4ren<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1805\" data-end=\"1933\">Das <strong data-start=\"1809\" data-end=\"1840\">Myrrhe \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen sowie f\u00fcr individuelle Aromakompositionen.<\/p>\n<p data-start=\"1935\" data-end=\"2187\">Sein tiefer Harzduft wird in der Aromatherapie traditionell mit einer <strong data-start=\"2005\" data-end=\"2053\">ruhigen, erdenden und meditativen Atmosph\u00e4re<\/strong> verbunden. Myrrhe eignet sich daher besonders f\u00fcr bewusste Ruhephasen, Meditation sowie warme und orientalisch inspirierte Raumd\u00fcfte.<\/p>\n<hr data-start=\"2189\" data-end=\"2192\" \/>\n<h4 data-start=\"2194\" data-end=\"2242\"><span class=\"ez-toc-section\" id=\"Jahrtausendealte_Duft-_und_Rauchertradition\"><\/span>Jahrtausendealte Duft- und R\u00e4uchertradition<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2244\" data-end=\"2444\">Myrrhe besitzt eine au\u00dfergew\u00f6hnlich lange Kulturgeschichte. Das aromatische Harz wurde bereits in der Antike als <strong data-start=\"2357\" data-end=\"2433\">R\u00e4ucherwerk, Parf\u00fcm und Bestandteil religi\u00f6ser und zeremonieller Rituale<\/strong> verwendet.<\/p>\n<p data-start=\"2446\" data-end=\"2608\">Insbesondere im Nahen Osten und in Nordostafrika geh\u00f6rte Myrrhe gemeinsam mit anderen kostbaren Harzen wie Weihrauch zu den bedeutenden aromatischen Handelswaren.<\/p>\n<p data-start=\"2610\" data-end=\"2751\">Traditionelle medizinische Anwendungen sind jedoch nicht mit wissenschaftlich nachgewiesenen Wirkungen dieses \u00e4therischen \u00d6ls gleichzusetzen.<\/p>\n<hr data-start=\"2753\" data-end=\"2756\" \/>\n<h4 data-start=\"2758\" data-end=\"2799\"><span class=\"ez-toc-section\" id=\"Kostbares_atherisches_Ol_aus_Somalia\"><\/span>Kostbares \u00e4therisches \u00d6l aus Somalia<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2801\" data-end=\"2959\">Die Gewinnung aus nat\u00fcrlichem Harz und die Herkunft des Rohstoffs machen Myrrhen\u00f6l zu einem vergleichsweise <strong data-start=\"2909\" data-end=\"2958\">hochwertigen und kostspieligen \u00e4therischen \u00d6l<\/strong>.<\/p>\n<p data-start=\"2961\" data-end=\"3144\">Sein intensiver Duft bedeutet gleichzeitig, dass f\u00fcr viele Aromamischungen bereits eine geringe Menge ausreicht, um eine deutlich wahrnehmbare warme und harzige Basisnote zu erzeugen.<\/p>\n<hr data-start=\"3146\" data-end=\"3149\" \/>\n<h4 data-start=\"3151\" data-end=\"3170\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"3172\" data-end=\"3685\">\n<li data-section-id=\"fe7sqm\" data-start=\"3172\" data-end=\"3214\"><strong data-start=\"3174\" data-end=\"3186\">Produkt:<\/strong> Myrrhe \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"1bnfv41\" data-start=\"3215\" data-end=\"3236\"><strong data-start=\"3217\" data-end=\"3229\">Pflanze:<\/strong> Myrrhe<\/li>\n<li data-section-id=\"vv9344\" data-start=\"3237\" data-end=\"3286\"><strong data-start=\"3239\" data-end=\"3266\">Botanische Bezeichnung:<\/strong> <em data-start=\"3267\" data-end=\"3286\">Commiphora myrrha<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"3287\" data-end=\"3306\"><strong data-start=\"3289\" data-end=\"3300\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"zbwni4\" data-start=\"3307\" data-end=\"3343\"><strong data-start=\"3309\" data-end=\"3338\">Verwendeter Pflanzenteil:<\/strong> Harz<\/li>\n<li data-section-id=\"1nwzzp7\" data-start=\"3344\" data-end=\"3367\"><strong data-start=\"3346\" data-end=\"3359\">Herkunft:<\/strong> Somalia<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"3368\" data-end=\"3408\"><strong data-start=\"3370\" data-end=\"3384\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"or860n\" data-start=\"3409\" data-end=\"3477\"><strong data-start=\"3411\" data-end=\"3426\">Duftprofil:<\/strong> Warm \/ harzig \/ balsamisch \/ erdig \/ leicht w\u00fcrzig<\/li>\n<li data-section-id=\"kkk135\" data-start=\"3478\" data-end=\"3514\"><strong data-start=\"3480\" data-end=\"3498\">Duftcharakter:<\/strong> Tiefe Basisnote<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"3515\" data-end=\"3566\"><strong data-start=\"3517\" data-end=\"3532\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"3567\" data-end=\"3624\"><strong data-start=\"3569\" data-end=\"3602\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3625\" data-end=\"3656\"><strong data-start=\"3627\" data-end=\"3646\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswpgc\" data-start=\"3657\" data-end=\"3685\"><strong data-start=\"3659\" data-end=\"3671\">Barcode:<\/strong> 5055796529643<\/li>\n<\/ul>\n<hr data-start=\"3687\" data-end=\"3690\" \/>\n<h4 data-start=\"3692\" data-end=\"3716\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3718\" data-end=\"3920\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"3756\" data-end=\"3820\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3922\" data-end=\"4075\">F\u00fcr Haut- oder Massageanwendungen ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vor der ersten Anwendung einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"4077\" data-end=\"4363\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"4077\" data-end=\"4221\">W\u00e4hrend der Schwangerschaft sollte Myrrhen\u00f6l vorsichtshalber nicht ohne ausdr\u00fcckliche fachkundige medizinische R\u00fccksprache verwendet werden.<\/strong> Bei Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten ebenfalls vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Myrrhe \u00e4therisches \u00d6l 50 ml aus Somalia, aus dem Harz von Commiphora myrrha dampfdestilliert. Warm-harziger Duft f\u00fcr Aromatherapie und R\u00e4uchermischungen.<\/em><\/p>","protected":false},"featured_media":61934,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-61944","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/comments?post=61944"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61944\/revisions"}],"predecessor-version":[{"id":63701,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product\/61944\/revisions\/63701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/media\/61934"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/media?parent=61944"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_brand?post=61944"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_cat?post=61944"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/ro\/wp-json\/wp\/v2\/product_tag?post=61944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}