{"id":62171,"date":"2026-08-14T09:48:44","date_gmt":"2026-08-14T09:48:44","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/jasmine-dilute-50ml-essential-oil\/"},"modified":"2026-09-02T14:47:22","modified_gmt":"2026-09-02T14:47:22","slug":"jasminoel-5-prozent-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/","title":{"rendered":"Jasmin\u00f6l 5% 50 ml verd\u00fcnnt in Traubenkern\u00f6l \u2013 Jasmin aus Indien"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Obsah<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Prepn\u00fa\u0165 obsah\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Prepn\u00fa\u0165<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Jasminol_5_50_ml_in_Traubenkernol\" >Jasmin\u00f6l 5% 50 ml in Traubenkern\u00f6l<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#5ige_Verdunnung_%E2%80%93_kein_reines_atherisches_Jasminol\" >5%ige Verd\u00fcnnung \u2013 kein reines \u00e4therisches Jasmin\u00f6l<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Intensiv_blumiger_und_sinnlicher_Jasminduft\" >Intensiv blumiger und sinnlicher Jasminduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Fur_Aromapflege_und_entspannte_Duftmomente\" >F\u00fcr Aromapflege und entspannte Duftmomente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Jasmin_mit_langer_Dufttradition\" >Jasmin mit langer Dufttradition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Produktdetails\" >Detaily produktu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Hinweis_zur_Herstellerangabe\" >Hinweis zur Herstellerangabe<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/sk\/produkt\/jasminoel-5-prozent-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"343\" data-end=\"382\"><span class=\"ez-toc-section\" id=\"Jasminol_5_50_ml_in_Traubenkernol\"><\/span>Jasmin\u00f6l 5% 50 ml in Traubenkern\u00f6l<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"384\" data-end=\"601\">Ten\/T\u00e1\/To <strong data-start=\"388\" data-end=\"409\">Jasmin\u00f6l 5% 50 ml<\/strong> verbindet das charakteristische Aroma von <em data-start=\"452\" data-end=\"473\">Jasminum officinale<\/em> mit mildem Traubenkern\u00f6l. Das Produkt enth\u00e4lt laut Hersteller <strong data-start=\"536\" data-end=\"569\">5 % Jasmin\u00f6l in Traubenkern\u00f6l<\/strong> und ist damit bereits verd\u00fcnnt.<\/p>\n<p data-start=\"603\" data-end=\"827\">Jasmin geh\u00f6rt zu den bekanntesten floralen Duftnoten der Parf\u00fcmerie und zeichnet sich durch ein <strong data-start=\"699\" data-end=\"751\">intensives, s\u00fc\u00dfes, blumiges und sinnliches Aroma<\/strong> aus. Das verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"816\" data-end=\"826\">Indien<\/strong>.<\/p>\n<hr data-start=\"829\" data-end=\"832\" \/>\n<h4 data-start=\"834\" data-end=\"890\"><span class=\"ez-toc-section\" id=\"5ige_Verdunnung_%E2%80%93_kein_reines_atherisches_Jasminol\"><\/span>5%ige Verd\u00fcnnung \u2013 kein reines \u00e4therisches Jasmin\u00f6l<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"892\" data-end=\"1072\">Bei diesem Produkt handelt es sich ausdr\u00fccklich <strong data-start=\"940\" data-end=\"974\">nicht um 100 % reines Jasmin\u00f6l<\/strong>. Der aromatische Jasminbestandteil liegt in einer Konzentration von <strong data-start=\"1043\" data-end=\"1067\">5 % in Traubenkern\u00f6l<\/strong> vor.<\/p>\n<p data-start=\"1074\" data-end=\"1276\">Die Verd\u00fcnnung macht den intensiven Jasminduft leichter dosierbar und eignet sich besonders f\u00fcr aromatische K\u00f6rperpflege- und Massageanwendungen, sofern die individuelle Hautvertr\u00e4glichkeit gegeben ist.<\/p>\n<hr data-start=\"1278\" data-end=\"1281\" \/>\n<h4 data-start=\"1283\" data-end=\"1331\"><span class=\"ez-toc-section\" id=\"Intensiv_blumiger_und_sinnlicher_Jasminduft\"><\/span>Intensiv blumiger und sinnlicher Jasminduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1333\" data-end=\"1546\">Jasmin besitzt einen unverwechselbaren <strong data-start=\"1372\" data-end=\"1445\">\u00fcppig-blumigen, s\u00fc\u00dflichen, warmen und leicht exotischen Duftcharakter<\/strong>. Schon kleine Mengen k\u00f6nnen einer Duftkomposition eine deutlich florale und elegante Note verleihen.<\/p>\n<p data-start=\"1548\" data-end=\"1684\">Ten\/T\u00e1\/To <strong data-start=\"1552\" data-end=\"1573\">Jasmin\u00f6l 5% 50 ml<\/strong> harmoniert besonders gut mit <strong data-start=\"1603\" data-end=\"1683\">Bergamotte, Orange, Neroli, Rose, Ylang Ylang, Patchouli und Sandelholznoten<\/strong>.<\/p>\n<hr data-start=\"1686\" data-end=\"1689\" \/>\n<h4 data-start=\"1691\" data-end=\"1738\"><span class=\"ez-toc-section\" id=\"Fur_Aromapflege_und_entspannte_Duftmomente\"><\/span>F\u00fcr Aromapflege und entspannte Duftmomente<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1740\" data-end=\"1999\">Jasminduft wird in der Aromatherapie traditionell mit einer <strong data-start=\"1800\" data-end=\"1853\">harmonischen, positiven und sinnlichen Atmosph\u00e4re<\/strong> verbunden. Aufgrund seines intensiven floralen Charakters wird Jasmin auch gerne f\u00fcr entspannte Abendrituale und luxuri\u00f6se Aromapflege verwendet.<\/p>\n<p data-start=\"2001\" data-end=\"2240\">Da dieses Produkt in Traubenkern\u00f6l verd\u00fcnnt ist, sollte vor der Verwendung in einem Diffuser oder einer Duftlampe gepr\u00fcft werden, ob das jeweilige Ger\u00e4t f\u00fcr <strong data-start=\"2158\" data-end=\"2226\">\u00f6lbasierte beziehungsweise in Pflanzen\u00f6l verd\u00fcnnte Aromaprodukte<\/strong> geeignet ist.<\/p>\n<hr data-start=\"2242\" data-end=\"2245\" \/>\n<h4 data-start=\"2247\" data-end=\"2283\"><span class=\"ez-toc-section\" id=\"Jasmin_mit_langer_Dufttradition\"><\/span>Jasmin mit langer Dufttradition<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2285\" data-end=\"2508\">Jasmin besitzt insbesondere in Asien eine lange kulturelle und aromatische Tradition. Die intensiv duftenden Pflanzenteile wurden \u00fcber Jahrhunderte f\u00fcr <strong data-start=\"2437\" data-end=\"2497\">Parf\u00fcmerie, Zeremonien und traditionelle Duftanwendungen<\/strong> ocenil.<\/p>\n<p data-start=\"2510\" data-end=\"2745\">Auch die Verbindung von Jasmin mit Romantik und Sinnlichkeit hat eine lange Tradition. Solche \u00fcberlieferten Anwendungen sind jedoch nicht mit wissenschaftlich nachgewiesenen medizinischen oder aphrodisierenden Wirkungen gleichzusetzen.<\/p>\n<hr data-start=\"2747\" data-end=\"2750\" \/>\n<h4 data-start=\"2752\" data-end=\"2771\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Detaily produktu<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2773\" data-end=\"3332\">\n<li data-section-id=\"ijplpp\" data-start=\"2773\" data-end=\"2805\"><strong data-start=\"2775\" data-end=\"2787\">Produkt:<\/strong> Jasmin\u00f6l 5% 50 ml<\/li>\n<li data-section-id=\"1dknjoq\" data-start=\"2806\" data-end=\"2827\"><strong data-start=\"2808\" data-end=\"2820\">Rastlina:<\/strong> Jasmin<\/li>\n<li data-section-id=\"13laic8\" data-start=\"2828\" data-end=\"2879\"><strong data-start=\"2830\" data-end=\"2857\">Botanische Bezeichnung:<\/strong> <em data-start=\"2858\" data-end=\"2879\">Jasminum officinale<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2880\" data-end=\"2899\"><strong data-start=\"2882\" data-end=\"2893\">Obsah:<\/strong> 50 ml<\/li>\n<li data-section-id=\"p72szm\" data-start=\"2900\" data-end=\"2924\"><strong data-start=\"2902\" data-end=\"2920\">Konzentration:<\/strong> 5 %<\/li>\n<li data-section-id=\"1fh8zm1\" data-start=\"2925\" data-end=\"2954\"><strong data-start=\"2927\" data-end=\"2940\">Tr\u00e4ger\u00f6l:<\/strong> Hroznov\u00fd olej<\/li>\n<li data-section-id=\"t80bkv\" data-start=\"2955\" data-end=\"3022\"><strong data-start=\"2957\" data-end=\"3002\">Verwendeter Pflanzenteil laut Hersteller:<\/strong> Getrocknete Bl\u00e4tter<\/li>\n<li data-section-id=\"1cav5hq\" data-start=\"3023\" data-end=\"3045\"><strong data-start=\"3025\" data-end=\"3038\">P\u00f4vod:<\/strong> Indien<\/li>\n<li data-section-id=\"l6avdl\" data-start=\"3046\" data-end=\"3102\"><strong data-start=\"3048\" data-end=\"3078\">Gewinnung laut Hersteller:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"o40vdr\" data-start=\"3103\" data-end=\"3164\"><strong data-start=\"3105\" data-end=\"3120\">Profil v\u00f4ne:<\/strong> Intensiv blumig \/ s\u00fc\u00dflich \/ warm \/ sinnlich<\/li>\n<li data-section-id=\"juuqo6\" data-start=\"3165\" data-end=\"3214\"><strong data-start=\"3167\" data-end=\"3182\">Pou\u017eitie:<\/strong> Aromapflege und Duftanwendungen<\/li>\n<li data-section-id=\"1nuk2t\" data-start=\"3215\" data-end=\"3271\"><strong data-start=\"3217\" data-end=\"3250\">Nettogewicht laut Hersteller:<\/strong> ca. 60 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"3272\" data-end=\"3303\"><strong data-start=\"3274\" data-end=\"3293\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswth4\" data-start=\"3304\" data-end=\"3332\"><strong data-start=\"3306\" data-end=\"3318\">Barcode:<\/strong> 5055796529353<\/li>\n<\/ul>\n<hr data-start=\"3334\" data-end=\"3337\" \/>\n<h4 data-start=\"3339\" data-end=\"3372\"><span class=\"ez-toc-section\" id=\"Hinweis_zur_Herstellerangabe\"><\/span>Hinweis zur Herstellerangabe<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3374\" data-end=\"3656\">Die gelieferten Produktdaten sind bei der <strong data-start=\"3416\" data-end=\"3466\">Gewinnungsmethode nicht vollst\u00e4ndig konsistent<\/strong>: In den technischen Angaben wird Wasserdampfdestillation genannt, w\u00e4hrend die Produktbeschreibung zus\u00e4tzlich auf <strong data-start=\"3580\" data-end=\"3607\">L\u00f6sungsmittelextraktion<\/strong> bei der Herstellung von Jasminessenzen verweist.<\/p>\n<p data-start=\"3658\" data-end=\"3825\">Daher w\u00fcrde ich im Shop keine weitergehende Behauptung zur konkreten Extraktionsmethode machen, solange keine eindeutige Produktspezifikation des Herstellers vorliegt.<\/p>\n<hr data-start=\"3827\" data-end=\"3830\" \/>\n<h4 data-start=\"3832\" data-end=\"3856\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"3858\" data-end=\"3984\">Dieses Produkt ist eine <strong data-start=\"3882\" data-end=\"3962\">5%ige Verd\u00fcnnung in Traubenkern\u00f6l und kein 100 % reines \u00e4therisches Jasmin\u00f6l<\/strong>. <strong data-start=\"3964\" data-end=\"3984\">Nicht einnehmen.<\/strong><\/p>\n<p data-start=\"3986\" data-end=\"4237\">Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren. Trotz der bereits vorhandenen Verd\u00fcnnung empfiehlt sich vor einer gro\u00dffl\u00e4chigen Hautanwendung ein <strong data-start=\"4184\" data-end=\"4236\">Vertr\u00e4glichkeitstest an einer kleinen Hautstelle<\/strong>.<\/p>\n<p data-start=\"4239\" data-end=\"4387\" data-is-last-node=\"\" data-is-only-node=\"\">Bei Schwangerschaft, Stillzeit, bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Jasmin\u00f6l 5% 50 ml aus Jasminum officinale, verd\u00fcnnt in Traubenkern\u00f6l. Intensiv blumiger, s\u00fc\u00dflicher Jasminduft f\u00fcr Aromapflege und Duftanwendungen.<\/em><\/p>","protected":false},"featured_media":62151,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62171","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product\/62171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/comments?post=62171"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product\/62171\/revisions"}],"predecessor-version":[{"id":63693,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product\/62171\/revisions\/63693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/media\/62151"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/media?parent=62171"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product_brand?post=62171"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product_cat?post=62171"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/sk\/wp-json\/wp\/v2\/product_tag?post=62171"}],"curies":[{"name":"pracovn\u00fd list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}