{"id":61752,"date":"2026-08-10T20:07:30","date_gmt":"2026-08-10T20:07:30","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/smudge-stick-white-sage-black-sage-10cm\/"},"modified":"2026-08-28T06:32:15","modified_gmt":"2026-08-28T06:32:15","slug":"weisser-schwarzer-salbei-raeucherbuendel-10-cm","status":"publish","type":"product","link":"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/","title":{"rendered":"Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel 10 cm Smudge Stick Meditation R\u00e4ucherwerk"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Weiser_und_schwarzer_Salbei_zum_Rauchern\" >Wei\u00dfer und schwarzer Salbei zum R\u00e4uchern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Fur_Meditation_und_spirituelle_Rituale\" >F\u00fcr Meditation und spirituelle Rituale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Kompakter_Smudge_Stick_mit_10_cm_Lange\" >Kompakter Smudge Stick mit 10 cm L\u00e4nge<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Fur_Zuhause_Meditation_und_Wellness\" >F\u00fcr Zuhause, Meditation und Wellness<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Anwendung\" >Anwendung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Material\" >Material<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/weisser-schwarzer-salbei-raeucherbuendel-10-cm\/#Weitere_Inspiration_entdecken\" >Weitere Inspiration entdecken<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-13\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-13\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-13\" data-testid=\"conversation-turn-38\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"d7902721-6f23-4dc2-9845-b3425bb9791b\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"416\" data-end=\"461\"><span class=\"ez-toc-section\" id=\"Weiser_und_schwarzer_Salbei_zum_Rauchern\"><\/span>Wei\u00dfer und schwarzer Salbei zum R\u00e4uchern<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"463\" data-end=\"694\">Das <strong data-start=\"467\" data-end=\"508\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/strong> kombiniert zwei Salbei-Varianten in einem kompakten Smudge Stick. Die besondere Pflanzenkombination eignet sich f\u00fcr pers\u00f6nliche R\u00e4ucherrituale, Meditation und bewusste Momente der Ruhe.<\/p>\n<hr data-start=\"696\" data-end=\"699\" \/>\n<h4 data-start=\"701\" data-end=\"744\"><span class=\"ez-toc-section\" id=\"Fur_Meditation_und_spirituelle_Rituale\"><\/span>F\u00fcr Meditation und spirituelle Rituale<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"746\" data-end=\"1036\">Das R\u00e4uchern mit Salbei wird traditionell mit der energetischen Reinigung von R\u00e4umen und der pers\u00f6nlichen Umgebung verbunden. Das <strong data-start=\"876\" data-end=\"917\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/strong> kann vor Meditation, Gebet oder anderen spirituellen Praktiken verwendet werden und schafft eine besondere Atmosph\u00e4re.<\/p>\n<hr data-start=\"1038\" data-end=\"1041\" \/>\n<h4 data-start=\"1043\" data-end=\"1086\"><span class=\"ez-toc-section\" id=\"Kompakter_Smudge_Stick_mit_10_cm_Lange\"><\/span>Kompakter Smudge Stick mit 10 cm L\u00e4nge<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1088\" data-end=\"1361\">Mit einer L\u00e4nge von <strong data-start=\"1108\" data-end=\"1117\">10 cm<\/strong> und einem Durchmesser von etwa <strong data-start=\"1149\" data-end=\"1157\">3 cm<\/strong> besitzt das <strong data-start=\"1170\" data-end=\"1211\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/strong> eine kompakte und handliche Gr\u00f6\u00dfe. Das gebundene Pflanzenmaterial l\u00e4sst sich einfach verwenden und kann je nach Anwendung mehrfach angez\u00fcndet werden.<\/p>\n<hr data-start=\"1363\" data-end=\"1366\" \/>\n<h4 data-start=\"1368\" data-end=\"1409\"><span class=\"ez-toc-section\" id=\"Fur_Zuhause_Meditation_und_Wellness\"><\/span>F\u00fcr Zuhause, Meditation und Wellness<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1411\" data-end=\"1685\">Ob f\u00fcr die pers\u00f6nliche R\u00e4ucherroutine, Meditation oder bewusste Auszeiten \u2013 das <strong data-start=\"1491\" data-end=\"1532\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/strong> ist vielseitig einsetzbar. Die Kombination aus wei\u00dfem und schwarzem Salbei macht es auch zu einer besonderen Geschenkidee f\u00fcr Liebhaber von R\u00e4ucherwerk.<\/p>\n<hr data-start=\"1687\" data-end=\"1690\" \/>\n<h4 data-start=\"1692\" data-end=\"1711\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"1713\" data-end=\"2020\">\n<li data-section-id=\"15a71p4\" data-start=\"1713\" data-end=\"1752\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/li>\n<li data-section-id=\"nn4ijp\" data-start=\"1753\" data-end=\"1791\">White Sage &amp; Black Sage Smudge Stick<\/li>\n<li data-section-id=\"2j2t4j\" data-start=\"1792\" data-end=\"1837\">Kombination aus wei\u00dfem und schwarzem Salbei<\/li>\n<li data-section-id=\"1cdy4wu\" data-start=\"1838\" data-end=\"1873\">F\u00fcr R\u00e4ucherrituale und Meditation<\/li>\n<li data-section-id=\"hago0a\" data-start=\"1874\" data-end=\"1904\">Nat\u00fcrliches Pflanzenmaterial<\/li>\n<li data-section-id=\"epxsla\" data-start=\"1905\" data-end=\"1926\">Mehrfach verwendbar<\/li>\n<li data-section-id=\"1c2aa3d\" data-start=\"1927\" data-end=\"1945\">L\u00e4nge: <strong data-start=\"1936\" data-end=\"1945\">10 cm<\/strong><\/li>\n<li data-section-id=\"13c2d10\" data-start=\"1946\" data-end=\"1973\">Durchmesser: <strong data-start=\"1961\" data-end=\"1973\">ca. 3 cm<\/strong><\/li>\n<li data-section-id=\"m9n574\" data-start=\"1974\" data-end=\"1997\">Gewicht: <strong data-start=\"1985\" data-end=\"1997\">ca. 28 g<\/strong><\/li>\n<li data-section-id=\"uacxt5\" data-start=\"1998\" data-end=\"2020\">Material: <strong data-start=\"2010\" data-end=\"2020\">Salbei<\/strong><\/li>\n<\/ul>\n<hr data-start=\"2022\" data-end=\"2025\" \/>\n<h4 data-start=\"2027\" data-end=\"2041\"><span class=\"ez-toc-section\" id=\"Anwendung\"><\/span>Anwendung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2043\" data-end=\"2373\">Das Ende des <strong data-start=\"2056\" data-end=\"2097\">Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel<\/strong> vorsichtig anz\u00fcnden und kurz brennen lassen. Anschlie\u00dfend die Flamme ausblasen, sodass das B\u00fcndel langsam glimmt und Rauch entwickelt. Eine feuerfeste Schale zum Auffangen der Asche verwenden. Nach der Anwendung vollst\u00e4ndig l\u00f6schen und niemals unbeaufsichtigt brennen lassen.<\/p>\n<hr data-start=\"2375\" data-end=\"2378\" \/>\n<h4 data-start=\"2380\" data-end=\"2393\"><span class=\"ez-toc-section\" id=\"Material\"><\/span>Material<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2395\" data-end=\"2402\" data-is-last-node=\"\" data-is-only-node=\"\">Salbei.<\/p>\n<hr data-start=\"1683\" data-end=\"1686\" \/>\n<h4 data-start=\"413\" data-end=\"449\"><span class=\"ez-toc-section\" id=\"Weitere_Inspiration_entdecken\"><\/span>Weitere Inspiration entdecken<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"450\" data-end=\"582\">Du suchst weitere besondere Produkte? Entdecke zus\u00e4tzliche Highlights in unserem Sortiment oder st\u00f6bere in unseren Partnerprojekten:<\/p>\n<ul data-start=\"584\" data-end=\"920\">\n<li data-start=\"584\" data-end=\"656\"><a href=\"https:\/\/honigbee.com\/shop\/\">Weitere Naturprodukte bei Honigbee entdecken<\/a><\/li>\n<li data-start=\"657\" data-end=\"783\">\n<p data-start=\"659\" data-end=\"783\"><a href=\"https:\/\/matvana.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Stilvolle Wohnideen bei Matvana ansehen<\/a><\/p>\n<\/li>\n<li data-start=\"784\" data-end=\"920\">\n<p data-start=\"786\" data-end=\"920\"><a href=\"https:\/\/saphirsmaragd.com\/shop\/\" target=\"_blank\" rel=\"noopener\">Edelsteine &amp; Schmuck bei Saphir &amp; Smaragd ansehen<\/a><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Das Wei\u00dfer Schwarzer Salbei R\u00e4ucherb\u00fcndel mit 10 cm kombiniert wei\u00dfen und schwarzen Salbei. Ideal f\u00fcr R\u00e4ucherrituale, Meditation und eine besondere Raumatmosph\u00e4re.<\/em><\/p>","protected":false},"featured_media":61746,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1650],"product_tag":[],"class_list":["post-61752","product","type-product","status-publish","has-post-thumbnail","product_cat-raeucherwerk","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/61752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/comments?post=61752"}],"version-history":[{"count":2,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/61752\/revisions"}],"predecessor-version":[{"id":63445,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/61752\/revisions\/63445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/media\/61746"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/media?parent=61752"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_brand?post=61752"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_cat?post=61752"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_tag?post=61752"}],"curies":[{"name":"delovni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}