{"id":62348,"date":"2026-08-14T09:50:58","date_gmt":"2026-08-14T09:50:58","guid":{"rendered":"https:\/\/honigbee.com\/produkt\/basil-50ml-essential-oil\/"},"modified":"2026-09-01T12:34:16","modified_gmt":"2026-09-01T12:34:16","slug":"basilikum-aetherisches-oel-50-ml","status":"publish","type":"product","link":"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/","title":{"rendered":"Basilikum \u00e4therisches \u00d6l 50 ml aus Indien f\u00fcr Aromatherapie und Duftanwendungen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Basilikum_atherisches_Ol_50_ml\" >Basilikum \u00e4therisches \u00d6l 50 ml<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Aus_bluhendem_Basilikumkraut_gewonnen\" >Aus bl\u00fchendem Basilikumkraut gewonnen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Frischer_und_wurziger_Krauterduft\" >Frischer und w\u00fcrziger Kr\u00e4uterduft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Fur_Aromatherapie_und_Konzentrationsmomente\" >F\u00fcr Aromatherapie und Konzentrationsmomente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Basilikum_mit_langer_Tradition\" >Basilikum mit langer Tradition<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Produktdetails\" >Produktdetails<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/honigbee.com\/sl\/izdelek\/basilikum-aetherisches-oel-50-ml\/#Sicherheitshinweise\" >Sicherheitshinweise<\/a><\/li><\/ul><\/nav><\/div>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-18\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-18\" data-turn-id-container=\"request-6a52093d-ba64-83ea-a38e-983d37168d35-18\" data-testid=\"conversation-turn-48\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"dc9d8cdb-3272-49ba-8eee-0b672599c954\" data-message-model-slug=\"gpt-5-6\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"fbskMG_root markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<h4 class=\"PDq2pG_selectionAnchorContainer\" data-start=\"377\" data-end=\"412\"><span class=\"ez-toc-section\" id=\"Basilikum_atherisches_Ol_50_ml\"><\/span>Basilikum \u00e4therisches \u00d6l 50 ml<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"414\" data-end=\"710\">Das <strong data-start=\"418\" data-end=\"452\">Basilikum \u00e4therisches \u00d6l 50 ml<\/strong> wird aus dem bl\u00fchenden Kraut von <em data-start=\"486\" data-end=\"504\">Ocimum basilicum<\/em> gewonnen. Basilikum ist nicht nur als Gew\u00fcrzpflanze bekannt, sondern wird aufgrund seines charakteristischen <strong data-start=\"614\" data-end=\"664\">frischen, krautigen und leicht w\u00fcrzigen Aromas<\/strong> auch zur Gewinnung \u00e4therischer \u00d6le verwendet.<\/p>\n<p data-start=\"712\" data-end=\"807\">Das f\u00fcr dieses \u00e4therische \u00d6l verwendete Pflanzenmaterial stammt laut Hersteller aus <strong data-start=\"796\" data-end=\"806\">Indien<\/strong>.<\/p>\n<hr data-start=\"809\" data-end=\"812\" \/>\n<h4 data-start=\"814\" data-end=\"856\"><span class=\"ez-toc-section\" id=\"Aus_bluhendem_Basilikumkraut_gewonnen\"><\/span>Aus bl\u00fchendem Basilikumkraut gewonnen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"858\" data-end=\"989\">F\u00fcr die Herstellung des <strong data-start=\"882\" data-end=\"916\">Basilikum \u00e4therisches \u00d6l 50 ml<\/strong> wird das bl\u00fchende Kraut mittels <strong data-start=\"949\" data-end=\"976\">Wasserdampfdestillation<\/strong> verarbeitet.<\/p>\n<p data-start=\"991\" data-end=\"1212\">Dabei werden die fl\u00fcchtigen aromatischen Bestandteile der Pflanze gewonnen. Das daraus entstehende \u00e4therische \u00d6l kann eine gr\u00fcnlich-gelbe F\u00e4rbung besitzen und zeichnet sich durch seinen klaren, intensiven Kr\u00e4uterduft aus.<\/p>\n<hr data-start=\"1214\" data-end=\"1217\" \/>\n<h4 data-start=\"1219\" data-end=\"1257\"><span class=\"ez-toc-section\" id=\"Frischer_und_wurziger_Krauterduft\"><\/span>Frischer und w\u00fcrziger Kr\u00e4uterduft<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1259\" data-end=\"1440\">Basilikum\u00f6l besitzt ein <strong data-start=\"1283\" data-end=\"1348\">frisches, krautiges, w\u00fcrziges und leicht s\u00fc\u00dfliches Duftprofil<\/strong>. Sein markantes Aroma verleiht Duftmischungen einen klaren und lebendigen Kr\u00e4utercharakter.<\/p>\n<p data-start=\"1442\" data-end=\"1525\">Besonders gut l\u00e4sst sich Basilikum mit Zitrus-, Kr\u00e4uter- und Holznoten kombinieren.<\/p>\n<hr data-start=\"1527\" data-end=\"1530\" \/>\n<h4 data-start=\"1532\" data-end=\"1580\"><span class=\"ez-toc-section\" id=\"Fur_Aromatherapie_und_Konzentrationsmomente\"><\/span>F\u00fcr Aromatherapie und Konzentrationsmomente<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1582\" data-end=\"1715\">In der Aromatherapie wird der Duft von Basilikum traditionell mit einer <strong data-start=\"1654\" data-end=\"1704\">klaren, belebenden und fokussierten Atmosph\u00e4re<\/strong> verbunden.<\/p>\n<p data-start=\"1717\" data-end=\"1944\">Das <strong data-start=\"1721\" data-end=\"1755\">Basilikum \u00e4therisches \u00d6l 50 ml<\/strong> eignet sich f\u00fcr geeignete Diffuser und Duftlampen und kann beispielsweise beim Arbeiten, Lernen oder w\u00e4hrend anderer konzentrierter T\u00e4tigkeiten als aromatische Begleitung verwendet werden.<\/p>\n<hr data-start=\"1946\" data-end=\"1949\" \/>\n<h4 data-start=\"1951\" data-end=\"1986\"><span class=\"ez-toc-section\" id=\"Basilikum_mit_langer_Tradition\"><\/span>Basilikum mit langer Tradition<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"1988\" data-end=\"2196\">Basilikum besitzt insbesondere in <strong data-start=\"2022\" data-end=\"2032\">Indien<\/strong> eine lange kulturelle und spirituelle Tradition. Verschiedene Basilikumarten werden dort seit Jahrhunderten in religi\u00f6sen und traditionellen Anwendungen verwendet.<\/p>\n<p data-start=\"2198\" data-end=\"2368\">Auch international geh\u00f6rt Basilikum heute zu den bekanntesten aromatischen Kr\u00e4utern und wird sowohl als Gew\u00fcrzpflanze als auch f\u00fcr nat\u00fcrliche Duftkompositionen gesch\u00e4tzt.<\/p>\n<hr data-start=\"2370\" data-end=\"2373\" \/>\n<h4 data-start=\"2375\" data-end=\"2394\"><span class=\"ez-toc-section\" id=\"Produktdetails\"><\/span>Produktdetails<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul data-start=\"2396\" data-end=\"2906\">\n<li data-section-id=\"mtztl4\" data-start=\"2396\" data-end=\"2441\"><strong data-start=\"2398\" data-end=\"2410\">Produkt:<\/strong> Basilikum \u00e4therisches \u00d6l 50 ml<\/li>\n<li data-section-id=\"11nsvyv\" data-start=\"2442\" data-end=\"2466\"><strong data-start=\"2444\" data-end=\"2456\">Pflanze:<\/strong> Basilikum<\/li>\n<li data-section-id=\"13r0q1b\" data-start=\"2467\" data-end=\"2515\"><strong data-start=\"2469\" data-end=\"2496\">Botanische Bezeichnung:<\/strong> <em data-start=\"2497\" data-end=\"2515\">Ocimum basilicum<\/em><\/li>\n<li data-section-id=\"qnfkbk\" data-start=\"2516\" data-end=\"2535\"><strong data-start=\"2518\" data-end=\"2529\">Inhalt:<\/strong> 50 ml<\/li>\n<li data-section-id=\"1q47y2v\" data-start=\"2536\" data-end=\"2583\"><strong data-start=\"2538\" data-end=\"2567\">Verwendeter Pflanzenteil:<\/strong> Bl\u00fchendes Kraut<\/li>\n<li data-section-id=\"1cav5hq\" data-start=\"2584\" data-end=\"2606\"><strong data-start=\"2586\" data-end=\"2599\">Herkunft:<\/strong> Indien<\/li>\n<li data-section-id=\"1peynr3\" data-start=\"2607\" data-end=\"2647\"><strong data-start=\"2609\" data-end=\"2623\">Gewinnung:<\/strong> Wasserdampfdestillation<\/li>\n<li data-section-id=\"16dndzc\" data-start=\"2648\" data-end=\"2674\"><strong data-start=\"2650\" data-end=\"2660\">Farbe:<\/strong> Gr\u00fcnlich-gelb<\/li>\n<li data-section-id=\"145okem\" data-start=\"2675\" data-end=\"2735\"><strong data-start=\"2677\" data-end=\"2692\">Duftprofil:<\/strong> Frisch \/ krautig \/ w\u00fcrzig \/ leicht s\u00fc\u00dflich<\/li>\n<li data-section-id=\"1smsgul\" data-start=\"2736\" data-end=\"2787\"><strong data-start=\"2738\" data-end=\"2753\">Verwendung:<\/strong> Aromatherapie und Duftanwendungen<\/li>\n<li data-section-id=\"uesb6b\" data-start=\"2788\" data-end=\"2845\"><strong data-start=\"2790\" data-end=\"2823\">Nettogewicht laut Hersteller:<\/strong> ca. 110 g pro Flasche<\/li>\n<li data-section-id=\"1wrwp1y\" data-start=\"2846\" data-end=\"2877\"><strong data-start=\"2848\" data-end=\"2867\">Versandgewicht:<\/strong> ca. 115 g<\/li>\n<li data-section-id=\"1qswtfi\" data-start=\"2878\" data-end=\"2906\"><strong data-start=\"2880\" data-end=\"2892\">Barcode:<\/strong> 5055796529377<\/li>\n<\/ul>\n<hr data-start=\"2908\" data-end=\"2911\" \/>\n<h4 data-start=\"2913\" data-end=\"2937\"><span class=\"ez-toc-section\" id=\"Sicherheitshinweise\"><\/span>Sicherheitshinweise<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p data-start=\"2939\" data-end=\"3141\">\u00c4therische \u00d6le sind hochkonzentriert. <strong data-start=\"2977\" data-end=\"3041\">Nicht einnehmen und nicht unverd\u00fcnnt auf die Haut auftragen.<\/strong> Kontakt mit Augen und Schleimh\u00e4uten vermeiden und au\u00dferhalb der Reichweite von Kindern aufbewahren.<\/p>\n<p data-start=\"3143\" data-end=\"3280\">Bei einer vorgesehenen Hautanwendung ausreichend mit einem geeigneten Basis\u00f6l verd\u00fcnnen und vorab einen Vertr\u00e4glichkeitstest durchf\u00fchren.<\/p>\n<p data-start=\"3282\" data-end=\"3534\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"3282\" data-end=\"3413\">Laut Hersteller sollte dieses Basilikum\u00f6l w\u00e4hrend der Schwangerschaft sowie bei Kindern unter 16 Jahren nicht verwendet werden.<\/strong> Bei bestehenden gesundheitlichen Beschwerden oder Einnahme von Medikamenten vor der Anwendung fachkundigen Rat einholen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><em>Basilikum \u00e4therisches \u00d6l 50 ml aus Indien, durch Wasserdampfdestillation des bl\u00fchenden Krauts gewonnen. Frisch-krautiger Duft f\u00fcr Aromatherapie.<\/em><\/p>","protected":false},"featured_media":62333,"comment_status":"open","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1651],"product_tag":[],"class_list":["post-62348","product","type-product","status-publish","has-post-thumbnail","product_cat-aetherische-oele","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/62348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/comments?post=62348"}],"version-history":[{"count":3,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/62348\/revisions"}],"predecessor-version":[{"id":63660,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product\/62348\/revisions\/63660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/media\/62333"}],"wp:attachment":[{"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/media?parent=62348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_brand?post=62348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_cat?post=62348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/honigbee.com\/sl\/wp-json\/wp\/v2\/product_tag?post=62348"}],"curies":[{"name":"delovni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}